{"id":12667,"date":"2021-07-27T15:34:56","date_gmt":"2021-07-27T18:34:56","guid":{"rendered":"https:\/\/www.greenpeace.org\/argentina\/?page_id=12667"},"modified":"2026-05-05T08:54:51","modified_gmt":"2026-05-05T11:54:51","slug":"no-a-la-tala-de-quebrachos-para-la-vias-del-tren","status":"publish","type":"page","link":"https:\/\/www.greenpeace.org\/argentina\/participa\/no-a-la-tala-de-quebrachos-para-la-vias-del-tren\/","title":{"rendered":"No a la tala de quebrachos para las v\u00edas del tren"},"content":{"rendered":"\n                \n                <div class=\"wp-block-group alignfull is-layout-flow wp-block-group-is-layout-flow\">\n                \n                <div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n                \n                <div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-pattern-p4-page-header is-style-parallax\">\n\n                <div class=\"wp-block-media-text__content\">\n                    <div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n                    \n                        <h1 class=\"wp-block-heading has-white-background-color has-background\">\n                            No a la tala de quebrachos para la v\u00edas del tren\n                        <\/h1>\n                    <\/div>\n                \n\n                \n                        <p style=\"font-size:1.25rem\">\n                            Por cada durmiente que va colocado debajo de las v\u00edas, se sacrifica innecesariamente un \u00e1rbol de quebracho (de entre 60 y 80 a\u00f1os de edad). Pedile ahora al Ministerio de Transporte de la Naci\u00f3n que deje de usar quebrachos para las v\u00edas de los trenes.\r\n\n                        <\/p>\n                    \n\n                \n                        <div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n                            \n                        <\/div>\n                        <div class=\"wp-block-button is-style-cta\">\n                            <a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/pages.greenpeace.org.ar\/quebrachos?utm_source=web&#038;utm_medium=hub&#038;utm_content=linkHub&#038;utm_term=todos&#038;utm_campaign=deforestacionCero\" target=\"_blank\" rel=\"noreferrer noopener\">\n                                Particip\u00e1\n                            <\/a>\n                        <\/div>\n                    \n\n                <\/div>\n                <figure class=\"wp-block-media-text__media\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\"\n                        src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-scaled.jpg\"\n                        alt=\"\"\n                        sizes=\"auto, (min-width: 601px) 50vw, 100vw\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-scaled.jpg 2560w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-300x225.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-1024x768.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-768x576.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-1536x1152.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-2048x1536.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-1821x1366.jpg 1821w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/07\/41c218d8-20210108_140647-453x340.jpg 453w\" class=\"wp-image-12680 size-full\"\n                    \/>\n                <\/figure>\n                <\/div>\n                \n                <\/div>\n                \n                <\/div>\n                \n                \n<h2 class=\"wp-block-heading\"><\/h2>\n\n<p><strong>El quebracho, una especie en peligro<\/strong><\/p>\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/mnL6BRDx7c7wqUQc7jzZYtfQptd6HUNvIpx2JFvdN5DYKCR9UOqKB0dW7Xvve8mR9c_eQhk2guQKjlrdd5wnw3ZAsztCDa9V5OOW7VUDN7neFQuIGSyrParyLp17gSHgNbrY8dW0\" alt=\"\" width=\"800\" height=\"531\"\/><\/figure>\n\n<p>El <strong>quebracho colorado<\/strong>, un \u00e1rbol de gran porte y crecimiento lento, fue declarado en el a\u00f1o 1956 \u201c\u00c1rbol Forestal Nacional\u201d, por su importancia ambiental, econ\u00f3mica y social. Sin embargo, su explotaci\u00f3n intensiva y los desmontes para desarrollo agropecuario llevaron a su <a href=\"https:\/\/www.iucnredlist.org\/species\/32017\/9674191\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>estado actual de vulnerabilidad<\/strong><\/a>. En Argentina ha sido <a href=\"https:\/\/www.researchgate.net\/profile\/Darien-Prado\/publication\/262663980_Schinopsis_balansae_Engl_Anacardiaceae\/links\/00b7d53c588dc91ce1000000\/Schinopsis-balansae-Engl-Anacardiaceae.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;categorizado como \u201cEn Peligro\u201d<\/a> por la Uni\u00f3n Internacional para la Conservaci\u00f3n de la Naturaleza (UICN) ya que los quebrachales y otros bosques de la regi\u00f3n chaque\u00f1a est\u00e1n sometidos a otras amenazas como los desmontes para agricultura y ganader\u00eda intensiva, y los incendios<\/p>\n\n<p>Durante las \u00faltimas d\u00e9cadas la deforestaci\u00f3n y la tala indiscriminada han colocado a la regi\u00f3n del <strong>Gran Chaco<\/strong> al tope de los \u00edndices globales de p\u00e9rdida de bosques nativos. El 85% de un ecosistema \u00fanico como el quebrachal del Bosque de Tres Quebrachos (sudoeste de la Provincia de Chaco) ha sido destruido.<\/p>\n\n<p><strong>Los durmientes<\/strong><\/p>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/yBbDLs6MnW5IEj3uib3CyHgxOsJnN4llcEEnbQxBBiEByB2rO-XkL6AwoPHD5Wqq0nNkoJzTdMiijarTzBhI3chp-kba3ryPz0MVx2vFpr5XiJwoNyY3rTIrtaoifO8KhLkgTubQ\" alt=\"\"\/><\/figure>\n\n<p>Los trenes son una pieza clave en un <strong>sistema de transporte eficiente y de bajo impacto ambiental<\/strong> comparado con alternativas terrestres como el transporte de carga vehicular. Sin embargo, existe un aspecto del desarrollo ferroviario que a\u00fan sigue generando efectos negativos sobre los bosques del norte de nuestro pa\u00eds y que puede, y debe, ser eliminado.&nbsp;<\/p>\n\n<p>Los <strong>durmientes<\/strong> (tambi\u00e9n conocidos como traviesas), que son utilizados tanto en la renovaci\u00f3n como en el mantenimiento de v\u00edas,<strong> siguen siendo de quebracho colorado; un \u00e1rbol de gran porte y crecimiento lento<\/strong>, de alto valor para la conservaci\u00f3n del bosque chaque\u00f1o, que se encuentra en estado de fragilidad.<\/p>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/GR1td1y_vh4AHgpeUGZ6BrDDklZ0ErA6nE0Ho82zix6ROHlaFiKC_MQR5_1ETsAynIXQd5lLpJ1P3EglEsMu_dVmUZuwuSekB1lLtn9BDtH5VvKv1uT1R-zrdLcckMH6qdF-wQiM\" alt=\"\"\/><\/figure>\n\n<p>Se estima que en el norte de Argentina, a mediados de la d\u00e9cada de 1940 se llevaban talados<strong> 350 millones de quebrachos colorados<\/strong> para la extracci\u00f3n de tanino y la elaboraci\u00f3n de durmientes de ferrocarril, postes, le\u00f1a y carb\u00f3n. Su sobreexplotaci\u00f3n provoc\u00f3, durante esos primeros 75 a\u00f1os, la <strong>degradaci\u00f3n de 10 millones de hect\u00e1reas de bosques chaque\u00f1os<\/strong><\/p>\n\n<p>Desde el a\u00f1o 2013 se realizaron licitaciones para la compra de 2,3 millones de durmientes de quebracho colorado y quebracho blanco. Esta cantidad de durmientes implica un impacto significativo en los bosques nativos, ya que representa<strong> m\u00e1s de 2 millones de \u00e1rboles talados.<\/strong><\/p>\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/aX7Oq2JfgT05I9ZVJVHBXAM9utci-_BY7tKg17bJItFJZIjiJwvNi86K_7h6kCyw-cEK96rRzprJcj178nwTNnkEunXcamPO03o0iBLPEu9dKoh2Q_QyerW_u9dQr2-Wv8bKMlWA\" alt=\"\"\/><\/figure>\n\n<p class=\"has-text-align-left\">Las provincias de Chaco y Santiago del Estero concentran la producci\u00f3n de durmientes de los \u00faltimos a\u00f1os. En Argentina el sector forestal se caracteriza por presentar una importante informalidad en su producci\u00f3n y comercializaci\u00f3n. <strong>Se calcula que el 30% del volumen total de la madera de bosques nativos que se comercializa es ilega<\/strong>l.&nbsp;<\/p>\n\n<p class=\"has-text-align-left\">El quebracho se distribuye naturalmente en toda la regi\u00f3n chaque\u00f1a. Pero hoy el 85% de un ecosistema \u00fanico como el quebrachal del Bosque de Tres Quebrachos (sudoeste de la Provincia de Chaco) ya ha sido destruido.<\/p>\n\n<p class=\"has-text-align-left\"><img loading=\"lazy\" decoding=\"async\" width=\"602\" height=\"503\" src=\"https:\/\/lh3.googleusercontent.com\/vBdZAkghuyE1vxSPdLvbNfwblhzldVBCDVDsbvNomeVh2T92oMA9TYDutcaDG2Bcr_f9tWwSqa2wt3v2brHpzxxDe0VOzCkkjZcZHfk6GOjNKb4fyr76F3Cl5_Ini-TkHehjOmKF\"><\/p>\n\n<p>Las distintas especies de quebracho tienen diferentes usos en la actualidad, siendo el <strong>quebracho colorado<\/strong> y el <strong>quebracho blanco<\/strong> (con un <a href=\"https:\/\/www.argentina.gob.ar\/sites\/default\/files\/fa_7025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">tratamiento qu\u00edmico especial<\/a> y en menor proporci\u00f3n) los utilizados para la producci\u00f3n de durmientes.<\/p>\n\n<p><strong>Existen alternativas y es hora de actuar&nbsp;<\/strong><\/p>\n\n<p>Los durmientes ferroviarios constituyen una parte fundamental del tendido de v\u00eda y un componente irremplazable. Actualmente <strong>existen diferentes tecnolog\u00edas aplicadas para su fabricaci\u00f3n, sin embargo la utilizaci\u00f3n de la madera sigue teniendo gran demanda<\/strong> a nivel mundial, a pesar de la preocupaci\u00f3n global por el uso de recursos forestales para fines productivos e industriales.&nbsp;<\/p>\n\n<p>Sumado a esto, hay publicaciones que ponen la atenci\u00f3n sobre el tratamiento qu\u00edmico al cual est\u00e1n sometidos los durmientes de madera, que luego de su vida \u00fatil son considerados residuos peligrosos.<\/p>\n\n<p>El <a href=\"http:\/\/biochem.flas.kps.ku.ac.th\/plastic02.pdf\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>durmiente sint\u00e9tico o compuesto<\/strong><\/a> puede ser utilizado en reemplazo de la madera para tareas de mantenimiento y renovaci\u00f3n de v\u00edas. Son realizados de <a href=\"https:\/\/greenpeace.org.ar\/pdf\/2021\/07\/AREMA_30_5_Engineered%20Composite%20Ties.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">diferentes materiales<\/a> y muchos pueden producirse de la cadena de reciclado como <a href=\"http:\/\/www.alaf.int.ar\/site\/revista\/Alaf97.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">restos de neum\u00e1ticos y bidones de agroqu\u00edmicos<\/a>. M\u00faltiples experiencias y estudios en todo el mundo demuestran que las alternativas a la madera son una realidad: India, Estados Unidos, Brasil, M\u00e9xico.<\/p>\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/SDWCgMTDZ_W7HLIaBRYuB6bd1PNwRkenvlcbkTKigsbae6YbsIHbVt87opHS-9fZWnHinbKMQbAkleqaf4OM4eqjOt59hMt3uPaaKSQ9_DorumdwLRsqoqFsbTrN1JEEqT1I2BqU\" alt=\"\" width=\"800\" height=\"534\"\/><\/figure>\n\n<p>En Argentina, a pesar de que existen estudios y capacidad t\u00e9cnica sobre durmientes sint\u00e9ticos, <strong>su desarrollo est\u00e1 retrasado.<\/strong> Recientemente <strong>una <\/strong><a rel=\"noreferrer noopener\" href=\"https:\/\/www.boletinoficial.gob.ar\/detalleAviso\/primera\/237330\/20201116\" target=\"_blank\"><strong>resoluci\u00f3n conjunta<\/strong><\/a><strong> entre el Ministerio de Ambiente y Desarrollo Sustentable y el Ministerio de Transporte de la Naci\u00f3n promueve la producci\u00f3n de durmientes con materiales post consumo<\/strong>, sin embargo no contempla asignaci\u00f3n presupuestaria ni plazos para el reemplazo de los de madera.&nbsp;<\/p>\n\n<p>Durante septiembre 2021 se van a adjudicar nuevas licitaciones para mejoramiento de v\u00edas que incluyen la compra de un total de 156.000 durmientes de madera nativa, lo que implica la destrucci\u00f3n de cerca de 156.000 quebrachos.<\/p>\n\n<p>La red ferroviaria nacional cuenta con m\u00e1s de <strong>40.000 km de extensi\u00f3n<\/strong>, de los cuales<strong> est\u00e1n activos la mitad<\/strong>. Es momento de tener una red ferroviaria sustentable, para lo cual es clave abandonar el uso del quebracho para durmientes de manera definitiva.<\/p>\n\n<h3 class=\"wp-block-heading\">Le\u00e9 m\u00e1s<\/h3>\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/greenpeace.org.ar\/pdf\/2021\/08\/INFORME%20En%20v%C3%ADas%20de%20extinci%C3%B3n%20FINAL%20%281%29.pdf\" target=\"_blank\"><strong>En v\u00edas de extinci\u00f3n. La sobrexplotaci\u00f3n del quebracho para la red ferroviaria argentina<\/strong><\/a> (julio 2021)<\/p>\n\n<p><\/p>\n\n    <div class=\"wp-block-query posts-list p4-query-loop is-custom-layout-list is-layout-flow wp-block-query-is-layout-flow\">\n        <div class=\"wp-block-group is-content-justification-space-between is-layout-flex wp-container-core-group-is-layout-3d213aab wp-block-group-is-layout-flex\"><h2 class=\"wp-block-heading\">\u00daltimas noticias<\/h2>\n        <li class=\" wp-block-navigation-item see-all-link wp-block-navigation-link\"><a class=\"wp-block-navigation-item__content\"  href=\"http:\/\/www.greenpeace.org\/argentina\/news-stories\/?tag=destruirbosquesesuncrimen\"><span data-ga-category=\"Posts List\" data-ga-action=\"See More Link\" data-ga-label=\"n\/a\" class=\"wp-block-navigation-item__label\">See all stories<\/span><\/a><\/li>\n        \n        <\/div>\n        \n\n    <p style=\"margin-top: 24px; margin-bottom: 36px;\"><\/p>\n\n    \n\n    <ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-33274 post type-post status-publish format-standard has-post-thumbnail hentry category-bosques tag-destruirbosquesesuncrimen p4-page-type-story\">\n            \n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/bosques\/greenpeace-denuncio-ante-la-corte-suprema-el-aumento-de-la-deforestacion-y-el-riesgo-de-flexibilizar-la-ley-de-bosques\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-scaled.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Greenpeace denunci\u00f3 ante la Corte Suprema el aumento de la deforestaci\u00f3n y el riesgo de flexibilizar la Ley de Bosques\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-scaled.jpg 2560w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-1536x1024.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-2048x1366.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-510x340.jpg 510w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-argentina-stateless\" data-stateless-media-name=\"2026\/02\/18a51803-salta-1-\u00a9-martin-katz-greenpeace-scaled.jpg\" \/><\/a><\/figure>\n\n        <div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n        <div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/argentina\/category\/problemas\/bosques\/\">Bosques<\/a><\/div>\n        \n        \n        <\/div>\n        \n        <h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/bosques\/greenpeace-denuncio-ante-la-corte-suprema-el-aumento-de-la-deforestacion-y-el-riesgo-de-flexibilizar-la-ley-de-bosques\/\" target=\"_self\" >Greenpeace denunci\u00f3 ante la Corte Suprema el aumento de la deforestaci\u00f3n y el riesgo de flexibilizar la Ley de Bosques<\/a><\/h3>\n        <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">En el marco del D\u00eda Internacional de los Bosques, Greenpeace denunci\u00f3 ante el m\u00e1ximo tribunal que durante 2025 la p\u00e9rdida de bosques en el norte del pa\u00eds aument\u00f3 un 40% <\/p><\/div>\n        \n        <div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/argentina\/author\/prensaarg\/'>Prensa Argentina<\/a><\/span>\n        <div class=\"wp-block-post-date\"><time datetime=\"2026-03-20T15:56:20-03:00\">20 marzo 2026<\/time><\/div>\n        \n        <\/div>\n        <\/div>\n        <\/div>\n\n            <\/li><li class=\"wp-block-post post-32883 post type-post status-publish format-standard has-post-thumbnail hentry category-bosques tag-destruirbosquesesuncrimen p4-page-type-story\">\n            \n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/bosques\/greenpeace-denuncia-que-aumento-un-40-la-perdida-de-bosques-en-el-norte\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"2560\" height=\"1706\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-scaled.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Greenpeace denuncia que aument\u00f3 un 40% la p\u00e9rdida de bosques en el norte\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-scaled.jpg 2560w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-1536x1024.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-2048x1366.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-510x340.jpg 510w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-argentina-stateless\" data-stateless-media-name=\"2026\/02\/0c1ada4d-formosa-1-\u00a9-martin-katz-greenpeace-scaled.jpg\" \/><\/a><\/figure>\n\n        <div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n        <div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/argentina\/category\/problemas\/bosques\/\">Bosques<\/a><\/div>\n        \n        \n        <\/div>\n        \n        <h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/bosques\/greenpeace-denuncia-que-aumento-un-40-la-perdida-de-bosques-en-el-norte\/\" target=\"_self\" >Greenpeace denuncia que aument\u00f3 un 40% la p\u00e9rdida de bosques en el norte<\/a><\/h3>\n        <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Desmontes e incendios arrasaron con m\u00e1s de 210.000 hect\u00e1reas en 2025 <\/p><\/div>\n        \n        <div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/argentina\/author\/prensaarg\/'>Prensa Argentina<\/a><\/span>\n        <div class=\"wp-block-post-date\"><time datetime=\"2026-02-18T11:51:36-03:00\">18 febrero 2026<\/time><\/div>\n        \n        <\/div>\n        <\/div>\n        <\/div>\n\n            <\/li><li class=\"wp-block-post post-32825 post type-post status-publish format-standard has-post-thumbnail hentry category-blog category-bosques tag-destruirbosquesesuncrimen tag-incendios-forestales p4-page-type-blog\">\n            \n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/bosques\/guia-para-prevenir-los-incendios-forestales-la-urgencia-de-cuidar-nuestros-bosques-2\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-scaled.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Gu\u00eda para prevenir los incendios forestales: la urgencia de cuidar nuestros bosques\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-scaled.jpg 2560w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-1536x1024.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-2048x1366.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-510x340.jpg 510w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-argentina-stateless\" data-stateless-media-name=\"2026\/01\/18bfd54e-gpa-incendios-pto.-patriada-chubut-22-\u00a9-matias-garay-greenpeace-scaled.jpg\" \/><\/a><\/figure>\n\n        <div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n        <div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/argentina\/category\/blog\/\">Blog<\/a><\/div>\n        \n        \n        <\/div>\n        \n        <h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/bosques\/guia-para-prevenir-los-incendios-forestales-la-urgencia-de-cuidar-nuestros-bosques-2\/\" target=\"_self\" >Gu\u00eda para prevenir los incendios forestales: la urgencia de cuidar nuestros bosques<\/a><\/h3>\n        <div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">El fuego es evitable y en esta nota te contamos por qu\u00e9. <\/p><\/div>\n        \n        <div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/argentina\/author\/meri\/'>Meri Castro<\/a><\/span>\n        <div class=\"wp-block-post-date\"><time datetime=\"2026-02-02T09:40:46-03:00\">2 febrero 2026<\/time><\/div>\n        \n        <\/div>\n        <\/div>\n        <\/div>\n\n            <\/li><\/ul>\n\n    \n<div class=\"wp-block-buttons carousel-controls is-horizontal is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-buttons-is-layout-044bd602 wp-block-buttons-is-layout-flex\">\n            <div class=\"wp-block-button carousel-control-prev\"><button type=\"button\" class=\"wp-block-button__link wp-element-button\">Prev<\/button><\/div>\n        \n\n            <div class=\"wp-block-button carousel-control-next\"><button type=\"button\" class=\"wp-block-button__link wp-element-button\">Next<\/button><\/div>\n        <\/div>\n\n\n    <li class=\" wp-block-navigation-item see-all-link wp-block-navigation-link\"><a class=\"wp-block-navigation-item__content\"  href=\"http:\/\/www.greenpeace.org\/argentina\/news-stories\/?tag=destruirbosquesesuncrimen\"><span data-ga-category=\"Posts List\" data-ga-action=\"See More Link\" data-ga-label=\"n\/a\" class=\"wp-block-navigation-item__label\">See all stories<\/span><\/a><\/li><\/div>\n    \n<h3>Videos <\/h3>\n<br>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/videoseries?list=PLgR0D19YPNICmUa1taRNY6CPKnqupsx2K\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe>\n<div data-render=\"planet4-blocks\/happypoint\" data-attributes=\"{&quot;attributes&quot;:{&quot;iframe_url&quot;:&quot;https:\\\/\\\/unite.greenpeace.org.ar\\\/happypoint\\\/&quot;,&quot;override_default_content&quot;:true,&quot;local_content_provider&quot;:&quot;iframe_url&quot;,&quot;opacity&quot;:30}}\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Por cada durmiente que va colocado debajo de las v\u00edas, se sacrifica innecesariamente un \u00e1rbol de quebracho (de entre 60 y 80 a\u00f1os de edad).<\/p>\n","protected":false},"author":19,"featured_media":12756,"parent":20109,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ep_exclude_from_search":false,"p4_hide_page_title_checkbox":"on","p4_title":"","p4_subtitle":"","p4_description":"","background_image_id":"","background_image":"","p4_button_title":"","p4_button_link":"","p4_button_link_checkbox":"","p4_og_title":"No a la tala de quebrachos","p4_og_description":"Por cada durmiente que va colocado debajo de las v\u00edas, se sacrifica innecesariamente un \u00e1rbol de quebracho (de entre 60 y 80 a\u00f1os de edad).","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[2],"tags":[52],"class_list":["post-12667","page","type-page","status-publish","has-post-thumbnail","hentry","category-bosques","tag-trenessindesmontes"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/12667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/comments?post=12667"}],"version-history":[{"count":21,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/12667\/revisions"}],"predecessor-version":[{"id":33727,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/12667\/revisions\/33727"}],"up":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/20109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/media\/12756"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/media?parent=12667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/categories?post=12667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/tags?post=12667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}