{"id":19882,"date":"2023-06-21T10:19:10","date_gmt":"2023-06-21T13:19:10","guid":{"rendered":"https:\/\/www.greenpeace.org\/argentina\/?page_id=19882"},"modified":"2026-06-29T07:36:59","modified_gmt":"2026-06-29T10:36:59","slug":"informate","status":"publish","type":"page","link":"https:\/\/www.greenpeace.org\/argentina\/informate\/","title":{"rendered":"Informate"},"content":{"rendered":"\n<h1 class=\"wp-block-heading has-blue-green-800-color has-text-color\">Informate<\/h1>\n\n<p class=\"wp-block-paragraph\">Desde Greenpeace <strong>generamos diversos tipos de contenido para que puedas informarte seg\u00fan tu preferencia. <\/strong>La informaci\u00f3n nos empodera, nos permite tomar conciencia y decidir con criterio.<\/p>\n\n<p class=\"wp-block-paragraph\">Compart\u00ed nuestro contenido para que seamos cada vez m\u00e1s las personas con conciencia ambiental. <\/p>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-style-default has-grey-100-color has-grey-200-background-color has-text-color has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center is-style-chevron has-x-dark-blue-color has-text-color\">Noticias<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-nowrap is-layout-flex wp-container-core-buttons-is-layout-60eede3f wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-action-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/story\/\">Leer<\/a><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center is-style-chevron has-x-dark-blue-color has-text-color\">Blog<\/h2>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-nowrap is-layout-flex wp-container-core-buttons-is-layout-21295d6f wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50 is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-action-yellow-background-color has-text-color has-background has-text-align-right wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/blog\/\">Leer<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:auto 34%\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">Animales en Peligro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><a href=\"https:\/\/animalesenpeligro.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Animales en Peligro<\/a><\/strong> es la nueva serie documental conducida por <strong>Natalia Oreiro<\/strong>, producida por Cimarr\u00f3n y Greenpeace, y distribuida por Glowstar Media que invita a conocer las especies m\u00e1s amenazadas de Sudam\u00e9rica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La serie sigue a un\u00a0<strong>grupo de j\u00f3venes influencers que emprenden un viaje por diferentes destinos latinoamericanos<\/strong>\u00a0con una misi\u00f3n urgente: y necesaria:\u00a0<strong>proteger a la fauna local y generar conciencia en la audiencia sobre las numerosas especies de la regi\u00f3n en peligro de extinci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Producida por\u00a0<a href=\"https:\/\/cimarroncine.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cimarr\u00f3n\u00a0<\/a>y Greenpeace, con\u00a0<a href=\"https:\/\/glowstar-media.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Glowstar Media<\/a>\u00a0como Productor Asociado, estar\u00e1\u00a0<strong>disponible en el\u00a0<a href=\"https:\/\/www.flow.com.ar\/\" target=\"_blank\" rel=\"noreferrer noopener\">On Demand de Flow<\/a>\u00a0desde el 6 de noviembre.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/animalesenpeligro.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a1Mirala ahora!<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2025\/10\/1694113e-1-nw-aep_main-poster_720x1080-683x1024.png\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2.9412),(min-width: 1200px) calc((1140px - 24px) \/ 2.9412),(min-width: 992px) calc((960px - 24px) \/ 2.9412),(min-width: 768px) calc((720px - 24px) \/ 2.9412),(min-width: 601px) calc((540px - 24px) \/ 2.9412),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2025\/10\/1694113e-1-nw-aep_main-poster_720x1080.png 720w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2025\/10\/1694113e-1-nw-aep_main-poster_720x1080-200x300.png 200w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2025\/10\/1694113e-1-nw-aep_main-poster_720x1080-683x1024.png 683w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2025\/10\/1694113e-1-nw-aep_main-poster_720x1080-227x340.png 227w\" class=\"wp-image-32050 size-full\"\/><\/figure><\/div>\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg-1024x1024.jpg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg.jpg 1080w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg-300x300.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg-1024x1024.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg-150x150.jpg 150w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg-768x768.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/c64bd096-postwp1-arg-340x340.jpg 340w\" class=\"wp-image-23409 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">Canal de WhatsApp<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Unite a nuestro canal de WhatsApp para recibir todas las novedades de las campa\u00f1as y sumarte a acciones digitales por el planeta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1S\u00e9 parte del cambio hoy! \ud83c\udf0d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te esperamos \ud83d\udc9a<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/whatsapp.com\/channel\/0029VaU9Qu21dAvxd5Xgsc2f\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a1Sumate ahora!<\/a><\/div>\n<\/div>\n<\/div><\/div>\n\n<div class=\"wp-block-group block is-pattern-p4-get-informed-pattern-layout is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-image-fill-element has-white-background-color has-background\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">Podcast : &#8220;Sonido ambiente&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de 6 episodios reflexionamos y brindamos alternativas que no generen enormes consecuencias sobre el planeta<\/p>\n\n\n\n<div class=\"wp-block-buttons is-vertical is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-afab3323 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/open.spotify.com\/show\/6o3uxUOSnPDUHMt6uROVK1\" target=\"_blank\" rel=\"noreferrer noopener\">Escuh\u00e1 todos los episodios<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/bosques\/escucha-el-podcast-de-greenpeace-sonido-ambiente-y-empeza-a-cambiar-tus-habitos-ahora\/\">Le\u00e9 m\u00e1s sobre los episodios<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"388\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/03\/39cfbaca-websonidoambientebanner-3-1024x388.png\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/03\/39cfbaca-websonidoambientebanner-3.png 1484w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/03\/39cfbaca-websonidoambientebanner-3-300x114.png 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/03\/39cfbaca-websonidoambientebanner-3-1024x388.png 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/03\/39cfbaca-websonidoambientebanner-3-768x291.png 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/03\/39cfbaca-websonidoambientebanner-3-510x193.png 510w\" class=\"wp-image-18563 size-full\" style=\"object-position:50% 50%\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top is-image-fill-element has-white-background-color has-background\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-768x1024.jpg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-scaled.jpg 1920w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-225x300.jpg 225w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-768x1024.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-1152x1536.jpg 1152w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-1536x2048.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-1025x1366.jpg 1025w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/01\/9bdf0871-poster_006-255x340.jpg 255w\" class=\"wp-image-14243 size-large\" style=\"object-position:59% 88%\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Serie infantil: &#8220;Lina y los amigos del Arco\u00edris&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En cada cap\u00edtulo, de aproximadamente 11 minutos de duraci\u00f3n,&nbsp;<strong>Lina y sus amigos enfrentar\u00e1n aventuras para cuidar el planeta<\/strong><\/p>\n\n\n\n<div class=\"wp-block-buttons is-vertical is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-df7bfe9b wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.youtube.com\/playlist?list=PLgR0D19YPNICFIWvamP3kxHw9qOXEcVSR\" target=\"_blank\" rel=\"noreferrer noopener\">Playlist en Youtube<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link has-grey-900-color has-action-yellow-background-color has-text-color has-background wp-element-button\" href=\" https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/oceanos\/se-estreno-lina-y-los-amigos-del-arcoiris-la-primera-serie-animada-de-greenpeace-en-argentina\/\">Le\u00e9 m\u00e1s sobre la serie<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-image-fill-element\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">\u00c1lbum musical: &#8220;Lina Music&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Se estren\u00f3 el primer \u00e1lbum&nbsp;musical de &#8220;Lina y los Amigos del Arco Iris&#8221;&nbsp;. Tiene su propio cana del Youtube.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-vertical is-layout-flex wp-container-core-buttons-is-layout-4fc3f8e1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.youtube.com\/@linamusicvideos\" target=\"_blank\" rel=\"noreferrer noopener\">Escuch\u00e1 en Youtube<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/story\/greenpeace\/greenpeace-se-une-al-mundo-de-la-musica-con-lina-y-los-amigos-del-arcoiris-la-serie-infantil-que-promueve-la-conciencia-ambiental\/\" target=\"_blank\" rel=\"noreferrer noopener\">Le\u00e9 m\u00e1s sobre el \u00e1lbum<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952-1024x576.jpg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952.jpg 1920w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952-300x169.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952-1024x576.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952-768x432.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952-1536x864.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2024\/03\/1224f221-vlcsnap-2023-11-24-10h59m27s952-510x287.jpg 510w\" class=\"wp-image-23293 size-full\" style=\"object-position:61% 60%\"\/><\/figure><\/div>\n\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-1024x683.jpg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-scaled.jpg 2560w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-1536x1024.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-2048x1366.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/04\/f963d3d5-avant-premier-credito-santiago-saferstein-greenpeace-37-510x340.jpg 510w\" class=\"wp-image-15561 size-full\" style=\"object-position:53% 23%\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Documental : &#8220;Por ac\u00e1, no!&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Film sobre la tragedia que enfrentar\u00e1 el Mar Argentino a consecuencia de la actividad petrolera<\/p>\n\n\n\n<div class=\"wp-block-buttons is-vertical is-layout-flex wp-container-core-buttons-is-layout-4fc3f8e1 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.youtube.com\/watch?v=hdPoEBDMzhI&amp;t=17s\" target=\"_blank\" rel=\"noreferrer noopener\">Mir\u00e1 el documental<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link has-x-dark-blue-color has-yellow-background-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/oceanos\/greenpeace-presento-su-documental-por-aca-no-con-chino-darin-natalie-perez-y-diego-poggi\/\">Le\u00e9 m\u00e1s sobre el documental<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:36px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">Marcha virtual por los humedales: &#8220;Fuego Cero&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En Argentina los humedales representan&nbsp;<strong>aproximadamente el 21% del territorio, pero no existe un marco legal que los proteja<\/strong>.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-vertical is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-afab3323 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.youtube.com\/watch?v=KmaHHHhtgCE\" target=\"_blank\" rel=\"noreferrer noopener\">Mir\u00e1 la marcha virtual<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/tag\/humedales\/\">Le\u00e9 m\u00e1s sobre el tema<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"857\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2020\/09\/61f78375-fuego-cero-lineup-1000x1000-1-e1696513312118-1024x857.jpg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2020\/09\/61f78375-fuego-cero-lineup-1000x1000-1-e1696513312118.jpg 1120w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2020\/09\/61f78375-fuego-cero-lineup-1000x1000-1-e1696513312118-300x251.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2020\/09\/61f78375-fuego-cero-lineup-1000x1000-1-e1696513312118-1024x857.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2020\/09\/61f78375-fuego-cero-lineup-1000x1000-1-e1696513312118-768x643.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2020\/09\/61f78375-fuego-cero-lineup-1000x1000-1-e1696513312118-406x340.jpg 406w\" class=\"wp-image-10776 size-full\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-image-fill-element\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-1024x680.jpg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1.jpg 2500w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-300x199.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-1024x680.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-768x510.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-1536x1020.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-2048x1360.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/09\/b62e7cb9-2013-salta-desmontes-1-510x340.jpg 510w\" class=\"wp-image-21283 size-full\" style=\"object-position:50% 50%\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">Desmonte ilegal: &#8220;Historias de impunidad&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un claro ejemplo de la impunidad con la que se viola la Ley de Bosques. El desmonte ilegal debe ser un delito penal. <\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-39697d9b wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.youtube.com\/watch?v=vA_1L87jyTs&amp;list=PLgR0D19YPNIC6sej8tJW6OQXYiiUmde9U&amp;pp=iAQB\" target=\"_blank\" rel=\"noreferrer noopener\">Mir\u00e1 todos los cap\u00edtulos en la playlist de Youtube<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/bosques\/mas-de-260-000-personas-votaron-si-a-defender-los-bosques-en-la-consulta-popular-de-greenpeace\/\">Le\u00e9 m\u00e1s sobre la Consulta Popular<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<h2 class=\"wp-block-heading\">Revista digital : &#8220;Semillas Andinas&#8221;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Cada una de las ediciones est\u00e1 dedicada a una tem\u00e1tica ambiental especial, con informaci\u00f3n, tips y actividades, para que los ni\u00f1os y las ni\u00f1as aprendan a cuidar el planeta.&nbsp;Este proyecto forma parte de nuestras iniciativas de educaci\u00f3n ambiental.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/landing.infogreenpeace.org\/es-ar\/semandinasnuestrahistoria-0-0?_ga=2.15578422.1250131297.1698420107-79114371.1698326155\" target=\"_blank\" rel=\"noreferrer noopener\">Descarg\u00e1 la edici\u00f3n especial<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/landing.infogreenpeace.org\/es-ar\/es-ar\/descarga_semandinas\" target=\"_blank\" rel=\"noreferrer noopener\">Descarg\u00e1 todas las ediciones<\/a><\/div>\n<\/div>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"626\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1-1024x626.png\" alt=\"Revista: Semillas andinas\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1.png 1808w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1-300x184.png 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1-1024x626.png 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1-768x470.png 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1-1536x940.png 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/10\/fed579c2-imagenopenrevista-1-510x312.png 510w\" class=\"wp-image-21832 size-full\"\/><\/figure><\/div>\n\n\n\n\n\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-medium-font-size\">Continu\u00e1 explorando<\/h3>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-style-mobile-carousel is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group group-stretched-link is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized force-no-lightbox force-no-caption mb-0 is-style-rounded-180\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/nuestros-barcos\/\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" title=\"Barcos Rainbow Warrior III en Australia\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2019\/10\/1b62a5cb-unnamed-2.jpg\" alt=\"Imagen del barco insignia de la organizaci\u00f3n ambientalista Greenpeace navegando en Great Australian Bight con un atardecer de fondo.\" class=\"wp-image-2784\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2019\/10\/1b62a5cb-unnamed-2.jpg 800w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2019\/10\/1b62a5cb-unnamed-2-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2019\/10\/1b62a5cb-unnamed-2-768x513.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2019\/10\/1b62a5cb-unnamed-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><figcaption class=\"wp-element-caption\">Barcos Rainbow Warrior III en Australia<\/figcaption><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-size:1rem\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/nuestros-barcos\/\">Nuestros barcos<\/a><\/h4>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group group-stretched-link is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized force-no-lightbox force-no-caption mb-0 is-style-rounded-180\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/participa\/voluntariado\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" title=\"GP03BMG\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-1024x682.jpg\" alt=\"\" class=\"wp-image-13125\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-1024x682.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-768x511.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-1536x1022.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-2048x1363.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2021\/09\/001cdc33-2011-noviembre.-levantando-turbina-eolica-en-sudafrica.-510x340.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Voluntarios de Greenpeace levantan una turbina e\u00f3lica en la playa de Durban, Sud\u00e1frica, enviando un mensaje de esperanza para la \u00faltima ronda de conversaciones de la ONU sobre cambio clim\u00e1tico.<\/figcaption><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-size:1rem\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/participa\/voluntariado\/\">Voluntarios<\/a><\/h4>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group group-stretched-link is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized force-no-lightbox force-no-caption mb-0 is-style-rounded-180\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/campanas\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" title=\"_GPA Accion Humedales BA Martin Katz Greenpeace (2)\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-1024x683.jpg\" alt=\"\" class=\"wp-image-16809\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-768x513.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-1536x1025.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-2048x1366.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/09\/d98292d7-gpa-accion-humedales-ba-martin-katz-greenpeace-2-510x340.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Bajo las consignas LeydeHumedalesYa, NoCualquierLey y BastaDeQuemas, m\u00e1s de 500 organizaciones en m\u00e1s de veinte provincias se movilizan en el marco de la Acci\u00f3n Plurinacional por los Humedales, para pedir protecci\u00f3n efectiva a estos ecosistemas. El epicentro es en Rosario, afectada por el humo de las quemas de humedales en forma casi permanente, con una marcha multitudinaria y corte en el puente.<\/figcaption><\/figure>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading has-text-align-center\" style=\"font-size:1rem\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/campanas\/\">Campa\u00f1as<\/a><\/h4>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Desde Greenpeace generamos diversos  contenidos: Series, Tik Tok, Podcast, Documentales, Canal en Twitch y m\u00e1s!<\/p>\n","protected":false},"author":55,"featured_media":20266,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ep_exclude_from_search":false,"p4_hide_page_title_checkbox":"on","p4_title":"","p4_subtitle":"","p4_description":"","background_image_id":"","background_image":"","p4_button_title":"","p4_button_link":"","p4_button_link_checkbox":"","p4_og_title":"Informate","p4_og_description":"Desde Greenpeace generamos diversos tipos de contenido para que puedas informarte seg\u00fan tu preferencia. La informaci\u00f3n nos empodera, nos permite tomar conciencia y decidir con criterio.","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[37],"tags":[],"class_list":["post-19882","page","type-page","status-publish","has-post-thumbnail","hentry","category-greenpeace"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/19882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/comments?post=19882"}],"version-history":[{"count":20,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/19882\/revisions"}],"predecessor-version":[{"id":34977,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/pages\/19882\/revisions\/34977"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/media\/20266"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/media?parent=19882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/categories?post=19882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/tags?post=19882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}