{"id":17829,"date":"2023-01-27T15:06:56","date_gmt":"2023-01-27T18:06:56","guid":{"rendered":"https:\/\/www.greenpeace.org\/argentina\/?p=17829"},"modified":"2026-06-29T07:39:21","modified_gmt":"2026-06-29T10:39:21","slug":"si-un-futuro-verde-es-posible-por-que-cuesta-imaginar-un-mundo-mejor-en-diez-anos","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/climayenergia\/si-un-futuro-verde-es-posible-por-que-cuesta-imaginar-un-mundo-mejor-en-diez-anos\/","title":{"rendered":"Si un futuro verde es posible, \u00bfpor qu\u00e9 cuesta imaginar un mundo mejor en diez a\u00f1os?"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" title=\"2a1bca23-gp0stua8z-1024x683-1\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/2a1bca23-gp0stua8z-1024x683-1.jpg\" alt=\"\" class=\"wp-image-17830\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/2a1bca23-gp0stua8z-1024x683-1.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/2a1bca23-gp0stua8z-1024x683-1-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/2a1bca23-gp0stua8z-1024x683-1-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/2a1bca23-gp0stua8z-1024x683-1-510x340.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Huelga por el Clima en Bangkok. \u00a9 Chanklang Kanthong \/ Greenpeace<\/figcaption><\/figure>\n\n<p>En esta nota queremos que<strong> nos acompa\u00f1es a viajar en el tiempo<\/strong>: vamos directo hacia el futuro <strong>hasta llegar al a\u00f1o 2032<\/strong>. Para entonces, lo que parec\u00eda imposible ahora se ha vuelto realidad. <strong>El planeta pas\u00f3 por la transformaci\u00f3n social, econ\u00f3mica y cultural m\u00e1s extraordinaria<\/strong>. Ahora contanos:<strong> \u00bfC\u00f3mo cre\u00e9s que ser\u00eda ese cambio? \u00bfQu\u00e9 es lo que visualiz\u00e1s?&nbsp;<\/strong><\/p>\n\n<p>Te apostamos que<strong> si fuera por lo que la industria del entretenimiento (del cine y las series<\/strong>) nos venden, <strong>lo primero que imaginar\u00edamos ser\u00edan escenarios apocal\u00edpticos<\/strong>. Para esta narrativa lo \u00fanico que nos espera son ciudades en ruinas, plagas, poblaciones sin agua, sin alimento y en guerra.&nbsp;<\/p>\n\n<p><strong>A\u00fan cuando la ficci\u00f3n propone un porvenir con grandes avances tecnol\u00f3gicos, resulta que esta herramienta se vuelve en nuestra contra.<\/strong> As\u00ed son cientos las historias sobre celulares, c\u00e1maras e inteligencia artificial que terminan us\u00e1ndose para hiper vigilarnos y hacer nuestras vidas m\u00e1s tristes y mon\u00f3tonas (<strong>basta pensar en la serie Black Mirror<\/strong>.)&nbsp;<\/p>\n\n<p>En cambio<strong> te proponemos corrernos de lo que otros dicen que pasar\u00e1 y poner en acci\u00f3n tu propio optimismo.<\/strong> Si se realizara el deseo de <strong>una nueva sociedad que privilegie la vida de sus habitantes (humanos y no humanos) antes que al crecimiento econ\u00f3mico y las finanzas<\/strong>, \u00bfc\u00f3mo se ver\u00eda?&nbsp;<\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button aligncenter is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/argentina\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cambiemos juntos el futuro <\/a><\/div>\n<\/div>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" title=\"b9539de5-gp0stu1at-1024x683-1\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/b9539de5-gp0stu1at-1024x683-1.jpg\" alt=\"\" class=\"wp-image-17831\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/b9539de5-gp0stu1at-1024x683-1.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/b9539de5-gp0stu1at-1024x683-1-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/b9539de5-gp0stu1at-1024x683-1-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/b9539de5-gp0stu1at-1024x683-1-510x340.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Comunidades del Archipi\u00e9lago Bailique (Amap\u00e1, Brasil) recibieron freezers que funcionan a energ\u00eda solar de parte de Greenpeace Brasil. \u00a9 Diego Baravelli \/ Greenpeace<\/figcaption><\/figure>\n\n<p>Para empezar, y aunque en ese futuro deseable a\u00fan habr\u00eda que vivir los impactos del cambio clim\u00e1tico, <strong>ser\u00edamos m\u00e1s resilientes gracias a haber optado por una econom\u00eda verde inclusiva, equitativa y socialmente justa<\/strong>.&nbsp;<\/p>\n\n<p>\u00bfQu\u00e9 y c\u00f3mo producir\u00edan las industrias? \u00bfQu\u00e9 tipo de trabajos existir\u00edan? \u00bfLas ciudades ser\u00edan m\u00e1s caminables, con aire m\u00e1s limpio y m\u00e1s espacios con naturaleza recuperada? \u00bfQu\u00e9 energ\u00eda usar\u00edamos y c\u00f3mo ser\u00edan producidos los alimentos? \u00bfQu\u00e9 tipo de educaci\u00f3n se dar\u00eda a las personas?&nbsp;<\/p>\n\n<p>Sabemos que pensar en positivo puede parecer ingenuo, pero no lo es. <strong>Necesitamos vislumbrar un futuro esperanzador para empezar hoy mismo a crearlo.<\/strong> Y tenemos que hacerlo enfrent\u00e1ndonos al aluvi\u00f3n de noticias desmoralizantes y la narrativa hollywoodense, lo que dificulta m\u00e1s las cosas.&nbsp;<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"688\" title=\"9bcf2a30-gp0stoqse-1024x688-1\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/9bcf2a30-gp0stoqse-1024x688-1.jpg\" alt=\"\" class=\"wp-image-17832\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/9bcf2a30-gp0stoqse-1024x688-1.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/9bcf2a30-gp0stoqse-1024x688-1-300x202.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/9bcf2a30-gp0stoqse-1024x688-1-768x516.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/9bcf2a30-gp0stoqse-1024x688-1-506x340.jpg 506w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Activistas de Greenpeace con miembros de ONGs de Sudam\u00e9rica preparados para protestar pac\u00edficamente en Chorillos, Lima (Per\u00fa).  \u00a9 Greenpeace \/ Eva Petschull<\/figcaption><\/figure>\n\n<p>Debemos recordarnos que esta lucha a\u00fan no est\u00e1 definida y estamos a tiempo de cambiar el resultado. <strong>Para poder revertir este pesimismo<\/strong> que parece dominar al pensar en las pr\u00f3ximas d\u00e9cadas, <strong>el ejercicio de imaginar otra realidad posible es un gran primer paso.<\/strong> Como suele decirse si pod\u00e9s creerlo, pod\u00e9s crearlo.&nbsp;<\/p>\n\n<p><strong>El futuro Imposible<\/strong> <strong>puso en im\u00e1genes esa nueva forma de vivir en la que creemos<\/strong>, mir\u00e1:&nbsp;<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<lite-youtube style=\"background-image: url('https:\/\/i.ytimg.com\/vi\/O7UhUODR30k\/hqdefault.jpg');\" videoid=\"O7UhUODR30k\" params=\"rel=0\"><\/lite-youtube>\n<\/div><\/figure>\n\n<p>En la misma l\u00ednea, l<strong>a Campa\u00f1a Futuros Alternativos de Greenpeace <\/strong>busca ampliar las conversaciones y plataformas, compartiendo soluciones y trabajando para construir <strong>una visi\u00f3n en la que el planeta se priorice ante el crecimiento infinito de la econom\u00eda<\/strong>.<\/p>\n\n<p>El programa de esta campa\u00f1a<strong> desaf\u00eda la idea de que hay un solo modelo econ\u00f3mico que todos los pa\u00edses deben seguir.<\/strong> A la vez, busca escuchar y aprender de las muchas soluciones existentes que ya est\u00e1n en pr\u00e1ctica. Otra buena forma de abrir el panorama y ver el vaso medio lleno.<\/p>\n\n<p>Por \u00faltimo, vale sumar a esta reflexi\u00f3n el t\u00e9rmino africano <em>Ubuntu<\/em>, que significa \u201cSoy porque nosotros somos\u201d y que refiere a la creencia de que existe un lazo universal que conecta a toda la humanidad. Siguiendo este hermoso concepto, <strong>compartamos, aprendamos y pensemos qu\u00e9 tipo de futuro podemos crear para poder prosperar en armon\u00eda con la naturaleza<\/strong>. Te leemos en los comentarios.<\/p>\n\n<p>Compartimos <a href=\"https:\/\/www.greenpeace.org\/international\/story\/56644\/what-could-a-better-world-look-like-in-10-years\/\" target=\"_blank\" rel=\"noreferrer noopener\">la nota que dispar\u00f3 este tema<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si se realizara el deseo de una nueva sociedad que privilegie la vida de sus habitantes (humanos y no humanos) antes que al crecimiento econ\u00f3mico y las finanzas, \u00bfc\u00f3mo se ver\u00eda?\u00a0<\/p>\n","protected":false},"author":48,"featured_media":17830,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"Si un futuro verde es posible, \u00bfpor qu\u00e9 cuesta imaginar un mundo mejor en diez a\u00f1os?","p4_og_description":"Si se realizara el deseo de una nueva sociedad que privilegie la vida de sus habitantes (humanos y no humanos) antes que al crecimiento econ\u00f3mico y las finanzas, \u00bfc\u00f3mo se ver\u00eda?\u00a0","p4_og_image":"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2023\/01\/2a1bca23-gp0stua8z-1024x683-1.jpg","p4_og_image_id":"17830","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[3],"tags":[],"p4-page-type":[14],"class_list":["post-17829","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climayenergia","p4-page-type-blog"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/posts\/17829","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/comments?post=17829"}],"version-history":[{"count":7,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/posts\/17829\/revisions"}],"predecessor-version":[{"id":35073,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/posts\/17829\/revisions\/35073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/media\/17830"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/media?parent=17829"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/categories?post=17829"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/tags?post=17829"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/argentina\/wp-json\/wp\/v2\/p4-page-type?post=17829"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}