{"id":24606,"date":"2020-06-24T12:10:03","date_gmt":"2020-06-24T15:10:03","guid":{"rendered":"https:\/\/www.greenpeace.org\/brasil\/?p=24606"},"modified":"2022-06-30T16:35:48","modified_gmt":"2022-06-30T19:35:48","slug":"imagens-desmatamento-maio-2020","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/brasil\/imprensa\/imagens-desmatamento-maio-2020\/","title":{"rendered":"Imagens desmatamento Maio\/2020"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"432\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/b86738e8-claudia-2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-1024x432.jpg\" alt=\"\" class=\"wp-image-24609\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/b86738e8-claudia-2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-1024x432.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/b86738e8-claudia-2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-300x127.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/b86738e8-claudia-2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-768x324.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/b86738e8-claudia-2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-510x215.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/b86738e8-claudia-2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires.jpg 1366w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Claudia (MT): imagens do Sentinel-2 de 26\/04\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"432\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/25456f17-claudia-2020-06-15-00_00-2020-06-15-23_59-sentinel-2-s2l2a-wildfires-1024x432.jpg\" alt=\"\" class=\"wp-image-24607\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/25456f17-claudia-2020-06-15-00_00-2020-06-15-23_59-sentinel-2-s2l2a-wildfires-1024x432.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/25456f17-claudia-2020-06-15-00_00-2020-06-15-23_59-sentinel-2-s2l2a-wildfires-300x127.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/25456f17-claudia-2020-06-15-00_00-2020-06-15-23_59-sentinel-2-s2l2a-wildfires-768x324.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/25456f17-claudia-2020-06-15-00_00-2020-06-15-23_59-sentinel-2-s2l2a-wildfires-510x215.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/25456f17-claudia-2020-06-15-00_00-2020-06-15-23_59-sentinel-2-s2l2a-wildfires.jpg 1366w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Claudia (MT): imagens do Sentinel-2 de 15\/06\/2020, demonstrando 1.600 hectares de desmatamento.<br>Foi emitido alerta pelo DETER em 30\/05\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large is-resized  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/05984850-3irma\u0303os-altamira2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-1024x469.jpg\" alt=\"\" class=\"wp-image-24610\" width=\"795\" height=\"364\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/05984850-3irma\u0303os-altamira2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-1024x469.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/05984850-3irma\u0303os-altamira2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-300x137.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/05984850-3irma\u0303os-altamira2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-768x351.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/05984850-3irma\u0303os-altamira2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires-510x233.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/05984850-3irma\u0303os-altamira2020-04-26-00_00-2020-04-26-23_59-sentinel-2-s2l2a-wildfires.jpg 1366w\" sizes=\"auto, (max-width: 795px) 100vw, 795px\" \/><figcaption>Altamira (PA): imagens do Sentinel-2 de 26\/04\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"469\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/be178052-3irma\u0303os-altamira2020-06-05-00_00-2020-06-05-23_59-sentinel-2-s2l2a-wildfires-1024x469.jpg\" alt=\"\" class=\"wp-image-24611\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/be178052-3irma\u0303os-altamira2020-06-05-00_00-2020-06-05-23_59-sentinel-2-s2l2a-wildfires-1024x469.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/be178052-3irma\u0303os-altamira2020-06-05-00_00-2020-06-05-23_59-sentinel-2-s2l2a-wildfires-300x137.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/be178052-3irma\u0303os-altamira2020-06-05-00_00-2020-06-05-23_59-sentinel-2-s2l2a-wildfires-768x351.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/be178052-3irma\u0303os-altamira2020-06-05-00_00-2020-06-05-23_59-sentinel-2-s2l2a-wildfires-510x233.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/be178052-3irma\u0303os-altamira2020-06-05-00_00-2020-06-05-23_59-sentinel-2-s2l2a-wildfires.jpg 1366w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Altamira (PA): imagens do Sentinel-2 de 05\/06\/2020, demonstrando 1.700 hectares de desmatamento.<br>Foi emitido alerta pelo DETER em 01\/05\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"432\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1-1024x432.jpg\" alt=\"\" class=\"wp-image-24612\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1-1024x432.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1-300x127.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1-768x324.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1-1536x648.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1-510x215.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/c1c8a02b-apui\u0301-2020-03-28-00_00-2020-03-28-23_59-sentinel-2-s2l2a-wildfires-1.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Apu\u00ed (AM): imagens do Sentinel-2 de 28\/03\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"469\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires-1024x469.jpg\" alt=\"\" class=\"wp-image-24613\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires-1024x469.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires-300x137.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires-768x351.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires-1536x703.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires-510x233.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/3f14ee70-apui\u0301-2020-06-16-00_00-2020-06-16-23_59-sentinel-2-s2l2a-wildfires.jpg 1707w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>Apu\u00ed (AM): imagens do Sentinel-2 de 16\/06\/2020, demonstrando 1.600 hectares de desmatamento.<br>Foi emitido alerta pelo DETER em 21\/05\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"432\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/9e60a879-la\u0301brea-2020-01-09-00_00-2020-01-09-23_59-sentinel-2-s2l2a-true-color-1024x432.jpg\" alt=\"\" class=\"wp-image-24614\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/9e60a879-la\u0301brea-2020-01-09-00_00-2020-01-09-23_59-sentinel-2-s2l2a-true-color-1024x432.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/9e60a879-la\u0301brea-2020-01-09-00_00-2020-01-09-23_59-sentinel-2-s2l2a-true-color-300x127.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/9e60a879-la\u0301brea-2020-01-09-00_00-2020-01-09-23_59-sentinel-2-s2l2a-true-color-768x324.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/9e60a879-la\u0301brea-2020-01-09-00_00-2020-01-09-23_59-sentinel-2-s2l2a-true-color-510x215.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/9e60a879-la\u0301brea-2020-01-09-00_00-2020-01-09-23_59-sentinel-2-s2l2a-true-color.jpg 1242w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>L\u00e1brea (AM): imagens do Sentinel-2 de 09\/01\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n\n<figure class=\"wp-block-image size-large  caption-style-medium caption-alignment-center\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"432\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/283bf00b-la\u0301brea-2020-05-28-00_00-2020-05-28-23_59-sentinel-2-s2l2a-true-color-1024x432.jpg\" alt=\"\" class=\"wp-image-24615\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/283bf00b-la\u0301brea-2020-05-28-00_00-2020-05-28-23_59-sentinel-2-s2l2a-true-color-1024x432.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/283bf00b-la\u0301brea-2020-05-28-00_00-2020-05-28-23_59-sentinel-2-s2l2a-true-color-300x127.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/283bf00b-la\u0301brea-2020-05-28-00_00-2020-05-28-23_59-sentinel-2-s2l2a-true-color-768x324.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/283bf00b-la\u0301brea-2020-05-28-00_00-2020-05-28-23_59-sentinel-2-s2l2a-true-color-510x215.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/283bf00b-la\u0301brea-2020-05-28-00_00-2020-05-28-23_59-sentinel-2-s2l2a-true-color.jpg 1242w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption>La\u0301brea (AM): imagens do Sentinel-2 de 28\/05\/2020, demonstrando 1.500 hectares de desmatamento.<br>Foi emitido alerta pelo DETER em 09\/05\/2020<\/figcaption><\/figure>\n\n<hr class=\"wp-block-separator\"\/>\n<\/p>\n<p><center><\/p>\n<\/p>\n<p><\/center><\/p>\n\n<figure class=\"wp-block-embed\"><div class=\"wp-block-embed__wrapper\">\n<div style=\"width: 640px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-24606-1\" width=\"640\" height=\"360\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/6d1d1995-3-irma\u0303os-abril-maio.mp4?_=1\" \/><a href=\"https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/6d1d1995-3-irma\u0303os-abril-maio.mp4\">https:\/\/www.greenpeace.org\/static\/planet4-brasil-stateless\/2020\/06\/6d1d1995-3-irma\u0303os-abril-maio.mp4<\/a><\/video><\/div>\n<\/div><\/figure>\n<\/p>\n\n<p style=\"font-size:14px\" class=\"has-text-align-center\">Altamira (PA): evolu\u00e7\u00e3o do desmatamento de 26\/04\/2020 a 05\/06\/2020<br>A \u00e1rea desmatada foi de 1.700 hectares e o DETER emitiu alerta em 01\/05\/2020<br>Imagens do Sat\u00e9lite Sentinel-2<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Altamira (PA): evolu\u00e7\u00e3o do desmatamento de 26\/04\/2020 a 05\/06\/2020A \u00e1rea desmatada foi de 1.700 hectares e o DETER emitiu alerta em 01\/05\/2020Imagens do Sat\u00e9lite Sentinel-2<\/p>\n","protected":false},"author":28,"featured_media":24615,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[5],"tags":[22,55],"p4-page-type":[14],"class_list":["post-24606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-greenpeace","tag-florestas","tag-imprensa","p4-page-type-imprensa"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/posts\/24606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/comments?post=24606"}],"version-history":[{"count":14,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/posts\/24606\/revisions"}],"predecessor-version":[{"id":25160,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/posts\/24606\/revisions\/25160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/media\/24615"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/media?parent=24606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/categories?post=24606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/tags?post=24606"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/brasil\/wp-json\/wp\/v2\/p4-page-type?post=24606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}