{"id":38457,"date":"2021-03-01T16:51:00","date_gmt":"2021-03-01T21:51:00","guid":{"rendered":"https:\/\/www.greenpeace.org\/canada\/?p=38457"},"modified":"2021-11-17T14:39:56","modified_gmt":"2021-11-17T19:39:56","slug":"allons-chercher-largent-ou-il-se-trouve-en-taxant-les-multimillionaires","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/canada\/fr\/story\/38457\/allons-chercher-largent-ou-il-se-trouve-en-taxant-les-multimillionaires\/","title":{"rendered":"Allons chercher l&rsquo;argent o\u00f9 il se trouve: gr\u00e2ce \u00e0 un imp\u00f4t sur la fortune"},"content":{"rendered":"\n<p>La semaine derni\u00e8re, en discutant avec une bonne amie qui fait du b\u00e9n\u00e9volat aupr\u00e8s de personnes vivant temporairement dans un ar\u00e9na, mon c\u0153ur s&rsquo;est bris\u00e9. J&rsquo;ai \u00e9t\u00e9 confront\u00e9e au fait que la crise de la COVID-19 avait touch\u00e9 plus durement certaines personnes. \u00ab\u00a0<em>Beaucoup de personnes avec lesquelles je travaille sont des voyageurs et voyageuses qui ne peuvent tout simplement pas rentrer dans leur pays. Mais certain\u00b7es sont de nouvelles et nouveaux pauvres&#8230;<\/em>\u00a0\u00bb a-t-elle affirm\u00e9 avant de prendre une pause, \u00ab\u00a0<em>de nouvelles et nouveaux sans-abri<\/em>s\u00a0\u00bb a-t-elle expliqu\u00e9. Mes pens\u00e9es se sont tourn\u00e9es vers toutes ces familles qui peuvent g\u00e9n\u00e9ralement joindre les deux bouts, mais qui n&rsquo;ont pas de coussin pour faire face aux impr\u00e9vus.&nbsp;<\/p>\n\n<p>J&rsquo;ai alors allum\u00e9 la radio, Radio Canada pour \u00eatre exacte, et le journaliste expliquait comment un certain nombre d&rsquo;entreprises avaient accru leur richesse pendant cette pand\u00e9mie. Prenons un moment pour absorber la nouvelle. Alors que mon amie donne un coup de main \u00e0 des gens qui ont presque tout perdu, les empires que sont Facebook, Netflix, Amazon se d\u00e9veloppent&#8230; et les PDG (et malheureusement trop peu souvent leurs employ\u00e9\u00b7es) s&rsquo;enrichissent. Ces derni\u00e8res ann\u00e9es, des organisations comme Oxfam ont d\u2019ailleurs publi\u00e9 de nombreux ouvrages sur le foss\u00e9 grandissant entre les riches et les pauvres[1]. Il est juste de dire que la crise \u00e0 laquelle nous sommes confront\u00e9\u00b7es pr\u00e9sentement exacerbe l\u2019ironie et les in\u00e9galit\u00e9s de notre syst\u00e8me \u00e9conomique mondial.&nbsp;<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Imp\u00f4t sur la fortune: quelques statistiques<\/strong><\/h2>\n\n<p>Alors que la COVID-19 s\u00e9vit et se r\u00e9pand, un nouveau rapport de l&rsquo;<em>Institute for Policy Studies<\/em> [2] d\u00e9voile que la richesse des milliardaires am\u00e9ricain\u00b7es, elle, a augment\u00e9 de pr\u00e8s de 10 % en trois semaines seulement. En fait, Jeff Bezos, fondateur et directeur g\u00e9n\u00e9ral d&rsquo;Amazon, ainsi que Mark Zuckerberg, directeur g\u00e9n\u00e9ral de Facebook, en sont jusqu&rsquo;\u00e0 pr\u00e9sent les plus grands gagnants. Ils ont vu leur richesse combin\u00e9e augmenter de 63 milliards de dollars depuis le 18 mars[3].<\/p>\n\n<p>De notre c\u00f4t\u00e9 de la fronti\u00e8re, alors que la moiti\u00e9 des Canadien\u00b7nes s&rsquo;en sortent \u00e0 peine, un rapport publi\u00e9 en 2018 a r\u00e9v\u00e9l\u00e9 que 87 familles poss\u00e8dent plus de 259 milliards de dollars. Ceci repr\u00e9sente plus de la <strong><em>moiti\u00e9 <\/em><\/strong>de la richesse du pays [4]. Oui oui, vous avez bien lu: elles poss\u00e8dent la moiti\u00e9 de toutes les richesses du Canada!&nbsp;<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Pouvons-nous nous permettre de continuer \u00e0 faire comme si de rien n&rsquo;\u00e9tait, alors que les gens tr\u00e8s riches s&rsquo;enrichissent et que le reste d&rsquo;entre nous sommes sur le point d&rsquo;\u00eatre \u00e9cras\u00e9\u00b7es par une crise \u00e9conomique mondiale, possiblement, oserais-je dire, sans pr\u00e9c\u00e9dent?&nbsp;<\/strong><\/h2>\n\n<p>Au d\u00e9but, ma r\u00e9action fut instinctive: \u201cCe n&rsquo;est pas juste, les riches devraient payer pour la reprise \u00e9conomique.\u201d Puis, la responsable de l\u2019\u00e9quipe num\u00e9rique chez Greenpeace en moi a pris le dessus. Je me suis mise \u00e0 penser \u00e0 tous les changements positifs que notre gouvernement pourrait apporter gr\u00e2ce \u00e0 une relance v\u00e9ritablement verte. Nous pourrions orienter notre \u00e9conomie en investissant dans les \u00e9nergies renouvelables plut\u00f4t que dans le p\u00e9trole sale, r\u00e9ellement mettre en \u0153uvre les droits des travailleuses et des travailleurs, un syst\u00e8me de soin de sant\u00e9, les droits autochtones, etc, etc&#8230; En tant qu\u2019ancienne employ\u00e9e d\u2019Oxfam, mes pens\u00e9es se sont \u00e9galement tourn\u00e9es vers le syst\u00e8me fiscal : \u00e9vasion fiscale l\u00e9gale, favoritisme des entreprises&#8230; les r\u00e8gles du jeu encouragent une croissance \u00e9conomique infinie et sont con\u00e7ues pour ne profiter qu\u2019\u00e0 une minorit\u00e9.&nbsp;<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Comment pouvons-nous assurer une relance juste et verte?&nbsp;<\/strong>Quel pourrait \u00eatre le r\u00f4le d&rsquo;une taxe sur la richesse?<\/h2>\n\n<p>Alors que je me pose cette question, j&rsquo;ouvre ma bo\u00eete courriel personnelle (pensant \u00e0 tou\u00b7tes ces milliardaires et leur richesse en cliquant), pour trouver un courriel de Leadnow, abordant cette m\u00eame question. L&rsquo;organisation a pr\u00e9cis\u00e9 lors d&rsquo;une action qu&rsquo;elle a r\u00e9cemment lanc\u00e9e: \u00ab\u00a0sans une fiscalit\u00e9 juste et \u00e9quitable, ces fortunes continuent de monter en fl\u00e8che alors que nos salaires stagnent, que nos emplois disparaissent et que nos services publics s&rsquo;effritent\u00a0\u00bb[5]. Avec le r\u00e9cent ralentissement drastique de notre \u00e9conomie mondiale, c&rsquo;est peut-\u00eatre exactement vers cela que nous nous dirigeons.&nbsp;<\/p>\n\n<p><strong>Avec la crise sanitaire tragique \u00e0 laquelle nous sommes confront\u00e9<\/strong><strong>\u00b7e<\/strong><strong>s, nous avons peut-\u00eatre une occasion unique de redresser notre syst\u00e8me \u00e9conomique.<\/strong> Je ne pense pas seulement \u00e0 une aide temporaire pour les populations vuln\u00e9rables ici, je pense \u00e0 un changement syst\u00e9mique.&nbsp;<\/p>\n\n<p>Un r\u00e9cent sondage a r\u00e9v\u00e9l\u00e9 que les Canadien\u00b7nes soutiennent massivement un <strong>imp\u00f4t sur la richesse des multimillionnaires<\/strong>, afin d&rsquo;aider \u00e0 financer la relance suite \u00e0 la COVID et \u00e0 r\u00e9duire les in\u00e9galit\u00e9s croissantes[6]. En regardant les chiffres et le monde qui nous entoure, pouvons-nous nous permettre de ne pas prendre des mesures imm\u00e9diates et urgentes pour lutter contre les in\u00e9galit\u00e9s de revenus ?<\/p>\n\n<p>Qu&rsquo;en pensez-vous ? Alors que notre gouvernement reconstruit nos politiques et notre \u00e9conomie pour faire face \u00e0 une crise sans pr\u00e9c\u00e9dent, nous pouvons mieux reconstruire. <strong>Devrions-nous rendre notre syst\u00e8me fiscal plus \u00e9quitable, au lieu de le maintenir tel qu\u2019il est, injuste et truqu\u00e9, pour continuer de rendre les riches plus riches ?<\/strong><\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link\" href=\"https:\/\/act.greenpeace.ca\/fr-ca\/instaurer-un-impot-sur-la-fortune\">Signez la p\u00e9tition<\/a><\/div>\n<\/div>\n\n<p>[1]<a href=\"https:\/\/www.reuters.com\/article\/us-davos-meeting-inequality\/gap-between-rich-and-poor-growing-fuelling-global-anger-oxfam-idUSKCN1PF00P\">https:\/\/www.reuters.com\/article\/us-davos-meeting-inequality\/gap-between-rich-and-poor-growing-fuelling-global-anger-oxfam-idUSKCN1PF00P<\/a><\/p>\n\n<p>[2]<a href=\"https:\/\/ips-dc.org\/billionaire-bonanza-2020\/\">https:\/\/ips-dc.org\/billionaire-bonanza-2020\/<\/a><\/p>\n\n<p>[3]<a href=\"https:\/\/markets.businessinsider.com\/news\/stocks\/us-billionaires-add-485-billion-net-worth-during-pandemic-report-2020-5-1029263947\">https:\/\/markets.businessinsider.com\/news\/stocks\/us-billionaires-add-485-billion-net-worth-during-pandemic-report-2020-5-1029263947<\/a><\/p>\n\n<p>[4]<a href=\"https:\/\/www.theguardian.com\/world\/2018\/jul\/31\/canada-richest-families-same-wealth-12-million-people-report\">https:\/\/www.theguardian.com\/world\/2018\/jul\/31\/canada-richest-families-same-wealth-12-million-people-report<\/a><\/p>\n\n<p>[5]<a href=\"https:\/\/act.leadnow.ca\/wealth-tax-super-rich\/\">https:\/\/act.leadnow.ca\/wealth-tax-super-rich\/<\/a><br>[6]<a href=\"https:\/\/ricochet.media\/en\/3143\/canadas-top-billionaires-are-getting-richer-thanks-to-covid-19-and-donating-a-pittance\">https:\/\/ricochet.media\/en\/3143\/canadas-top-billionaires-are-getting-richer-thanks-to-covid-19-and-donating-a-pittance<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En discutant avec une bonne amie qui fait du b\u00e9n\u00e9volat avec des personnes vivant temporairement dans un ar\u00e9na la semaine derni\u00e8re, mon c\u0153ur s&rsquo;est bris\u00e9 en r\u00e9alisant \u00e0 quel point&hellip;<\/p>\n","protected":false},"author":63,"featured_media":38468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[20,19,21],"tags":[41,47,49,83],"p4-page-type":[155],"class_list":["post-38457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climat","category-nature-fr","category-vivre-de-facon-durable","tag-climat","tag-petrole","tag-solutionsenergetiques","tag-consommation","p4-page-type-histoire"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/38457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/users\/63"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/comments?post=38457"}],"version-history":[{"count":12,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/38457\/revisions"}],"predecessor-version":[{"id":50889,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/38457\/revisions\/50889"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/media\/38468"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/media?parent=38457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/categories?post=38457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/tags?post=38457"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/p4-page-type?post=38457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}