{"id":42541,"date":"2020-09-24T12:31:19","date_gmt":"2020-09-24T16:31:19","guid":{"rendered":"https:\/\/www.greenpeace.org\/canada\/?p=42541"},"modified":"2020-11-25T09:48:42","modified_gmt":"2020-11-25T14:48:42","slug":"discours-du-trone-du-blabla-ou-des-bonnes-nouvelles","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/canada\/fr\/blog-des-volontaires\/42541\/discours-du-trone-du-blabla-ou-des-bonnes-nouvelles\/","title":{"rendered":"Discours du Tr\u00f4ne: du blabla ou des bonnes nouvelles?"},"content":{"rendered":"\n<p><strong>Notre grille d\u2019\u00e9valuation vous dira si le gouvernement compte s\u2019attaquer aux in\u00e9galit\u00e9s et \u00e0 la crise climatique<\/strong>.<\/p>\n\n<div class=\"wp-block-image  caption-style-medium caption-alignment-center\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" title=\"justin trudeau \u00e9valuation greenpeace discours du tr\u00f4ne\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2020\/09\/5caf4d61-3.png\" alt=\"\" class=\"wp-image-42609\" width=\"470\" height=\"394\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2020\/09\/5caf4d61-3.png 940w, https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2020\/09\/5caf4d61-3-300x251.png 300w, https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2020\/09\/5caf4d61-3-768x644.png 768w, https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2020\/09\/5caf4d61-3-406x340.png 406w\" sizes=\"auto, (max-width: 470px) 100vw, 470px\" \/><\/figure><\/div>\n\n<p>Le gouvernement f\u00e9d\u00e9ral a pr\u00e9sent\u00e9 son discours du Tr\u00f4ne le 23 septembre, ouvrant la nouvelle session parlementaire et annon\u00e7ant les plans et les priorit\u00e9s du gouvernement.&nbsp;<\/p>\n\n<p><strong>La mouture 2020 du discours \u00e9tait particuli\u00e8rement attendue &#8211; et vous lirez ci-dessous s\u2019il a \u00e9t\u00e9 \u00e0 la hauteur des attentes. <\/strong>Il est important cette ann\u00e9e en raison du fait que les cas de COVID-19 augmentent \u00e0 nouveau et qu\u2019une r\u00e9cession \u00e9conomique sans pr\u00e9c\u00e9dent affecte le pays, touchant plus durement les femmes, les personnes racialis\u00e9es et les m\u00e9nages \u00e0 faible revenu. Les plans pr\u00e9sent\u00e9s dans le discours fa\u00e7onneront directement notre avenir.<\/p>\n\n<p>Plus que jamais, la crise climatique et l&rsquo;effondrement de la biodiversit\u00e9 ont des r\u00e9percussions directes sur notre vie quotidienne. Les feux de for\u00eat s&rsquo;aggravent et leurs fum\u00e9es toxiques ne connaissent pas de fronti\u00e8res. Les grandes inondations et les temp\u00eates sont de plus en plus fr\u00e9quentes et les co\u00fbts d&rsquo;assurances augmentent. Des chercheurs ont \u00e9tabli que <a href=\"https:\/\/unearthed.greenpeace.org\/2020\/04\/24\/deforestation-amazon-next-pandemic-covid-coronavirus\/\">31 % des \u00e9pid\u00e9mies de maladies infectieuses \u00e9mergentes<\/a> sont li\u00e9es \u00e0 la destruction des for\u00eats et des \u00e9cosyst\u00e8mes.&nbsp;<\/p>\n\n<p><strong>Chez Greenpeace Canada, nous demandons que le discours du Tr\u00f4ne pr\u00e9sente un plan qui r\u00e9ponde aux multiples crises auxquelles nous sommes confront\u00e9\u00b7es.<\/strong> Les moments de crise ouvrent le champ du possible et permettent d\u2019adopter des id\u00e9es et des mesures qui \u00e9taient autrefois consid\u00e9r\u00e9es comme impensables. Ainsi, les lib\u00e9raux du Premier ministre Trudeau ont la possibilit\u00e9 de voir grand et de faire preuve d&rsquo;audace afin de s\u2019attaquer aux probl\u00e8mes syst\u00e9miques qui affectent notre soci\u00e9t\u00e9. Pour ce faire, <a href=\"https:\/\/www.greenpeace.org\/canada\/fr\/histoires\/40389\/quest-ce-quun-changement-systemique-et-comment-pouvons-nous-mieux-reconstruire-apres-la-covid-19\/\">nous avons mis \u00e0 leur disposition une feuille de route visant \u00e0 construire une \u00e9conomie forte, durable et \u00e9quitable<\/a>. Et nous ne nous sommes pas arr\u00eat\u00e9\u00b7es l\u00e0, nous avons m\u00eame r\u00e9dig\u00e9 <a href=\"https:\/\/www.greenpeace.org\/canada\/fr\/histoires\/42137\/discours-du-trone-de-greenpeace-canada\/\">notre version du discours du Tr\u00f4ne<\/a>.&nbsp;<\/p>\n\n<p><strong>Comment les promesses des lib\u00e9raux se comparent-elles aux demandes de Greenpeace? Lisez la suite et d\u00e9couvrez le r\u00e9sultat.<\/strong><\/p>\n\n<h2 class=\"wp-block-heading\"><strong>Impressions g\u00e9n\u00e9rales<\/strong><\/h2>\n\n<p>Ce discours du Tr\u00f4ne 2020 du gouvernement lib\u00e9ral de Justin Trudeau est l&rsquo;un des plus ambitieux et des plus progressistes que l\u2019on ait vu depuis des ann\u00e9es &#8211; mais ces ambitions demeureront vides de sens si elles ne sont pas suivies d\u2019actions concr\u00e8tes. <strong>Nous donnons aux lib\u00e9raux cette ann\u00e9e une note plus \u00e9lev\u00e9e que d&rsquo;habitude. Cependant, c\u2019est au fruit que l\u2019on juge l\u2019arbre (soit les lettres de mandat minist\u00e9riel \u00e0 venir et la mise \u00e0 jour \u00e9conomique pr\u00e9vue cette automne). Il manquait de d\u00e9tails pour \u00e9valuer de nombreuses politiques et statuer si les plans des lib\u00e9raux sont \u00e0 la hauteur&#8230; m\u00eame si leurs promesses semblent all\u00e9chantes.<\/strong><\/p>\n\n<style>\n  .tweet {\n    position: relative;\n    margin: 10px 0 10px 64px;\n    padding: 10px;\n    background: #ffffff;\n    font-size: 15px;\n    white-space: pre-wrap;\n    font-family: system-ui, -apple-system, BlinkMacSystemFont, \"Segoe UI\", Roboto, Ubuntu, \"Helvetica Neue\", sans-serif;\n    line-height: 1.3125;\n  }\n  .tweet::before {\n    position: absolute;\n    left: -59px;\n    background-image: url(\"https:\/\/www.thefutureoftransportconference.com\/images\/twitter.png\");\n    background-repeat: no-repeat;\n    background-size: 49px 49px;\n    width: 49px;\n    height: 49px;\n    content: \"\";\n    display: block;\n    float: left;\n    border-radius: 32px;\n  }\n\n  .twitter-mention, .twitter-link {\n    color: rgb(42, 163, 239);\n  }\n\n  .twitter-hashtag {\n    font-weight: bold;\n  }\n  .twitter-image {\n    max-width: 100%;\n    width: 300px;\n  }\n\n  .float-me-right {\n    float: right;\n  }\n  .click-to-tweet-btn {\n    text-align: right;\n  }\n  .click-to-tweet-btn a {\n    font-size: 15px;\n    font-weight: bold;\n    font-family: system-ui, -apple-system, BlinkMacSystemFont, \"Segoe UI\", Roboto, Ubuntu, \"Helvetica Neue\", sans-serif;\n    color: white;\n    background-color: rgb(29, 161, 242);\n    transition-property: background-color;\n    transition-duration: 0.2s;\n    user-select: none;\n    padding: 8px 15px;\n    border-radius: 9999px;\n  }\n  .click-to-tweet-btn a:hover {\n    background-color: rgb(26, 145, 218);\n  }\n<\/style>\n\n<div class=\"tweet\">\n  Le bon, le mauvais, le suspicieux:  comment les promesses du <span class=\"twitter-hashtag\">#DiscoursduTrone<\/span> se comparent \u00e0 ce qui doit \u00eatre fait pour qu&rsquo;une <span class=\"twitter-hashtag\">#RelanceJuste<\/span> et verte devienne r\u00e9alit\u00e9.\nPour y r\u00e9pondre, voici la grille d\u2019\u00e9valuation de <span class=\"twitter-mention\">@GreenpeaceQC<\/span> &gt;&gt;<span class=\"twitter-link\">https:\/\/act.gp\/2G3Tjvy<\/span>\n<span class=\"twitter-hashtag\">#polcan<\/span> <span class=\"twitter-hashtag\">#RelanceVerte<\/span>\n\n<\/div>\n<div class=\"click-to-tweet-btn\">\n  <a href=\"https:\/\/twitter.com\/intent\/tweet?text=Le%20bon%2C%20le%20mauvais%2C%20le%20suspicieux%3A%20%20comment%20les%20promesses%20du%20%23DiscoursduTrone%20se%20comparent%20%C3%A0%20ce%20qui%20doit%20%C3%AAtre%20fait%20pour%20qu'une%20%23RelanceJuste%20et%20verte%20devienne%20r%C3%A9alit%C3%A9.%0APour%20y%20r%C3%A9pondre%2C%20voici%20la%20grille%20d%E2%80%99%C3%A9valuation%20de%20%40GreenpeaceQC%20%3E%3Ehttps%3A%2F%2Fact.gp%2F2G3Tjvy%0A%23polcan%20%23RelanceVerte%0A\">Tweet<\/a>\n<\/div>\n\n<div class=\"tweet\">\n  Est-ce que les belles paroles du <span class=\"twitter-hashtag\">#DiscoursduTrone<\/span> se traduiront par des actions concr\u00e8tes et une <span class=\"twitter-hashtag\">#RelanceJuste<\/span> et verte?\n<span class=\"twitter-mention\">@GreenpeaceQC<\/span> analyse le bon du mauvais du suspicieux?\npic.twitter.com\/lR7gidzzWc pic.twitter.com\/KcFjt3qWJa\npic.twitter.com\/oNqgk3TpsO\n&gt;<span class=\"twitter-link\">https:\/\/act.gp\/3i47o9A<\/span>\n<\/div>\n<div class=\"click-to-tweet-btn\">\n  <a href=\"https:\/\/twitter.com\/intent\/tweet?text=Est-ce%20que%20les%20belles%20paroles%20du%20%23DiscoursduTrone%20se%20traduiront%20par%20des%20actions%20concr%C3%A8tes%20et%20une%20%23RelanceJuste%20et%20verte%3F%0A%40GreenpeaceQC%20analyse%20le%20bon%20du%20mauvais%20du%20suspicieux%F0%9F%91%87%0Apic.twitter.com%2FlR7gidzzWc%20pic.twitter.com%2FKcFjt3qWJa%0Apic.twitter.com%2FoNqgk3TpsO%0A%3Ehttps%3A%2F%2Fact.gp%2F3i47o9A\">Tweet<\/a>\n<\/div>\n\n<p><strong>L\u00e9gende : nos recommandations sont-elles pr\u00e9sentes dans le discours?<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/QdWRd642hlcBaKGKWG8-D5jxx9cLLcbiuuwolyN7xtSmbiyxd2Mi9ypBguN-AAjm9Xmhjp2oN3UMmeJiA2V39DTECgDARuNQx9_cZFJsG2BPnIaQuNMOeBkTlr5VxmBU2AbEU_uY\" style=\"width: 35px;\"><\/td><td>Oui, ce qui a \u00e9t\u00e9 annonc\u00e9 va dans la bonne direction.<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 35px;\"><\/td><td>En quelque sorte, mais pas compl\u00e8tement.<\/td><\/tr><tr><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/Xu52ZqtYby3-Ly0K_KOjRPbb7rkV_71_SXuMMsGlek-epSADN2cNyXCR9KfymD-u0TBQaecr0n0MvjiZvzT_gehMEzXG-zESICTatfNqz1LHerUCJb5rAHrf_oecqOt7FFAFcwad\" style=\"width: 35px;\"><\/td><td>Non, ceci n\u2019a pas \u00e9t\u00e9 mentionn\u00e9 ou c\u2019est en r\u00e9gression.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"has-text-color has-background has-grey-200-color has-genoa-background-color\"><strong>Am\u00e9liorer le filet de s\u00e9curit\u00e9 sociale<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Les recommandations de Greenpeace Canada&nbsp;<\/strong><\/td><td><strong>Dans le discours?<\/strong><\/td><\/tr><tr><td>Un salaire viable et une allocation universelle.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/Xu52ZqtYby3-Ly0K_KOjRPbb7rkV_71_SXuMMsGlek-epSADN2cNyXCR9KfymD-u0TBQaecr0n0MvjiZvzT_gehMEzXG-zESICTatfNqz1LHerUCJb5rAHrf_oecqOt7FFAFcwad\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Un programme national de services de garde.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/QdWRd642hlcBaKGKWG8-D5jxx9cLLcbiuuwolyN7xtSmbiyxd2Mi9ypBguN-AAjm9Xmhjp2oN3UMmeJiA2V39DTECgDARuNQx9_cZFJsG2BPnIaQuNMOeBkTlr5VxmBU2AbEU_uY\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Un programme national d\u2019assurance-m\u00e9dicaments.&nbsp;<\/td><td><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/QdWRd642hlcBaKGKWG8-D5jxx9cLLcbiuuwolyN7xtSmbiyxd2Mi9ypBguN-AAjm9Xmhjp2oN3UMmeJiA2V39DTECgDARuNQx9_cZFJsG2BPnIaQuNMOeBkTlr5VxmBU2AbEU_uY\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Un programme national de cong\u00e9 maladie.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/Xu52ZqtYby3-Ly0K_KOjRPbb7rkV_71_SXuMMsGlek-epSADN2cNyXCR9KfymD-u0TBQaecr0n0MvjiZvzT_gehMEzXG-zESICTatfNqz1LHerUCJb5rAHrf_oecqOt7FFAFcwad\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Des conditions de travail s\u00e9curitaires pour le personnel soignant.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/QdWRd642hlcBaKGKWG8-D5jxx9cLLcbiuuwolyN7xtSmbiyxd2Mi9ypBguN-AAjm9Xmhjp2oN3UMmeJiA2V39DTECgDARuNQx9_cZFJsG2BPnIaQuNMOeBkTlr5VxmBU2AbEU_uY\" style=\"width: 50px;\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"has-text-color has-background has-grey-200-color has-genoa-background-color\"><strong>Prot\u00e9ger l\u2019environnement<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Les recommandations de Greenpeace Canada&nbsp;<\/strong><\/td><td><strong>Dans le discours?<\/strong><\/td><\/tr><tr><td>Une strat\u00e9gie de d\u00e9carbonisation de l\u2019\u00e9conomie d\u2019ici \u00e0 2040.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Des plans pour prot\u00e9ger 30% des sols, des oc\u00e9ans et des r\u00e9serves d\u2019eau douce d&rsquo;ici 2030.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>L\u2019expansion des infrastructures pi\u00e9tonnes et cyclables, et des r\u00e9seaux de transports en communs \u00e9lectriques.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Des plans pour amorcer la transition des constructeurs automobiles vers l\u2019\u00e9lectrique d\u2019ici 2030.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>La construction de logements sociaux ou abordables, \u00e0 faible empreinte carbone pour les communaut\u00e9s vuln\u00e9rables.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/QdWRd642hlcBaKGKWG8-D5jxx9cLLcbiuuwolyN7xtSmbiyxd2Mi9ypBguN-AAjm9Xmhjp2oN3UMmeJiA2V39DTECgDARuNQx9_cZFJsG2BPnIaQuNMOeBkTlr5VxmBU2AbEU_uY\" style=\"width: 50px;\"><\/td><\/tr><tr><td>La cr\u00e9ation d\u2019emplois pour la r\u00e9habilitation d\u2019\u00e9cosyst\u00e8mes naturels vitaux et d\u00e9grad\u00e9s.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>La cr\u00e9ation d&#8217;emplois en agriculture communautaire et r\u00e9g\u00e9n\u00e9rative.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>La prise de mesures visant \u00e0 b\u00e2tir une \u00e9conomie v\u00e9ritablement circulaire,&nbsp; encourageant les innovations en mati\u00e8re de z\u00e9ro d\u00e9chet et&nbsp; interdisant les plastiques \u00e0 usage unique.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"has-text-color has-background has-grey-200-color has-genoa-background-color\"><strong>Droits des femmes, des Peuples autochtones et des personnes racialis\u00e9es<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Les recommandations de Greenpeace Canada&nbsp;<\/strong><\/td><td><strong>Dans le discours?<\/strong><\/td><\/tr><tr><td>Prendre des mesures pour att\u00e9nuer la r\u00e9cession au f\u00e9minin, garantir un salaire \u00e9gal et une meilleure s\u00e9curit\u00e9 d\u2019emploi pour toutes les femmes.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh5.googleusercontent.com\/QdWRd642hlcBaKGKWG8-D5jxx9cLLcbiuuwolyN7xtSmbiyxd2Mi9ypBguN-AAjm9Xmhjp2oN3UMmeJiA2V39DTECgDARuNQx9_cZFJsG2BPnIaQuNMOeBkTlr5VxmBU2AbEU_uY\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Respecter les droits des Peuples autochtones, mettre en \u0153uvre la r\u00e9conciliation, assurer la justice pour les <a href=\"https:\/\/www.mmiwg-ffada.ca\/fr\/\">FFADA<\/a>, garantir l\u2019acc\u00e8s \u00e0 l\u2019eau potable et \u00e0 des logements d\u00e9cents.<\/td><td>&nbsp;<img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>D\u00e9financer la GRC et investir dans des programmes de sant\u00e9 mentale pour les populations racialis\u00e9es.<\/td><td>&nbsp;<img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Accorder la citoyennet\u00e9 et de meilleures conditions d\u2019emploi aux personnes migrantes.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p class=\"has-text-color has-background has-grey-200-color has-genoa-background-color\"><strong>Comment financer ces mesures?<\/strong><\/p>\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Les recommandations de Greenpeace Canada&nbsp;<\/strong><\/td><td><strong>Dans le discours?<\/strong><\/td><\/tr><tr><td>\u00c9tablir un imp\u00f4t sur la fortune.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Interdire les paradis fiscaux<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/Xu52ZqtYby3-Ly0K_KOjRPbb7rkV_71_SXuMMsGlek-epSADN2cNyXCR9KfymD-u0TBQaecr0n0MvjiZvzT_gehMEzXG-zESICTatfNqz1LHerUCJb5rAHrf_oecqOt7FFAFcwad\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Cesser de subventionner l&rsquo;industrie des \u00e9nergies fossiles.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/Xu52ZqtYby3-Ly0K_KOjRPbb7rkV_71_SXuMMsGlek-epSADN2cNyXCR9KfymD-u0TBQaecr0n0MvjiZvzT_gehMEzXG-zESICTatfNqz1LHerUCJb5rAHrf_oecqOt7FFAFcwad\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Annuler la construction du pipeline Trans Mountain<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/Xu52ZqtYby3-Ly0K_KOjRPbb7rkV_71_SXuMMsGlek-epSADN2cNyXCR9KfymD-u0TBQaecr0n0MvjiZvzT_gehMEzXG-zESICTatfNqz1LHerUCJb5rAHrf_oecqOt7FFAFcwad\" style=\"width: 50px;\"><\/td><\/tr><tr><td>Obliger les grands pollueurs \u00e0 payer leur juste part pour financer les efforts de lutte aux changements climatiques.<\/td><td><img decoding=\"async\" src=\"https:\/\/lh4.googleusercontent.com\/GRh8qa8Hg1cJ_usCbenbKdEYp1OQw-JqUZj81on-sKVBoLjIjsjGGqKdnkrj836LLIul-MtG91naWvyNM0J_o2hRRvw4yRmvc5SS7tueFKH3v2OJZ66rQ43kB2WHfBv0vB8MPGNn\" style=\"width: 50px;\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n<h2 class=\"wp-block-heading\">Voici un rapide aper\u00e7u du meilleur et du pire du discours du Tr\u00f4ne 2020.<\/h2>\n\n<h3 class=\"wp-block-heading\"><strong>Le bon: des mesures qui tendent vers une relance verte et juste&nbsp;&nbsp;<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li>Les changements climatiques seront la pierre angulaire de la strat\u00e9gie pour cr\u00e9er un million d\u2019emplois.<\/li><li>&nbsp;Des plans pour d\u00e9carboniser la soci\u00e9t\u00e9 et rendre la vie plus saine et plus abordable, gr\u00e2ce aux v\u00e9hicules \u00e0 \u00e9mission z\u00e9ro, aux transports en commun et actifs, \u00e0 un meilleur acc\u00e8s \u00e0 la nature et aux parcs, et \u00e0 des logements verts.<\/li><li>Un plan pour aborder la r\u00e9cession au f\u00e9minin avec un programme d\u2019emplois pour les femmes et un programme national de service de garde.<\/li><li>Un soutien aux communaut\u00e9s pour renforcer leur r\u00e9silience face \u00e0 l&rsquo;aggravation des catastrophes climatiques, comme les inondations et les incendies.<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Le mauvais : le recyclage de vieilles promesses non tenues et peu convaincantes<\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li>Des mesures recycl\u00e9es de la plate-forme \u00e9lectorale de 2019 ou du Cadre pancanadien sur le changement climatique de 2016 ont \u00e9t\u00e9 incluses sans que leur ambition n\u2019ait \u00e9t\u00e9 bonifi\u00e9e.<\/li><li>Aucune nouvelle promesse n&rsquo;a \u00e9t\u00e9 faite concernant l&rsquo;interdiction des plastiques \u00e0 usage unique d\u00e9j\u00e0 annonc\u00e9e en 2019. La promesse d\u2019augmenter le recyclage donnent de faux espoirs \u00e0 la population, comme si l\u2019on pouvait r\u00e9gler la crise du plastique sans r\u00e9duire la production \u00e0 la source.<\/li><li>La r\u00e9apparition de la promesse de planter 2 milliards d&rsquo;arbres, insuffisante pour atteindre le niveau de protection de la nature n\u00e9cessaire (sans parler du fait que c&rsquo;est une promesse sur laquelle aucun progr\u00e8s n&rsquo;a \u00e9t\u00e9 fait en un an).<\/li><li>Des engagements en faveur des droits des peuples autochtones et de la r\u00e9conciliation qui sonnent creux, apr\u00e8s des ann\u00e9es de statu quo et de non-respect du droit des Premi\u00e8res Nations, M\u00e9tis et Inuit\u00b7es. <a href=\"https:\/\/www.princegeorgecitizen.com\/reactions-to-the-minority-liberal-government-s-speech-from-the-throne-1.24208451\">Comme l&rsquo;a d\u00e9clar\u00e9 le chef de l&rsquo;APN, Perry Bellegarde, au sujet de la D\u00e9claration des Nations unies sur les droits des peuples autochtones<\/a>, \u00ab\u00a0je ne serai pas heureux tant que je n&rsquo;aurai pas entendu deux mots : <a href=\"https:\/\/sencanada.ca\/fr\/a-propos\/references-procedures\/notes\/n6\/\">sanction royale<\/a>\u00ab\u00a0.[1]&nbsp;<\/li><\/ul>\n\n<h3 class=\"wp-block-heading\"><strong><strong>Le suspicieux: le recours aux fausses solutions<\/strong><\/strong><\/h3>\n\n<ul class=\"wp-block-list\"><li>Au cours des derni\u00e8res semaines, le gouvernement Lib\u00e9ral a laiss\u00e9 entendre de mani\u00e8re peu subtile qu&rsquo;il pr\u00e9voyait mettre en place des mesures vertes, mais aussi, une s\u00e9rie de mesures qu\u2019on pourrait qualifier de \u00ab\u00a0fausses solutions\u00a0\u00bb: elles semblent vertes, mais sont en fait dommageables pour l&rsquo;environnement. Plus pr\u00e9cis\u00e9ment, il a indiqu\u00e9 qu&rsquo;<a href=\"https:\/\/www.ctvnews.ca\/politics\/cleaner-lng-one-answer-to-climate-change-crisis-o-regan-tells-investors-1.5095332\">il souhaitait d\u00e9velopper la fracturation<\/a> (en lien avec l\u2019exploitation du gaz naturel) et <a href=\"https:\/\/www.cbc.ca\/radio\/thehouse\/chris-hall-there-s-no-path-to-net-zero-without-nuclear-power-says-o-regan-1.5730197\">mettre en service des r\u00e9acteurs nucl\u00e9aires risqu\u00e9s<\/a>. Ce genre de <em>greenwashing<\/em> pourrait annuler la progression de nos objectifs climatiques et mettre en danger notre avenir.<\/li><li>Si vous ne vous rappelez pas la mention de ces \u00e9nergies nocives dans le discours du Tr\u00f4ne, vous avez raison. Cependant, vous pouvez \u00e9galement vous demander ce que voulait dire la Gouverneure g\u00e9n\u00e9rale en faisant allusion \u00e0 des \u00ab\u00a0solutions de la prochaine g\u00e9n\u00e9ration en mati\u00e8re d&rsquo;\u00e9nergie et de technologies propres\u00a0\u00bb, eh bien &#8230; Voil\u00e0 que vous pourriez bien avoir trouv\u00e9 la r\u00e9ponse.<\/li><\/ul>\n\n<h2 class=\"wp-block-heading\"><strong>Que se passe-t-il apr\u00e8s le discours du Tr\u00f4ne ?<\/strong><\/h2>\n\n<p>Apr\u00e8s le discours du Tr\u00f4ne, le Premier ministre donnera \u00e0 ses ministres des instructions plus d\u00e9taill\u00e9es dans ce que l&rsquo;on appelle des \u00ab lettres de mandat \u00bb, o\u00f9 seront expos\u00e9s la l\u00e9gislation et les programmes sur lesquels les ministres et leurs \u00e9quipes doivent se pencher. Ces instructions devraient \u00eatre rendues publiques dans les deux semaines suivant le discours du Tr\u00f4ne. Un mini-budget (aussi appel\u00e9 la mise \u00e0 jour \u00e9conomique) devra ensuite \u00eatre pr\u00e9sent\u00e9 par le gouvernement f\u00e9d\u00e9ral d\u2019ici novembre 2020.<\/p>\n\n<div class=\"wp-block-buttons aligncenter is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-text-color has-background\" href=\"https:\/\/act.greenpeace.org\/page\/60162\/action\/1?locale=fr-CA&amp;\" style=\"background-color:#f36d3a;color:#ffffff\">SIGNEZ LA P\u00c9TITION<\/a><\/div>\n<\/div>\n\n<p><em>[1] La sanction royale est l\u2019approbation par le souverain d\u2019un projet de loi adopt\u00e9 dans une forme identique par les deux Chambres du Parlement. C\u2019est le processus \u00e0 l\u2019issue duquel un projet de loi devient une loi du Parlement et une partie int\u00e9grante des lois du Canada. Au Canada, la sanction royale est accord\u00e9e par le gouverneur g\u00e9n\u00e9ral ou un de ses suppl\u00e9ants (un juge de la Cour supr\u00eame du Canada ou un haut fonctionnaire tel le secr\u00e9taire du gouverneur g\u00e9n\u00e9ral). (<a href=\"https:\/\/sencanada.ca\/fr\/a-propos\/references-procedures\/notes\/n6\/\">source<\/a>)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre grille d\u2019\u00e9valuation vous dira si le gouvernement compte s\u2019attaquer aux in\u00e9galit\u00e9s et \u00e0 la crise climatique.<\/p>\n","protected":false},"author":18,"featured_media":42609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[20,21,19],"tags":[40,41,43,46,47,48,72,83],"p4-page-type":[],"class_list":["post-42541","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climat","category-vivre-de-facon-durable","category-nature-fr","tag-autochtones","tag-climat","tag-forets","tag-oceans-fr","tag-petrole","tag-sante","tag-plastique","tag-consommation"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/42541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/comments?post=42541"}],"version-history":[{"count":18,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/42541\/revisions"}],"predecessor-version":[{"id":44814,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/42541\/revisions\/44814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/media\/42609"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/media?parent=42541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/categories?post=42541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/tags?post=42541"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/p4-page-type?post=42541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}