{"id":62103,"date":"2023-11-29T14:57:03","date_gmt":"2023-11-29T19:57:03","guid":{"rendered":"https:\/\/www.greenpeace.org\/canada\/?p=62103"},"modified":"2023-11-29T15:01:02","modified_gmt":"2023-11-29T20:01:02","slug":"cop28-note-dinformation","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/canada\/fr\/story\/62103\/cop28-note-dinformation\/","title":{"rendered":"COP28 Note d\u2019information"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2023\/11\/86d619aa-gpca-cop28-greenpeace-note-dinformation.docx-2.pdf\">Note d&rsquo;information<\/a><\/p>\n\n<p><em>La COP28 cl\u00f4ture une ann\u00e9e caract\u00e9ris\u00e9e par des temp\u00e9ratures record et des ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames sans pr\u00e9c\u00e9dent. Les climatologues du monde entier ont soulign\u00e9 la n\u00e9cessit\u00e9 de proc\u00e9der \u00e0 une r\u00e9duction importante et imm\u00e9diate des \u00e9missions de gaz effet de serre (GES) afin de limiter le r\u00e9chauffement \u00e0 1,5 \u00b0C et propos\u00e9 des moyens d&rsquo;y parvenir. Quant \u00e0 l&rsquo;Agence internationale de l\u2019\u00e9nergie, elle a \u00e9tabli une trajectoire ambitieuse mais r\u00e9alisable de r\u00e9duction des combustibles fossiles et d&rsquo;acc\u00e9l\u00e9ration du passage aux sources d&rsquo;\u00e9nergie renouvelable, et ce en vue de respecter l&rsquo;objectif des 1,5 oC.<\/em><\/p>\n\n<p><em>Les causes et les cons\u00e9quences des changements climatiques n&rsquo;ont jamais \u00e9t\u00e9 aussi claires, et les solutions n&rsquo;ont jamais \u00e9t\u00e9 aussi \u00e0 port\u00e9e de main. Les combustibles fossiles nous tuent, mais les \u00e9nergies renouvelables sont porteuses d&rsquo;un avenir meilleur. Or, l&rsquo;augmentation des \u00e9missions et l&rsquo;expansion pr\u00e9vue de la production de combustibles fossiles ne sont absolument pas en phase avec les progr\u00e8s que nous devons accomplir. De plus, le soutien financier visant \u00e0 r\u00e9duire les \u00e9missions dans les pays les plus pauvres, ainsi que les fonds affect\u00e9s \u00e0 la lutte contre l&rsquo;aggravation des impacts des changements climatiques, reste tout \u00e0 fait insuffisant. La COP28, qui constitue un v\u00e9ritable test de r\u00e9sistance pour l&rsquo;Accord de Paris, sera l&rsquo;occasion de faire face aux faits, de rectifier le tir et de donner aux solutions une r\u00e9elle chance de porter leurs fruits.<\/em><\/p>\n\n<p><strong>Ce dont nous avons besoin lors de la COP28<\/strong><\/p>\n\n<ol class=\"wp-block-list\">\n<li>C&rsquo;est lors de la COP28 \u00e0 Duba\u00ef que les pays devront enfin s&rsquo;engager \u00e0 nous affranchir des combustibles fossiles. C&rsquo;est \u00e0 ce moment que les leaders de ce monde devront d\u00e9cider de mettre fin \u00e0 l&rsquo;expansion du charbon, du p\u00e9trole et du gaz et d&rsquo;acc\u00e9l\u00e9rer la transition vers les \u00e9nergies renouvelables, tout en proc\u00e9dant \u00e0 une \u00e9limination progressive, \u00e9quitable et contr\u00f4l\u00e9e des combustibles fossiles.<\/li>\n\n\n\n<li>Le bilan mondial de la COP28 (Global Stocktake) doit se solder par des r\u00e9sultats qui permettront de mettre en \u0153uvre des actions transformatrices dans tous les domaines afin de limiter le r\u00e9chauffement climatique \u00e0 1,5 \u00b0C et de faire face aux cons\u00e9quences climatiques grandissantes.<\/li>\n\n\n\n<li>Le succ\u00e8s ne sera possible qu&rsquo;avec un ensemble de mesures financi\u00e8res cr\u00e9dibles correspondant aux besoins r\u00e9els, comprenant le lancement d&rsquo;un nouveau fonds pour les pertes et dommages et nous rapprochant de l&rsquo;objectif de faire payer les pollueurs pour la destruction et les dommages dont ils sont responsables.<\/li>\n<\/ol>\n\n<p>Nos attentes sont d\u00e9taill\u00e9es dans la <a href=\"https:\/\/www.greenpeace.org\/static\/planet4-canada-stateless\/2023\/11\/86d619aa-gpca-cop28-greenpeace-note-dinformation.docx-2.pdf\">Note d&rsquo;information de Greenpeace Canada<\/a> et le dossier politique int\u00e9gral de Greenpeace est disponible&nbsp;<a href=\"https:\/\/www.greenpeace.org\/static\/planet4-international-stateless\/2023\/11\/2bf4dd7d-greenpeace-cop28-policy-brief.pdf\">ici&nbsp;(en anglais)<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos attentes sont d\u00e9taill\u00e9es dans la Note d&rsquo;information de Greenpeace Canada, et le dossier politique int\u00e9gral de Greenpeace, disponible\u00a0ici\u00a0(en anglais).<\/p>\n","protected":false},"author":30,"featured_media":62104,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[20],"tags":[41,47,49],"p4-page-type":[155],"class_list":["post-62103","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-climat","tag-climat","tag-petrole","tag-solutionsenergetiques","p4-page-type-histoire"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/62103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/comments?post=62103"}],"version-history":[{"count":4,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/62103\/revisions"}],"predecessor-version":[{"id":62111,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/posts\/62103\/revisions\/62111"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/media\/62104"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/media?parent=62103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/categories?post=62103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/tags?post=62103"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/canada\/fr\/wp-json\/wp\/v2\/p4-page-type?post=62103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}