{"id":10887,"date":"2023-11-29T16:25:10","date_gmt":"2023-11-29T16:25:10","guid":{"rendered":"https:\/\/www.greenpeace.org\/colombia\/?p=10887"},"modified":"2026-06-29T10:20:54","modified_gmt":"2026-06-29T10:20:54","slug":"dia-internacional-del-jaguar-fotogaleria-y-datos-curiosos-para-apreciar-y-valorar-al-felino-mas-imponente","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/colombia\/blog\/campanas\/bosques\/dia-internacional-del-jaguar-fotogaleria-y-datos-curiosos-para-apreciar-y-valorar-al-felino-mas-imponente\/","title":{"rendered":"D\u00eda Internacional del Jaguar: fotogaler\u00eda y datos curiosos para apreciar y valorar al felino m\u00e1s imponente"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"667\" title=\"D\u00eda Internacional del Yaguaret\u00e9\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-colombia-stateless\/2023\/11\/7c5f3b91-yaguarete-1.jpg\" alt=\"\" class=\"wp-image-10894\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-colombia-stateless\/2023\/11\/7c5f3b91-yaguarete-1.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-colombia-stateless\/2023\/11\/7c5f3b91-yaguarete-1-300x195.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-colombia-stateless\/2023\/11\/7c5f3b91-yaguarete-1-768x500.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-colombia-stateless\/2023\/11\/7c5f3b91-yaguarete-1-510x332.jpg 510w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Se estima que quedan s\u00f3lo 20 en la regi\u00f3n del Gran Chaco y alrededor de 250 en toda la zona; el felino m\u00e1s grande de nuestro continente se encuentra en \u201cpeligro cr\u00edtico\u201d seg\u00fan organismos  oficiales y son muchos los motivos para destacar su importancia y revertir esta situaci\u00f3n.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Hoy es el <strong>D\u00eda Internacional del Jaguar<\/strong>, un momento perfecto para hablar de la importancia que este felino tiene para nuestro pa\u00eds y la regi\u00f3n. Y tambi\u00e9n para apreciar toda su belleza \ud83d\ude0d.<\/p>\n<div data-hydrate=\"planet4-blocks\/gallery\" data-attributes=\"{&quot;attributes&quot;:{&quot;multiple_image&quot;:&quot;10893,10889,10890,10892&quot;,&quot;image_data&quot;:[{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/8e592cb3-gp0sttkhi_low_res_with_credit_line.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:10893},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/d4ac3818-gp0sttkh2_low_res_with_credit_line.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:10889},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/9d9a0883-gp0sttkh4_low_res_with_credit_line.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:10890},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/fe1dc497-gp0sttkhe_low_res_with_credit_line.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:10892}],&quot;className&quot;:&quot;is-style-grid&quot;,&quot;gallery_block_style&quot;:0,&quot;gallery_block_title&quot;:&quot;&quot;,&quot;gallery_block_description&quot;:&quot;&quot;,&quot;gallery_block_focus_points&quot;:&quot;&quot;,&quot;images&quot;:[{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/8e592cb3-gp0sttkhi_low_res_with_credit_line.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/8e592cb3-gp0sttkhi_low_res_with_credit_line.jpg 800w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/8e592cb3-gp0sttkhi_low_res_with_credit_line-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/8e592cb3-gp0sttkhi_low_res_with_credit_line-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/8e592cb3-gp0sttkhi_low_res_with_credit_line-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Un jaguar (Panthera onca) en Mato Grosso, Brasil.\\n\\nLa foto est\\u00e1 tomada en el norte del Pantanal, en el estado de Mato Grosso, en plena selva, espec\\u00edficamente en la zona de Porto Jofre, Pocon\\u00e9, aguas arriba y aguas abajo del r\\u00edo Cuiab\\u00e1.&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/d4ac3818-gp0sttkh2_low_res_with_credit_line.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/d4ac3818-gp0sttkh2_low_res_with_credit_line.jpg 800w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/d4ac3818-gp0sttkh2_low_res_with_credit_line-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/d4ac3818-gp0sttkh2_low_res_with_credit_line-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/d4ac3818-gp0sttkh2_low_res_with_credit_line-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Un jaguar (Panthera onca) en Mato Grosso, Brasil.\\n\\nLa foto est\\u00e1 tomada en el norte del Pantanal, en el estado de Mato Grosso, en plena selva, espec\\u00edficamente en la zona de Porto Jofre, Pocon\\u00e9, aguas arriba y aguas abajo del r\\u00edo Cuiab\\u00e1.&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/9d9a0883-gp0sttkh4_low_res_with_credit_line.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/9d9a0883-gp0sttkh4_low_res_with_credit_line.jpg 800w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/9d9a0883-gp0sttkh4_low_res_with_credit_line-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/9d9a0883-gp0sttkh4_low_res_with_credit_line-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/9d9a0883-gp0sttkh4_low_res_with_credit_line-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Un jaguar (Panthera onca) en Mato Grosso, Brasil.\\n\\nLa foto est\\u00e1 tomada en el norte del Pantanal, en el estado de Mato Grosso, en plena selva, espec\\u00edficamente en la zona de Porto Jofre, Pocon\\u00e9, aguas arriba y aguas abajo del r\\u00edo Cuiab\\u00e1.&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/fe1dc497-gp0sttkhe_low_res_with_credit_line.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/fe1dc497-gp0sttkhe_low_res_with_credit_line.jpg 800w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/fe1dc497-gp0sttkhe_low_res_with_credit_line-300x200.jpg 300w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/fe1dc497-gp0sttkhe_low_res_with_credit_line-768x512.jpg 768w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/fe1dc497-gp0sttkhe_low_res_with_credit_line-510x340.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Un jaguar (Panthera onca) en Mato Grosso, Brasil.\\n\\nLa foto est\\u00e1 tomada en el norte del Pantanal, en el estado de Mato Grosso, en plena selva, espec\\u00edficamente en la zona de Porto Jofre, Pocon\\u00e9, aguas arriba y aguas abajo del r\\u00edo Cuiab\\u00e1.&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;}]}}\"><section class=\"block gallery-grid is-style-grid\"><\/section><\/div>\n<p class=\"wp-block-paragraph\">Te contamos algunos datos sobre el mayor f\u00e9lido del continente y el tercero del mundo.<\/p>\n\n<p class=\"wp-block-paragraph\">\ud83d\udc06En guaran\u00ed <strong>su nombre significa \u201cverdadera fiera\u201d<\/strong> y es considerado un animal sagrado.&nbsp;<\/p>\n\n<p class=\"wp-block-paragraph\">\ud83d\udc06Para muchos pueblos originarios, la historia del animal es parte de su propia historia. Por ejemplo, <strong>para los Chan\u00e9s de Campo Dur\u00e1n, en la provincia de Salta, el jaguar es su t\u00edo<\/strong>, un pariente cercano, por este motivo saben que nunca los va a atacar.<\/p>\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<lite-youtube style=\"background-image: url('https:\/\/i.ytimg.com\/vi\/7Rbz0M9evbg\/hqdefault.jpg');\" videoid=\"7Rbz0M9evbg\" params=\"rel=0\"><\/lite-youtube>\n<\/div><figcaption class=\"wp-element-caption\"><strong>En este documental te enter\u00e1s m\u00e1s sobre esta valiosa creencia.&nbsp;<\/strong><\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">\ud83d\udc06Son <strong>excelentes nadadores, solitarios y muy territoriales<\/strong>.&nbsp;&nbsp;<\/p>\n\n<p class=\"wp-block-paragraph\">\ud83d\udc06En Argentina, <strong>la especie fue desplazada del 95% del territorio que habitaba<\/strong>. Los pocos individuos que quedan se ven amenazados no s\u00f3lo por la p\u00e9rdida de su h\u00e1bitat sino tambi\u00e9n por la caza y los atropellamientos en las rutas y caminos.<\/p>\n<div data-hydrate=\"planet4-blocks\/gallery\" data-attributes=\"{&quot;attributes&quot;:{&quot;multiple_image&quot;:&quot;10895,10896&quot;,&quot;gallery_block_focus_points&quot;:&quot;{\\&quot;17350\\&quot;:\\&quot;50% 50%\\&quot;,\\&quot;21964\\&quot;:\\&quot;86% 22%\\&quot;}&quot;,&quot;image_data&quot;:[{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:10895},{&quot;url&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2.jpg&quot;,&quot;focalPoint&quot;:{&quot;x&quot;:0.5,&quot;y&quot;:0.5},&quot;id&quot;:10896}],&quot;className&quot;:&quot;is-style-three-columns&quot;,&quot;gallery_block_style&quot;:0,&quot;gallery_block_title&quot;:&quot;&quot;,&quot;gallery_block_description&quot;:&quot;&quot;,&quot;images&quot;:[{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3.jpg 2560w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3-300x166.jpg 300w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3-1024x568.jpg 1024w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3-768x426.jpg 768w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3-1536x852.jpg 1536w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3-2048x1136.jpg 2048w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/417f0b97-yaguarete-3-510x283.jpg 510w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Se estima que quedan s\\u00f3lo 20 en la regi\\u00f3n del Gran Chaco y alrededor de 250 en todo el pa\\u00eds; el felino m\\u00e1s grande de nuestro continente se encuentra en \\u201cpeligro cr\\u00edtico\\u201d seg\\u00fan organismos  oficiales y son muchos los motivos para destacar su importancia y revertir esta situaci\\u00f3n.&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;},{&quot;image_src&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2.jpg&quot;,&quot;image_srcset&quot;:&quot;https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2.jpg 1200w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2-300x225.jpg 300w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2-1024x768.jpg 1024w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2-768x576.jpg 768w, https:\\\/\\\/www.greenpeace.org\\\/static\\\/planet4-colombia-stateless\\\/2023\\\/11\\\/16080d8f-yaguarete2-453x340.jpg 453w&quot;,&quot;image_sizes&quot;:false,&quot;alt_text&quot;:&quot;&quot;,&quot;caption&quot;:&quot;Un jaguar (Panthera onca) en Mato Grosso, Brasil.\\n\\nLa foto est\\u00e1 tomada en el norte del Pantanal, en el estado de Mato Grosso, en plena selva, espec\\u00edficamente en la zona de Porto Jofre, Pocon\\u00e9, aguas arriba y aguas abajo del r\\u00edo Cuiab\\u00e1.&quot;,&quot;focus_image&quot;:&quot;&quot;,&quot;credits&quot;:&quot;&quot;}]}}\"><section class=\"block split-three-column is-style-three-columns\"><\/section><\/div>\n<p class=\"wp-block-paragraph\">En este sentido, resulta una buena se\u00f1al que la Corte Suprema de Justicia de la Naci\u00f3n Argentina se declarara competente en la causa que busca frenar el desmonte en el territorio que es hogar del jaguar.<\/p>\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-fundacion-greenpeace-argentina wp-block-embed-fundacion-greenpeace-argentina\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"m1qLkspOtE\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/bosques\/greenpeace-sobre-el-fallo-de-la-corte-es-un-avance-importante-para-defender-a-los-ultimos-20-yaguaretes-del-gran-chaco\/\">Greenpeace sobre el fallo de la Corte: \u201cEs un avance importante para defender a los \u00faltimos 20 yaguaret\u00e9s del Gran Chaco\u201d<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Greenpeace sobre el fallo de la Corte: \u201cEs un avance importante para defender a los \u00faltimos 20 yaguaret\u00e9s del Gran Chaco\u201d&#8221; &#8212; Fundaci\u00f3n Greenpeace Argentina\" src=\"https:\/\/www.greenpeace.org\/argentina\/story\/problemas\/bosques\/greenpeace-sobre-el-fallo-de-la-corte-es-un-avance-importante-para-defender-a-los-ultimos-20-yaguaretes-del-gran-chaco\/embed\/#?secret=GzqUARZeLQ#?secret=m1qLkspOtE\" data-secret=\"m1qLkspOtE\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n\n<p class=\"wp-block-paragraph\">\ud83d\udc06Cada animal precisa aproximadamente 40 mil hect\u00e1reas de bosque continuo y en buen estado de conservaci\u00f3n. Por eso es tan importante detener la deforestaci\u00f3n. Estamos al l\u00edmite de perder a esta especie y toda acci\u00f3n que se haga para evitar su desaparici\u00f3n es importante, pero todos sabemos que sin monte no ser\u00e1&nbsp; posible.&nbsp;<\/p>\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-argentina-stateless\/2022\/05\/b5d93d36-gpa-yaguarete-1-1024x683.jpg\" alt=\"\" class=\"wp-image-15891\"\/><figcaption class=\"wp-element-caption\">Greenpeace recorri\u00f3 la provincia de Formosa y document\u00f3 desmontes en cinco fincas. La organizaci\u00f3n ecologista asimismo denunci\u00f3 que, desde la sanci\u00f3n de la Ley de Bosques a fines de 2007, en lugar de disminuir, la deforestaci\u00f3n all\u00ed se cuadruplic\u00f3, lo que afecta seriamente la supervivencia de los menos de 20 ejemplares de jaguares que quedan en la regi\u00f3n del Gran Chaco Argentino.<\/figcaption><\/figure>\n\n<p class=\"wp-block-paragraph\">Debemos exigir que se hagan todos los esfuerzos posibles para que los jaguares pueden sobrevivir \ud83d\udcaa\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Si quer\u00e9s conocer a\u00fan m\u00e1s, te dejamos m\u00e1s info ac\u00e1 \u2b07<\/p>\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-fundacion-greenpeace-argentina wp-block-embed-fundacion-greenpeace-argentina\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"RDGQxNfpYy\"><a href=\"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/bosques\/yaguarete-lo-que-seguro-no-sabias-del-felino-mas-grande-de-america\/\">Yaguaret\u00e9, lo que seguro no sab\u00edas del felino m\u00e1s grande de Am\u00e9rica<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;Yaguaret\u00e9, lo que seguro no sab\u00edas del felino m\u00e1s grande de Am\u00e9rica&#8221; &#8212; Fundaci\u00f3n Greenpeace Argentina\" src=\"https:\/\/www.greenpeace.org\/argentina\/blog\/problemas\/bosques\/yaguarete-lo-que-seguro-no-sabias-del-felino-mas-grande-de-america\/embed\/#?secret=EOvqPyng4u#?secret=RDGQxNfpYy\" data-secret=\"RDGQxNfpYy\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un repaso por para conocer (y valorar) al Jaguar en su d\u00eda.<\/p>\n","protected":false},"author":53,"featured_media":10891,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"D\u00eda Internacional del Jaguaret\u00e9: fotogaler\u00eda y datos curiosos para apreciar y valorar al felino m\u00e1s imponente","p4_og_description":"Un repaso por para conocer (y valorar) al Jaguar en su d\u00eda.","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[2],"tags":[33],"p4-page-type":[14],"class_list":["post-10887","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bosques","tag-bosques","p4-page-type-blog"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/posts\/10887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/comments?post=10887"}],"version-history":[{"count":16,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/posts\/10887\/revisions"}],"predecessor-version":[{"id":18061,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/posts\/10887\/revisions\/18061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/media\/10891"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/media?parent=10887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/categories?post=10887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/tags?post=10887"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/colombia\/wp-json\/wp\/v2\/p4-page-type?post=10887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}