{"id":20971,"date":"2024-02-28T13:08:18","date_gmt":"2024-02-28T12:08:18","guid":{"rendered":"https:\/\/www.greenpeace.org\/italy\/?page_id=20971"},"modified":"2026-04-02T10:53:58","modified_gmt":"2026-04-02T08:53:58","slug":"nucleare","status":"publish","type":"page","link":"https:\/\/www.greenpeace.org\/italy\/cosa-facciamo\/nucleare\/","title":{"rendered":"Nucleare"},"content":{"rendered":"\n\n<div class=\"wp-block-group block is-layout-flow wp-block-group-is-layout-flow\">\n\n<div class=\"wp-block-group alignfull has-beige-100-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:0px;padding-bottom:0px\">\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-media-text alignfull has-media-on-the-right is-stacked-on-mobile is-pattern-p4-page-header is-style-parallax\"><div class=\"wp-block-media-text__content\">\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading\" style=\"font-size:3.6rem\">Nucleare<\/h1>\n\n\n\n<p style=\"font-size:1.25rem\">L\u2019energia nucleare ha costi insostenibili, \u00e8 pericolosa e genera enormi quantit\u00e0 di scorie radioattive che non possiamo smaltire. Solo le fonti rinnovabili possono fermare il cambiamento climatico, fornire energia pulita e porre fine all\u2019incubo nucleare.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/ede04b85-gp0253m_medium_res-1024x683.jpeg\" alt=\"\" sizes=\"auto, (min-width: 601px) 50vw, 100vw\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/ede04b85-gp0253m_medium_res.jpeg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/ede04b85-gp0253m_medium_res-300x200.jpeg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/ede04b85-gp0253m_medium_res-1024x683.jpeg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/ede04b85-gp0253m_medium_res-768x512.jpeg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/ede04b85-gp0253m_medium_res-510x340.jpeg 510w\" class=\"wp-image-20973 size-full\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns block is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized mb-0 force-no-lightbox force-no-caption is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/aa875de2-icon-nucleare1.png\" alt=\"\" class=\"wp-image-20983\" style=\"width:75px\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/aa875de2-icon-nucleare1.png 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/aa875de2-icon-nucleare1-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left fontGPsans\" style=\"font-size:2.5rem\"><strong><strong><strong>9,2%<\/strong><\/strong><\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La produzione di elettricit\u00e0 globale fornita dal nucleare, costantemente in declino.<br>Le rinnovabili hanno invece raggiunto quasi il 30%, oltre il triplo del nucleare.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized mb-0 force-no-lightbox force-no-caption is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7d82e744-icon-nucleare2.png\" alt=\"\" class=\"wp-image-20984\" style=\"width:75px\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7d82e744-icon-nucleare2.png 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7d82e744-icon-nucleare2-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left fontGPsans\" style=\"font-size:2.5rem\"><strong><strong>9<\/strong><\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Gli Stati in possesso di armi nucleari<br>(Stati Uniti, Russia, Gran Bretagna, Francia, Cina, India, Pakistan, Corea del Nord e Israele).<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized mb-0 force-no-lightbox force-no-caption is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/771c812b-icon-nucleare3.png\" alt=\"\" class=\"wp-image-20985\" style=\"width:75px\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/771c812b-icon-nucleare3.png 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/771c812b-icon-nucleare3-150x150.png 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-left fontGPsans\" style=\"font-size:2.5rem\"><strong><strong><strong>112$-189$ (MWh)<\/strong><\/strong><\/strong><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Il costo dell\u2019energia nucleare rispetto ai 36$-44$(MWh) dell\u2019energia solare e i 29$-56$ (MWh) dell\u2019energia a terra, secondo il World Nuclear Industry Status Report.<\/p>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-green-500-color has-text-color\" style=\"font-size:3rem\">SENZA IL NUCLEARE PER UN MONDO VERDE E DI PACE<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\"><\/div>\n<\/div>\n\n\n\n<p><strong>Da sempre ci battiamo contro il nucleare:<\/strong> fu proprio una spedizione organizzata nel 1971 per impedire i danni ambientali di un test nucleare sull\u2019isola di Amchitka, al largo dell\u2019Alaska, a dare vita a Greenpeace.<\/p>\n\n\n\n<p><strong>Siamo contro il nucleare perch\u00e9 \u00e8 un\u2019energia pericolosa come hanno dimostrato, tra gli altri, l\u2019incidente di Chernobyl e quello di Fukushima<\/strong> le cui conseguenze sono ben note: enormi quantit\u00e0 di radiazioni rilasciate, centinaia di migliaia di persone costrette all\u2019evacuazione, fiumi e foreste contaminati, estese aree diventate inabitabili, danni economici incalcolabili. <strong>Incidenti del genere hanno chiarito in modo evidente che<\/strong> <strong>questa tecnologia non pu\u00f2 essere controllata in caso di catastrofe<\/strong>.&nbsp;<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-not-stacked-on-mobile is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"800\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f2fcf296-gp0stvm58_medium_res-edited.jpeg\" alt=\"\" class=\"wp-image-20979\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f2fcf296-gp0stvm58_medium_res-edited.jpeg 500w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f2fcf296-gp0stvm58_medium_res-edited-188x300.jpeg 188w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f2fcf296-gp0stvm58_medium_res-edited-213x340.jpeg 213w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"501\" height=\"802\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/e206c1be-gp0stso6d_medium_res-edited.jpeg\" alt=\"\" class=\"wp-image-20980\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/e206c1be-gp0stso6d_medium_res-edited.jpeg 501w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/e206c1be-gp0stso6d_medium_res-edited-187x300.jpeg 187w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/e206c1be-gp0stso6d_medium_res-edited-212x340.jpeg 212w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"800\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/3f18c220-gp1sx16i_medium_res-edited.jpeg\" alt=\"\" class=\"wp-image-20981\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/3f18c220-gp1sx16i_medium_res-edited.jpeg 500w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/3f18c220-gp1sx16i_medium_res-edited-188x300.jpeg 188w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/3f18c220-gp1sx16i_medium_res-edited-213x340.jpeg 213w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Ma oltre ai rischi legati alle centrali nucleari, un\u2019altra minaccia incombe sulla sicurezza delle persone e del pianeta: le armi atomiche<\/strong>. Qualsiasi Paese abbia accesso al nucleare civile ha la capacit\u00e0 di sviluppare il nucleare militare, ed entrambi sono da sempre interconnessi: basti pensare che i primi reattori nucleari della storia sono stati costruiti proprio per costruire bombe atomiche e per la propulsione delle navi militari. <strong>Ancora oggi nucleare civile e militare condividono conoscenze, personale specializzato e fabbriche di componenti<\/strong>: si pu\u00f2 dire che uno non esisterebbe senza l\u2019altro ed \u00e8 per questo che vogliamo che entrambi scompaiano.<\/p>\n\n\n\n<p>Energia nucleare e ordigni atomici rappresentano una minaccia per l\u2019incolumit\u00e0 dell\u2019umanit\u00e0 e del pianeta: <strong>l\u2019unica soluzione \u00e8 fermare l\u2019espansione del nucleare, chiudere le centrali esistenti e rivolgere i nostri sforzi verso energie rinnovabili, sicure e pulite<\/strong>.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-green-500-color has-text-color\" style=\"font-size:3rem\">PERCH\u00c9 DICIAMO NO AL NUCLEARE<\/h2>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group block is-layout-flow wp-block-group-is-layout-flow\">\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/0ac88806-gp0stxugq_medium_res-1024x683.jpeg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/0ac88806-gp0stxugq_medium_res.jpeg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/0ac88806-gp0stxugq_medium_res-300x200.jpeg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/0ac88806-gp0stxugq_medium_res-1024x683.jpeg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/0ac88806-gp0stxugq_medium_res-768x512.jpeg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/0ac88806-gp0stxugq_medium_res-510x340.jpeg 510w\" class=\"wp-image-20977 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading has-dark-green-800-color has-text-color\">Il nucleare non \u00e8 sicuro n\u00e9 sostenibile<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>L\u2019energia nucleare non \u00e8 una fonte di energia rinnovabile e produce inoltre enormi quantit\u00e0 di scorie radioattive che rimarranno pericolose per diverse migliaia di anni<\/strong>: una condanna per l\u2019ambiente e per le generazioni future, perch\u00e9 non esiste una soluzione sicura per smaltirle. <strong>Per questo, quando l\u2019Unione Europea ha incluso energia nucleare nell\u2019elenco degli investimenti considerati sostenibili, otto uffici europei di Greenpeace hanno deciso di fare causa<\/strong>: l&#8217;energia nucleare non deve beneficiare di finanziamenti verdi n\u00e9 essere spacciata per sostenibile!<\/p>\n<\/div><\/div>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div class=\"wp-block-media-text alignwide has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\"><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading has-dark-green-800-color has-text-color\">Il nucleare \u00e8 una falsa soluzione per la crisi climatica<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>La crisi climatica parla chiaro: entro il 2050 dobbiamo ridurre del 100% l\u2019uso dei combustibili fossili <\/strong>e non c\u2019\u00e8 tempo affinch\u00e9 il nucleare possa contribuire alla decarbonizzazione.<\/p>\n\n\n\n<p>Perfino due organizzazioni che promuovono il nucleare come la World Nuclear Association e l\u2019Agenzia per l\u2019energia nucleare dell\u2019OCSE ammettono che se la capacit\u00e0 di energia nucleare raddoppiasse entro il 2050, le emissioni di gas serra si ridurrebbero di appena il 4%. <strong>Per ottenere questo misero risultato dovremmo costruire ben 37 nuovi reattori ogni anno, a partire da ora e fino al 2050<\/strong>,<strong> <\/strong>quando in realt\u00e0 il numero di reattori nel mondo \u00e8 da tempo in declino. <strong>E comunque per ottenere cosa? Per ridurre le emissioni del 4% quando a noi occorre il 100%<\/strong>.<\/p>\n\n\n\n<p>I nuovi reattori in Francia e USA hanno avuto tempi di costruzione ben superiori a 10 anni e costi da 3 a 4 volte quelli previsti. <strong>Perch\u00e9 continuare a investire sul nucleare quando esistono fonti energetiche rinnovabili, pulite e meno costose come il solare e l\u2019eolico, <\/strong>che secondo diversi studi e rapporti scientifici possono fornirci il 100% di energia rinnovabile entro il 2050?<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/943f3073-gp02d4s_medium_res-1024x683.jpeg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/943f3073-gp02d4s_medium_res.jpeg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/943f3073-gp02d4s_medium_res-300x200.jpeg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/943f3073-gp02d4s_medium_res-1024x683.jpeg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/943f3073-gp02d4s_medium_res-768x512.jpeg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/943f3073-gp02d4s_medium_res-510x340.jpeg 510w\" class=\"wp-image-20978 size-full\"\/><\/figure><\/div>\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile is-vertically-aligned-top\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a2dbd44-gp02ffc_medium_res-1024x683.jpeg\" alt=\"\" sizes=\"auto, (min-width: 1600px) calc((1320px - 24px) \/ 2),(min-width: 1200px) calc((1140px - 24px) \/ 2),(min-width: 992px) calc((960px - 24px) \/ 2),(min-width: 768px) calc((720px - 24px) \/ 2),(min-width: 601px) calc((540px - 24px) \/ 2),(min-width: 577px) calc((540px - 24px) \/ 1), calc(100vw - 24px)\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a2dbd44-gp02ffc_medium_res.jpeg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a2dbd44-gp02ffc_medium_res-300x200.jpeg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a2dbd44-gp02ffc_medium_res-1024x683.jpeg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a2dbd44-gp02ffc_medium_res-768x512.jpeg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a2dbd44-gp02ffc_medium_res-510x340.jpeg 510w\" class=\"wp-image-21039 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\">\n<h3 class=\"wp-block-heading has-dark-green-800-color has-text-color\">Tornare al nucleare in Italia? Un pessimo affare<\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Mentre a fasi alterne i governi del nostro Paese mostrano possibili aperture al nucleare, vale la pena ricordare che le cittadine e i cittadini italiani si sono gi\u00e0 dimostrati contrari con ben due referendum, nel 1987 e nel 2011. <strong>L\u2019Italia inoltre sta tuttora facendo i conti con la gestione delle nostre scorie radioattive<\/strong> e non ha ancora trovato una soluzione a 37 anni di distanza dal referendum che decret\u00f2 l\u2019uscita dal nucleare.<\/p>\n\n\n\n<p><strong>A dissuaderci dal ritorno al nucleare dovrebbe bastare il fatto che si \u00e8 rivelato un un fallimento economico sia in Francia sia negli Stati Uniti<\/strong>. I costi dell&#8217;impianto francese di Flamanville sono lievitati a 19,1 miliardi di euro (invece dei 3,3 miliardi stimati), mentre due dei quattro reattori in costruzione negli USA sono stati cancellati e gli altri due proseguono a costi esorbitanti: da circa 9 miliardi di dollari si \u00e8 gi\u00e0 passati a una stima di circa 32 miliardi. Non \u00e8 andata meglio ai due reattori di Hinkley Point, in Gran Bretagna, che dovevano costare 18 miliardi di sterline e oggi sono stimati a 46 miliardi.<\/p>\n<\/div><\/div>\n\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n<div class=\"wp-block-group alignfull block has-dark-green-800-background-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"padding-top:80px;padding-bottom:80px\">\n<figure class=\"wp-block-image aligncenter size-full is-resized caption-alignment-center is-style-rounded-90\"><img loading=\"lazy\" decoding=\"async\" width=\"142\" height=\"142\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/01\/2109f126-icon-ctapetizione.png\" alt=\"\" class=\"wp-image-20513\"\/><\/figure>\n\n\n\n<div class=\"wp-block-group container is-layout-flow wp-block-group-is-layout-flow\">\n<h3 class=\"wp-block-heading has-text-align-center has-white-color has-text-color\" style=\"margin-bottom:24px\">Contro i cambiamenti climatici,<br>l\u2019unica soluzione non \u00e8 il nucleare ma eliminare le fonti fossili.<\/h3>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/attivati.greenpeace.it\/petizioni\/stop-cambiamenti-climatici\/?utm_source=greenpeace.org&amp;utm_medium=cosa-facciamo&amp;utm_campaign=clima\" target=\"_blank\" rel=\"noreferrer noopener\">FIRMA LA PETIZIONE<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-green-500-color has-text-color\" style=\"font-size:3rem\">ULTIME NOTIZIE<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-query posts-list p4-query-loop is-custom-layout-list is-layout-flow wp-block-query-is-layout-flow\">\n<div class=\"wp-block-group is-content-justification-space-between is-layout-flex wp-container-core-group-is-layout-3d213aab wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\"><\/h2>\n<\/div>\n\n\n\n<p style=\"margin-top:24px;margin-bottom:36px\"><\/p>\n\n\n\n\n<ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-21148 post type-post status-publish format-standard has-post-thumbnail hentry category-proteggi tag-azioni tag-nucleare p4-page-type-storia\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/storia\/21148\/david-mctaggart-e-la-costruzione-di-una-organizzazione\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1200\" height=\"791\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f3343d64-david-mctaggart-vega.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"David McTaggart e la costruzione di una organizzazione\u00a0\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f3343d64-david-mctaggart-vega.jpg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f3343d64-david-mctaggart-vega-300x198.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f3343d64-david-mctaggart-vega-1024x675.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f3343d64-david-mctaggart-vega-768x506.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/f3343d64-david-mctaggart-vega-510x336.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2024\/02\/f3343d64-david-mctaggart-vega.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/proteggi\/\">Proteggi<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/azioni\/\" rel=\"tag\">Azioni<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/storia\/21148\/david-mctaggart-e-la-costruzione-di-una-organizzazione\/\" target=\"_self\" >David McTaggart e la costruzione di una organizzazione\u00a0<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Pragmatico, motivato e molto determinato, fu David McTaggart a trasformare Greenpeace in un&#8217;organizzazione internazionale. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/andrea-pinchera\/'>Andrea Pinchera<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2024-02-05T16:13:01+01:00\">5 Febbraio 2024<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-21167 post type-post status-publish format-standard has-post-thumbnail hentry category-proteggi tag-azioni tag-nucleare tag-pace p4-page-type-storia\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/storia\/21167\/un-viaggio-per-la-vita-la-pace-e-l-indipendenza\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1200\" height=\"804\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Un viaggio per la vita, la pace&#8230; e l\u2019indipendenza\u00a0\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack.jpg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack-300x201.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack-1024x686.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack-768x515.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack-507x340.jpg 507w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2024\/02\/7416d784-equipaggio-greenpeace-phyllis-cormack.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/proteggi\/\">Proteggi<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/azioni\/\" rel=\"tag\">Azioni<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/pace\/\" rel=\"tag\">Pace<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/storia\/21167\/un-viaggio-per-la-vita-la-pace-e-l-indipendenza\/\" target=\"_self\" >Un viaggio per la vita, la pace&#8230; e l\u2019indipendenza\u00a0<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Come un viaggio intrapreso per fermare dei test nucleari ad Amchitka si trasform\u00f2 in molto di pi\u00f9. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/andrea-pinchera\/'>Andrea Pinchera<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2024-02-05T16:12:41+01:00\">5 Febbraio 2024<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-21140 post type-post status-publish format-standard has-post-thumbnail hentry category-proteggi tag-nucleare tag-clima tag-energia p4-page-type-storia\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/storia\/21140\/1986-greenpeace-sbarca-in-italia\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1200\" height=\"800\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/62781ce1-sirius-blocca-porto-marghera.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"1986: Greenpeace sbarca in Italia\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/62781ce1-sirius-blocca-porto-marghera.jpg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/62781ce1-sirius-blocca-porto-marghera-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/62781ce1-sirius-blocca-porto-marghera-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/62781ce1-sirius-blocca-porto-marghera-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/62781ce1-sirius-blocca-porto-marghera-510x340.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2024\/02\/62781ce1-sirius-blocca-porto-marghera.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flex wp-block-group-is-layout-flex\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/proteggi\/\">Proteggi<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/clima\/\" rel=\"tag\">Clima<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/storia\/21140\/1986-greenpeace-sbarca-in-italia\/\" target=\"_self\" >1986: Greenpeace sbarca in Italia<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">David McTaggart decide di aprire a Roma la sede italiana di Greenpeace: \u00e8 l&#8217;inizio di tutto. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/andrea-pinchera\/'>Andrea Pinchera<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2024-02-05T16:12:20+01:00\">5 Febbraio 2024<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><\/ul>\n\n\n<div class=\"wp-block-buttons carousel-controls is-horizontal is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-buttons-is-layout-044bd602 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button carousel-control-prev\"><button type=\"button\" class=\"wp-block-button__link wp-element-button\">Prev<\/button><\/div>\n\n\n\n<div class=\"wp-block-button carousel-control-next\"><button type=\"button\" class=\"wp-block-button__link wp-element-button\">Next<\/button><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-dark-green-800-background-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/www.greenpeace.org\/italy\/storia\/?tag=nucleare\">LEGGI LE ALTRE NEWS<\/a><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-green-500-color has-text-color\" style=\"font-size:3rem\">LEGGI I REPORT<\/h2>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-bottom is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:40%\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-query posts-list p4-query-loop is-custom-layout-carousel is-layout-flex wp-block-query-is-layout-flex\">\n<div class=\"wp-block-group is-content-justification-space-between is-layout-flex wp-container-core-group-is-layout-3d213aab wp-block-group-is-layout-flex\">\n<h2 class=\"wp-block-heading\"><\/h2>\n<\/div>\n\n\n\n<p style=\"margin-top:24px;margin-bottom:36px\"><\/p>\n\n\n\n\n<ul class=\"wp-block-post-template is-layout-flow wp-block-post-template-is-layout-flow\"><li class=\"wp-block-post post-16739 post type-post status-publish format-standard has-post-thumbnail hentry category-scegli tag-energia tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/16739\/gpnews147-intervista-al-professore-giovanni-battista-zorzoli\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1200\" height=\"800\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/980dcf78-gp0253t.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"GPNews147 &#8211; Intervista al Professore Giovanni Battista Zorzoli\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/980dcf78-gp0253t.jpg 1200w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/980dcf78-gp0253t-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/980dcf78-gp0253t-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/980dcf78-gp0253t-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/980dcf78-gp0253t-510x340.jpg 510w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2018\/11\/980dcf78-gp0253t.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/scegli\/\">Scegli<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/16739\/gpnews147-intervista-al-professore-giovanni-battista-zorzoli\/\" target=\"_self\" >GPNews147 &#8211; Intervista al Professore Giovanni Battista Zorzoli<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Si torna a parlare di nucleare, ma non \u00e8 una cosa seria. Per cercare di capirne qualcosa abbiamo interpellato il professore Giovanni Battista Zorzoli. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2022-11-24T18:51:41+01:00\">24 Novembre 2022<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-12745 post type-post status-publish format-standard has-post-thumbnail hentry category-scegli tag-volontariato tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/12745\/il-prezzo-dellatomica-sotto-casa\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"882\" height=\"1114\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Il prezzo dell&#8217;atomica sotto casa\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa.png 882w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa-238x300.png 238w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa-811x1024.png 811w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa-768x970.png 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa-269x340.png 269w\" sizes=\"auto, (max-width: 882px) 100vw, 882px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2024\/02\/52ede63e-il-prezzo-dell-atomica-sotto-casa.png\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/scegli\/\">Scegli<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/volontariato\/\" rel=\"tag\">Volontariato<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/12745\/il-prezzo-dellatomica-sotto-casa\/\" target=\"_self\" >Il prezzo dell&#8217;atomica sotto casa<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">La nuova inchiesta dell&#8217;Unit\u00e0 Investigativa di Greenpeace sui rischi e i costi del nuclear sharing in Italia <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2020-12-01T13:30:00+01:00\">1 Dicembre 2020<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-12734 post type-post status-publish format-standard has-post-thumbnail hentry category-uncategorized tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/12734\/italiani-e-il-nucleare-sondaggio-ipsos-greenpeace\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"838\" height=\"1038\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a5ec702-italiani-e-il-nucleare.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"&#8220;Italiani e il nucleare&#8221;: sondaggio Ipsos-Greenpeace\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a5ec702-italiani-e-il-nucleare.png 838w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a5ec702-italiani-e-il-nucleare-242x300.png 242w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a5ec702-italiani-e-il-nucleare-827x1024.png 827w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a5ec702-italiani-e-il-nucleare-768x951.png 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/5a5ec702-italiani-e-il-nucleare-274x340.png 274w\" sizes=\"auto, (max-width: 838px) 100vw, 838px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2024\/02\/5a5ec702-italiani-e-il-nucleare.png\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/uncategorized\/\">Uncategorized<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/12734\/italiani-e-il-nucleare-sondaggio-ipsos-greenpeace\/\" target=\"_self\" >&#8220;Italiani e il nucleare&#8221;: sondaggio Ipsos-Greenpeace<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Il verdetto degli italiani sulle armi atomiche \u00e8 inequivocabile. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2020-12-01T13:00:00+01:00\">1 Dicembre 2020<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-773 post type-post status-publish format-standard has-post-thumbnail hentry category-denuncia category-proteggi tag-energia tag-salute tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/773\/disastro-di-fukushima-i-diritti-violati-di-donne-e-bambini\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1052\" height=\"1488\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Disastro di Fukushima, i diritti violati di donne e bambini\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact.jpg 1052w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact-212x300.jpg 212w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact-768x1086.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact-724x1024.jpg 724w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact-966x1366.jpg 966w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2017\/03\/c309f75c-unequal-impact-240x340.jpg 240w\" sizes=\"auto, (max-width: 1052px) 100vw, 1052px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2017\/03\/c309f75c-unequal-impact.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/denuncia\/\">Denuncia<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/salute\/\" rel=\"tag\">Salute<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/773\/disastro-di-fukushima-i-diritti-violati-di-donne-e-bambini\/\" target=\"_self\" >Disastro di Fukushima, i diritti violati di donne e bambini<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">La politica del Giappone di riportare gli sfollati del disastro di Fukushima in aree ancora pesantemente contaminate va contro le leggi dello Stato nipponico e viola numerosi trattati internazionali sui diritti umani. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2017-03-07T00:00:00+01:00\">7 Marzo 2017<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-1012 post type-post status-publish format-standard has-post-thumbnail hentry category-denuncia tag-energia tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/1012\/radiation-reloaded\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1045\" height=\"1490\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Radiation reloaded\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report.jpg 1045w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report-210x300.jpg 210w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report-768x1095.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report-718x1024.jpg 718w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report-958x1366.jpg 958w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report-238x340.jpg 238w\" sizes=\"auto, (max-width: 1045px) 100vw, 1045px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2016\/03\/1cade004-gpj_fukushima_radiation_reloaded_report.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/denuncia\/\">Denuncia<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/1012\/radiation-reloaded\/\" target=\"_self\" >Radiation reloaded<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Gli impatti ambientali del disastro nucleare di Fukushima Daiichi avranno effetti per secoli su foreste, fiumi ed estuari. \u00c8 quanto emerge da \u201cRadiation reloaded\u201d, un nuovo rapporto diffuso oggi da Greenpeace Giappone, secondo cui gli elementi radioattivi a lunga vita sono stati assorbiti da piante e animali, riconcentrati tramite le catene alimentari, e trascinati a&hellip; <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2016-03-04T00:00:00+01:00\">4 Marzo 2016<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-966 post type-post status-publish format-standard has-post-thumbnail hentry category-denuncia tag-energia tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/966\/fukushima-4-anni-fa-il-disastro-nucleare\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1052\" height=\"1490\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Fukushima, 4 anni fa il disastro nucleare\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear.jpg 1052w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear-212x300.jpg 212w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear-768x1088.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear-723x1024.jpg 723w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear-964x1366.jpg 964w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2015\/03\/2988af5c-japan-nuclear-240x340.jpg 240w\" sizes=\"auto, (max-width: 1052px) 100vw, 1052px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2015\/03\/2988af5c-japan-nuclear.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/denuncia\/\">Denuncia<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/966\/fukushima-4-anni-fa-il-disastro-nucleare\/\" target=\"_self\" >Fukushima, 4 anni fa il disastro nucleare<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">A quattro anni dal disastro nucleare di Fukushima, che si verific\u00f2 l\u201911 marzo 2011 con la fusione dei noccioli di tre reattori della centrale, Greenpeace pubblica due rapporti che mostrano come la contaminazione continui ancora oggi. Montagne coperte di foreste e fiumi rilasciano continuamente radioattivit\u00e0, che raggiunge zone gi\u00e0 decontaminate in precedenza, ricontaminandole. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2015-03-09T00:00:00+01:00\">9 Marzo 2015<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-1268 post type-post status-publish format-standard has-post-thumbnail hentry category-proteggi category-scegli tag-energia tag-clima tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/1268\/g7-energia-vogliamo-lindipendenza-energetica-dai-combustibili-fossili-non-dalla-russia\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1190\" height=\"1684\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"G7 Energia.\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001.jpg 1190w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001-212x300.jpg 212w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001-768x1087.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001-724x1024.jpg 724w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001-965x1366.jpg 965w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001-240x340.jpg 240w\" sizes=\"auto, (max-width: 1190px) 100vw, 1190px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2014\/05\/173989dc-4ff68e49-4ff68e49-briefing-g7-001.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/proteggi\/\">Proteggi<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/clima\/\" rel=\"tag\">Clima<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/1268\/g7-energia-vogliamo-lindipendenza-energetica-dai-combustibili-fossili-non-dalla-russia\/\" target=\"_self\" >G7 Energia.<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Vogliamo l&#8217;indipendenza energetica dai combustibili fossili, non dalla Russia <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2014-05-06T00:00:00+02:00\">6 Maggio 2014<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-1218 post type-post status-publish format-standard has-post-thumbnail hentry category-proteggi category-scegli tag-energia tag-clima tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/1218\/energy-revolution-2012\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"978\" height=\"1344\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Energy [R]evolution 2012\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51.png 978w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51-218x300.png 218w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51-768x1055.png 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51-745x1024.png 745w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51-247x340.png 247w\" sizes=\"auto, (max-width: 978px) 100vw, 978px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2012\/10\/49c8e90e-schermata-2018-11-21-alle-11.56.51.png\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/proteggi\/\">Proteggi<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/clima\/\" rel=\"tag\">Clima<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/1218\/energy-revolution-2012\/\" target=\"_self\" >Energy [R]evolution 2012<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Non solo nuovi posti di lavoro, la rivoluzione energetica garantirebbe risparmi a lungo termine per i consumatori e un freno ai cambiamenti climatici. <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2012-10-24T00:00:00+02:00\">24 Ottobre 2012<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><li class=\"wp-block-post post-3534 post type-post status-publish format-standard has-post-thumbnail hentry category-denuncia category-proteggi category-scegli tag-clima tag-inquinamento tag-energia tag-nucleare p4-page-type-rapporto\">\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\"><figure class=\"wp-block-post-featured-image\"><a href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/3534\/fukushima-come-cernobyl\/\" target=\"_self\"  ><img loading=\"lazy\" decoding=\"async\" data-ga-category=\"Posts List\" data-ga-action=\"Image\" data-ga-label=\"n\/a\" width=\"1190\" height=\"1684\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image wp-stateless-item\" alt=\"Fukushima come Cernobyl\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001.jpg 1190w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001-212x300.jpg 212w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001-768x1087.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001-724x1024.jpg 724w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001-965x1366.jpg 965w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001-240x340.jpg 240w\" sizes=\"auto, (max-width: 1190px) 100vw, 1190px\" data-image-size=\"post-thumbnail\" data-stateless-media-bucket=\"planet4-italy-stateless\" data-stateless-media-name=\"2018\/11\/8ae79606-greenpeace_hirsch_ines_report_25032011-001.jpg\" \/><\/a><\/figure>\n\n\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\"><div class=\"wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Post Type Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/category\/issues\/denuncia\/\">Denuncia<\/a><\/div>\n\n<div class=\"taxonomy-post_tag wp-block-post-terms\"><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/clima\/\" rel=\"tag\">Clima<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/inquinamento\/\" rel=\"tag\">Inquinamento<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/energia\/\" rel=\"tag\">Energia<\/a><span class=\"wp-block-post-terms__separator\"> <\/span><a data-ga-category=\"Posts List\" data-ga-action=\"Navigation Tag\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/tag\/nucleare\/\" rel=\"tag\">Nucleare<\/a><\/div><\/div>\n\n\n<h3 class=\"wp-block-post-title\"><a data-ga-category=\"Posts List\" data-ga-action=\"Title\" data-ga-label=\"n\/a\" href=\"https:\/\/www.greenpeace.org\/italy\/rapporto\/3534\/fukushima-come-cernobyl\/\" target=\"_self\" >Fukushima come Cernobyl<\/a><\/h3>\n\n<div class=\"wp-block-post-excerpt\"><p class=\"wp-block-post-excerpt__excerpt\">Un nuovo studio commissionato da Greenpeace Germania al Dr. Helmut Hirsch, esperto di sicurezza nucleare, rivela che gi\u00e0 dal 23 marzo 2011 l&#8217;incidente alla centrale di Fukushima in Giappone aveva rilasciato abbastanza radioattivit\u00e0 da essere classificato di livello 7, secondo la International Nuclear Event Scale (INES). 7 \u00e8 il livello massimo di gravit\u00e0 per gli&hellip; <\/p><\/div>\n\n\n<div class=\"wp-block-group posts-list-meta is-layout-flow wp-block-group-is-layout-flow\"><span class='article-list-item-author'><a data-ga-category=\"Posts List\" data-ga-action=\"Author\" data-ga-label=\"n\/a\" href='https:\/\/www.greenpeace.org\/italy\/author\/gp_italy\/'>Greenpeace Italy<\/a><\/span>\n\n<div class=\"wp-block-post-date\"><time datetime=\"2011-03-26T12:05:07+01:00\">26 Marzo 2011<\/time><\/div><\/div>\n<\/div>\n<\/div>\n\n<\/li><\/ul>\n\n\n<div class=\"wp-block-buttons carousel-controls is-horizontal is-content-justification-space-between is-nowrap is-layout-flex wp-container-core-buttons-is-layout-044bd602 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button carousel-control-prev\"><button type=\"button\" class=\"wp-block-button__link wp-element-button\">Prev<\/button><\/div>\n\n\n\n<div class=\"wp-block-button carousel-control-next\"><button type=\"button\" class=\"wp-block-button__link wp-element-button\">Next<\/button><\/div>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><strong>AREE CORRELATE<\/strong><\/h3>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n\n\n<div class=\"wp-block-columns block is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized mb-0 force-no-lightbox force-no-caption is-style-rounded-90\"><img loading=\"lazy\" decoding=\"async\" width=\"1199\" height=\"858\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/9253f139-gp0stq7oo.jpg\" title=\"Plastic Waste Blown Away from Waste Landfill La Crau in France. \u00a9 Wolf Wichmann \/ Greenpeace\" alt=\"Plastic Waste Blown Away from Waste Landfill La Crau in France. \u00a9 Wolf Wichmann \/ Greenpeace\" class=\"wp-image-22090\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/9253f139-gp0stq7oo.jpg 1199w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/9253f139-gp0stq7oo-300x215.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/9253f139-gp0stq7oo-1024x733.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/9253f139-gp0stq7oo-768x550.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2024\/02\/9253f139-gp0stq7oo-475x340.jpg 475w\" sizes=\"auto, (max-width: 1199px) 100vw, 1199px\" \/><figcaption class=\"wp-element-caption\">Plastic waste blown away from formerly open domestic waste landfill La Crau in Entressen France. The landfill was open until 2008. Plastic bags, film and foil entangled in bushes and washed up in canal.<div class=\"credit icon-left\"> \u00a9 Wolf Wichmann \/ Greenpeace<\/div><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Inquinamento<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Plastica, PFAS e sostanze chimiche tossiche stanno soffocando il pianeta e mettendo in pericolo la nostra salute.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/italy\/cosa-facciamo\/inquinamento\">SCOPRI DI PI\u00d9<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized mb-0 force-no-lightbox force-no-caption is-style-rounded-90\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2022\/05\/644ec11c-gp1suobg_medium_res-1024x683.jpg\" alt=\"\" class=\"wp-image-16080\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2022\/05\/644ec11c-gp1suobg_medium_res-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2022\/05\/644ec11c-gp1suobg_medium_res-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2022\/05\/644ec11c-gp1suobg_medium_res-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2022\/05\/644ec11c-gp1suobg_medium_res-510x340.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2022\/05\/644ec11c-gp1suobg_medium_res.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Portofino Marine Protected Area joins Greenpeace Italy &#8220;Progetto Mare Caldo&#8221; (Hot Sea Water Project&#8221;.\nThe underwater thermometers placed in the area since 2015 have registered an increase in water temperature. The Greenpeace dive team with researcher have checked the impact on the local biodiversity, and have found clear signs of the impact of climate change (similar to those observed in Elba Island).<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Mare<\/h2>\n\n\n\n<p class=\"has-text-align-center\">La vita sulla Terra dipende dal mare e dagli oceani. \u00c8 fondamentale proteggerli dalle attivit\u00e0 umane e dai cambiamenti climatici.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/italy\/cosa-facciamo\/mare\">SCOPRI DI PI\u00d9<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-group is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-large is-resized mb-0 force-no-lightbox force-no-caption is-style-rounded-90\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"695\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2023\/11\/7d62780f-gp0stui1y-1024x695.jpg\" title=\"Wind Park in Feldheim, Germany. \u00a9 Paul Langrock \/ Greenpeace\" alt=\"Wind Park in Feldheim, Germany. \u00a9 Paul Langrock \/ Greenpeace\" class=\"wp-image-19362\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2023\/11\/7d62780f-gp0stui1y-1024x695.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2023\/11\/7d62780f-gp0stui1y-300x204.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2023\/11\/7d62780f-gp0stui1y-768x522.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2023\/11\/7d62780f-gp0stui1y-501x340.jpg 501w, https:\/\/www.greenpeace.org\/static\/planet4-italy-stateless\/2023\/11\/7d62780f-gp0stui1y.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Enercon wind turbines E126 at wind park Feldheim.<div class=\"credit icon-left\"> \u00a9 Paul Langrock \/ Greenpeace<\/div><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Clima<\/h2>\n\n\n\n<p class=\"has-text-align-center\">Il cambiamento climatico \u00e8 la crisi pi\u00f9 urgente che l\u2019umanit\u00e0 deve affrontare. Se vogliamo un futuro, non c\u2019\u00e8 pi\u00f9 tempo da perdere.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button is-style-cta\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.greenpeace.org\/italy\/cosa-facciamo\/clima\">SCOPRI DI PI\u00d9<\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:16px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n\n\n<div style=\"height:64px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>In un futuro sicuro e sostenibile non c\u2019\u00e8 posto per il nucleare. I costi, i pericoli e le scorie radioattive sono rischi inaccettabili per il pianeta.<\/p>\n","protected":false},"author":21,"featured_media":20973,"parent":19392,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ep_exclude_from_search":false,"p4_hide_page_title_checkbox":"on","p4_title":"","p4_subtitle":"","p4_description":"","background_image_id":"","background_image":"","p4_button_title":"","p4_button_link":"","p4_button_link_checkbox":"","p4_og_title":"Il nucleare non \u00e8 un\u2019opzione","p4_og_description":"In un futuro sicuro e sostenibile non c\u2019\u00e8 posto per il nucleare. I costi, i pericoli e le scorie radioattive sono rischi inaccettabili per il pianeta.","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[],"tags":[],"class_list":["post-20971","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/pages\/20971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/comments?post=20971"}],"version-history":[{"count":20,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/pages\/20971\/revisions"}],"predecessor-version":[{"id":30470,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/pages\/20971\/revisions\/30470"}],"up":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/pages\/19392"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/media\/20973"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/media?parent=20971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/categories?post=20971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/italy\/wp-json\/wp\/v2\/tags?post=20971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}