{"id":11862,"date":"2021-07-08T13:51:04","date_gmt":"2021-07-08T11:51:04","guid":{"rendered":"https:\/\/www.greenpeace.org\/luxembourg\/?p=11862"},"modified":"2021-12-01T17:23:51","modified_gmt":"2021-12-01T15:23:51","slug":"fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/","title":{"rendered":"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Die k\u00fcnftige Investitionsstrategie des Pensionsfonds muss mit den Zielen des Pariser Klimaabkommens \u00fcbereinstimmen.<\/h2>\n\n<p><em>Luxemburg, 8. Juli 2021 &#8211;<\/em><strong> Trotz des Klimanotstandes sind die Investitionen des Luxemburger Pensionsfonds (Fonds de Compensation, FDC) weiterhin nicht im Einklang mit den Zielen des Pariser Klimaschutzabkommens. Zu diesem Schluss kommt Greenpeace Luxemburg infolge einer Analyse des Jahresberichts 2020 der FDC SICAV [1]. Gleichzeitig haben einige der nachhaltig gemanagten Teilfonds des Pensionsfonds laut dem in der letzten Woche ver\u00f6ffentlichten Jahresbericht 2020 des FDC deutlich besser abgeschnitten als ihre Benchmarks und damit bewiesen, dass Nachhaltigkeit und Rentabilit\u00e4t Hand in Hand gehen. [2] Greenpeace fordert den FDC auf, bei der anstehenden \u00dcberarbeitung seiner Investitionsstrategie eine ambiti\u00f6se Nachhaltigkeitsstrategie f\u00fcr alle Investitionen zu beschlie\u00dfen, einschlie\u00dflich des Ausstiegs aus klimasch\u00e4dlichen fossilen Brennstoffindustrien und anderen kohlenstoffintensiven Sektoren. <\/strong><\/p>\n\n<p>Eine von Greenpeace Luxemburg durchgef\u00fchrte Analyse des Jahresberichts 2020 der FDC SICAV kam zu dem Ergebnis, dass der Pensionsfonds in seinen Bem\u00fchungen f\u00fcr mehr Nachhaltigkeit keine koh\u00e4rente Strategie verfolgt. W\u00e4hrend die Investitionen des Fonds in die Unternehmen der <em>Carbon Majors<\/em> r\u00fcckl\u00e4ufig waren, stiegen die Investitionen in Kohleunternehmen von 257 Millionen \u20ac im Jahr 2019 auf 289 Millionen \u20ac im Jahr 2020, obwohl Kohle der klimasch\u00e4dlichste fossile Brennstoff ist. Die weltweite Kohlenutzung in der Stromerzeugung muss bis 2030 auslaufen, wenn wir die schlimmsten Auswirkungen des Klimawandels vermeiden wollen. [3] Dar\u00fcber hinaus investierten einige ESG-gelabelte FDC-Teilfonds im Jahr 2020 in \u00d6l-, Gas- und andere kohlenstoffintensive Unternehmen sowie in den Nuklearsektor. [4] <\/p>\n\n<p>&#8220;<em>Auch in diesem Sommer werden wir wieder Zeuge der weltweiten verheerenden Auswirkungen des Klimawandels, und dennoch haben die Entscheidungstr\u00e4ger des FDC bislang nicht die notwendigen Entscheidungen getroffen, um den klimasch\u00e4dlichen Investitionen ein Ende zu bereiten<\/em>&#8220;, sagt Myrna Koster, Kampaignerin f\u00fcr Klimagerechtigkeit bei Greenpeace Luxemburg. &#8220;<em>Laut einer k\u00fcrzlich von TNS Ilres im Auftrag von Greenpeace durchgef\u00fchrten Umfrage sind 47% der Bev\u00f6lkerung unseres Landes nicht damit einverstanden, dass der FDC in fossile Brennstoffe investiert. Der Ausstieg aus kohlenstoffintensiven Investitionen zugunsten von nachhaltigen Unternehmen w\u00fcrde es dem FDC erm\u00f6glichen, finanzielle Risiken zu vermeiden und die Renten der jetzigen und zuk\u00fcnftigen Pension\u00e4rinnen und Pension\u00e4ren zu sichern.<\/em>&#8220;<em> <\/em>[5]<\/p>\n\n<p>Auf dem Papier scheint Nachhaltigkeit ein wichtiges Anliegen des FDC geworden zu sein. Im vergangenen Jahr ver\u00f6ffentlichte der Fonds seinen ersten Sustainable Investor Report, in dem es hei\u00dft: &#8220;<em>Als institutioneller Verm\u00f6gensverwalter ist sich der FDC seiner \u00f6kologischen, sozialen und Good-Governance-Verantwortung bewusst.<\/em>&#8221; [6] Die Integration von ESG- und Nachhaltigkeitsaspekten in das Gesch\u00e4ftsmodell ist auch ein wiederkehrendes Thema im Jahresbericht 2020. Dar\u00fcber hinaus erkl\u00e4rte der FDC, dass er die Investitionsstrategie des Fonds im Laufe dieses Jahres \u00fcberarbeiten wird, &#8220;<em>um ESG- und Nachhaltigkeitskriterien noch st\u00e4rker in seine Anlagestrategie zu integrieren<\/em>.&#8221; [7]<\/p>\n\n<p>Gleichzeitig berufen sich aber sowohl der FDC als auch die politischen Entscheidungstr\u00e4ger weiterhin auf das Mandat des Fonds, &#8220;<em>die langfristige Lebensf\u00e4higkeit der allgemeinen Rentenversicherung zu sichern<\/em>&#8221; [8], um Investitionen in umweltsch\u00e4dliche Unternehmen zu rechtfertigen. Und das, obwohl der FDC-Jahresbericht 2020 deutlich zeigt, dass es keinen Konflikt zwischen dem Mandat des FDC und nachhaltigem Investieren gibt &#8211; im Gegenteil. Der Bericht hebt das Beispiel eines Teilfondsmanagers hervor, der ausschlie\u00dflich Verm\u00f6genswerte von Unternehmen mit nachhaltigen Gesch\u00e4ftsmodellen ausw\u00e4hlte und als Folge eine au\u00dfergew\u00f6hnliche Rendite von fast 24% erzielte, die den Benchmark um 17% \u00fcbertraf. In \u00e4hnlicher Weise \u00fcbertraf der f\u00fcr einen Teilfonds mit dem Investment-Ansatz \u2018Positive Impact\u2019 zust\u00e4ndige Manager die Performance des Benchmarks um \u00fcber 10%. [9]<\/p>\n\n<p>&#8220;<em>In ihrer<\/em> \u2018<em>Nation Branding<\/em>\u2019<em>-Strategie hat sich die Luxemburger Regierung Nachhaltigkeit auf ihre Fahnen geschrieben, doch der staatliche Pensionsfonds FDC wird diesem Anspruch immer noch nicht gerecht<\/em>&#8220;, sagt Martina Holbach, Kampaignerin f\u00fcr Klima &amp; Finanzen bei Greenpeace Luxemburg. &#8220;<em>Greenpeace fordert den FDC-Vorstand auf, die notwendigen Ma\u00dfnahmen zu ergreifen, um eine ambiti\u00f6se und koh\u00e4rente Nachhaltigkeitsstrategie f\u00fcr alle seine Investitionen zu verabschieden und diese mit den Klimazielen des Pariser Abkommens in Einklang zu bringen.<\/em>&#8221; <\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<p><strong>Anmerkungen: <\/strong><\/p>\n\n<p>[1] Fonds de Compensation de la S\u00e9curit\u00e9 Sociale, SICAV-FIS, \u2018Annual Report, including audited financial statements as of 31 December 2020\u2019, <a href=\"https:\/\/www.fdc.lu\/fileadmin\/file\/fdc\/SICAV_Audited_Annual_Report_20201231_signed.pdf#pageMode=bookmarks\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> einzusehen<\/p>\n\n<p>[2] Fonds de Compensation, \u2018Rapport annuel 2020\u2019, <a rel=\"noreferrer noopener\" href=\"https:\/\/www.fdc.lu\/fileadmin\/file\/fdc\/Rapport_annuel_2020_version_finale.pdf#pageMode=bookmarks\" target=\"_blank\">hier<\/a> einzusehen <\/p>\n\n<p>[3] Obwohl die Investitionen in &#8220;Carbon Major&#8221;-Unternehmen im Vergleich zum Vorjahr um 30% gesunken sind, zeigt ein Vergleich mit der Global Coal Exit List (GCEL), dass die FDC-Investitionen in gro\u00dfe Kohleunternehmen 2020 um 16% gestiegen sind.<\/p>\n\n<p>Zum Kohleausstieg: United Nations Climate Change Webseite, &#8220;<em>UN Chief Calls for Immediate Global Action to Phase Out Coal<\/em>&#8220;, 2. M\u00e4rz 2021, <a href=\"https:\/\/unfccc.int\/fr\/node\/268711\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> einzusehen<\/p>\n\n<p>[4] Im Jahr 2020 wurden die FDC-Investitionen in 25 Teilfonds aufgeteilt, die jeweils von verschiedenen Fondsmanagern verwaltet wurden. Nach Angaben des FDC haben 9 der Teilfonds ein ESG-Label der luxemburgischen Labelling-Vereinigung Luxflag erhalten. Unsere Analyse zeigt, dass alle ESG-gelabelten Teilfonds in gro\u00dfe \u00d6l-, Bergbau- oder Gasunternehmen sowie in Autohersteller, Stromversorger, Fluggesellschaften oder andere kohlenstoffintensive Branchen investiert haben. Zu den Fondsmanagern dieser Portfolios geh\u00f6ren Axa, Allianz Global Investors, HSBC, Amundi und Natixis.<\/p>\n\n<p>[5] TNS Ilres Umfrage im Auftrag von Greenpeace Luxemburg, \u201cPerception du changement climatique et des investissements du secteur financier\u201d, Mai 2021, <a href=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/5ecc1c39-tns-ilres_greenpeace2021_mai2021_page_23.png\" target=\"_blank\" rel=\"noreferrer noopener\">Folie 23<\/a><\/p>\n\n<p>[6] FDC Sustainable Investor Report, Seite 4, <a href=\"https:\/\/www.fdc.lu\/fileadmin\/file\/fdc\/Rapport_investisseur_responsable_2020_%28version_finale_web%29.pdf#pageMode=bookmarks\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> einzusehen <\/p>\n\n<p>[7] Fonds de Compensation, \u2018Rapport annuel 2020\u2019, Seite 7, <a href=\"https:\/\/www.fdc.lu\/fileadmin\/file\/fdc\/Rapport_annuel_2020_version_finale.pdf#pageMode=bookmarks\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> einzusehen<\/p>\n\n<p>[8] FDC Sustainable Investor Report, Seite 6, <a href=\"https:\/\/www.fdc.lu\/fileadmin\/file\/fdc\/Rapport_investisseur_responsable_2020_%28version_finale_web%29.pdf#pageMode=bookmarks\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> einzusehen<\/p>\n\n<p>[9] Fonds de Compensation, \u2018Rapport annuel 2020\u2019, Seite 23, <a href=\"https:\/\/www.fdc.lu\/fileadmin\/file\/fdc\/Rapport_annuel_2020_version_finale.pdf#pageMode=bookmarks\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> einzusehen<\/p>\n\t\t\t<section\n\t\t\tclass=\"boxout post-5673 \"\n\t\t\t\n\t\t>\n\t\t\t<a\n\t\t\t\tdata-ga-category=\"Take Action Boxout\"\n\t\t\t\tdata-ga-action=\"Image\"\n\t\t\t\tdata-ga-label=\"n\/a\"\n\t\t\t\tclass=\"cover-card-overlay\"\n\t\t\t\thref=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/wir-weigern-uns-die-klimakrise-zu-finanzieren\/\" \n\t\t\t><\/a>\n\t\t\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-1024x683.jpg\"\n\t\t\t\t\t\tsrcset=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-510x340.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp.jpg 1200w\"\n\t\t\t\t\t\tsizes=\"(min-width: 1000px) 358px, (min-width: 780px) 313px, 88px\"\n\t\t\t\t\t\talt=\"Coal Fired Power Plant in the Rhenish Lignite Mining Area. \u00a9 Bernd Lauter \/ Greenpeace\" title=\"Coal Fired Power Plant in the Rhenish Lignite Mining Area. \u00a9 Bernd Lauter \/ Greenpeace\"\n\t\t\t\t\/>\n            \t\t\t<div class=\"boxout-content\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\tclass=\"boxout-heading medium\"\n\t\t\t\t\t\tdata-ga-category=\"Take Action Boxout\"\n\t\t\t\t\t\tdata-ga-action=\"Title\"\n\t\t\t\t\t\tdata-ga-label=\"n\/a\"\n\t\t\t\t\t\thref=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/wir-weigern-uns-die-klimakrise-zu-finanzieren\/\"\n\t\t\t\t\t\t\n\t\t\t\t\t>\n\t\t\t\t\t\tFDC: Wir weigern uns die Klimakrise mit unseren Rentengeldern zu finanzieren\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t                                    <a\n                        class=\"btn btn-primary\"\n                        data-ga-category=\"Take Action Boxout\"\n                        data-ga-action=\"Call to Action\"\n                        data-ga-label=\"n\/a\"\n                        href=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/wir-weigern-uns-die-klimakrise-zu-finanzieren\/\"\n                        \n                    >\n                        Machen Sie mit!\n                    <\/a>\n                \t\t\t<\/div>\n\t\t\t\t\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"<p>Die Investitionen des Luxemburger Pensionsfonds FDC sind weiterhin nicht im Einklang mit den Zielen des Pariser Klimaschutzabkommens. <\/p>\n","protected":false},"author":31,"featured_media":11859,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[49,48,46],"tags":[60,63,96],"p4-page-type":[69],"class_list":["post-11862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","category-klima","category-problem","tag-luxemburg","tag-fossileenergien","tag-finanzsektor","p4-page-type-presseerklaerungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht - Greenpeace Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht\" \/>\n<meta property=\"og:description\" content=\"Die Investitionen des Luxemburger Pensionsfonds FDC sind weiterhin nicht im Einklang mit den Zielen des Pariser Klimaschutzabkommens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\" \/>\n<meta property=\"og:site_name\" content=\"Greenpeace Luxembourg\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/greenpeaceluxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2021-07-08T11:51:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T15:23:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Myriam Wecker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Myriam Wecker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\"},\"author\":{\"name\":\"Myriam Wecker\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776\"},\"headline\":\"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht\",\"datePublished\":\"2021-07-08T11:51:04+00:00\",\"dateModified\":\"2021-12-01T15:23:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\"},\"wordCount\":847,\"publisher\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg\",\"keywords\":[\"Luxemburg\",\"FossileEnergien\",\"Finanzsektor\"],\"articleSection\":[\"Energie\",\"Klima\",\"Problem\"],\"inLanguage\":\"de-LU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\",\"name\":\"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht - Greenpeace Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg\",\"datePublished\":\"2021-07-08T11:51:04+00:00\",\"dateModified\":\"2021-12-01T15:23:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#breadcrumb\"},\"inLanguage\":\"de-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage\",\"url\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg\",\"contentUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg\",\"width\":400,\"height\":600,\"caption\":\"Aktivisten und Aktivistinnen von Greenpeace Luxemburg platzieren zwei menschengro\u00dfe gelbe Schilder mit der Aufschrift \\\"Caution - Greenwash\\\" am Haupteingang des Sitzes des nationalen Pensionsfonds in Luxemburg, um gegen weitere Investitionen in fossile Brennstoffe zu protestieren. Known as Fonds de Compensation (FDC), Luxembourg\u2019s pension fund claims to conduct sustainable and socially responsible investments, yet provided more than half of a billion Euro to oil, gas and coal companies like Shell, BP, Total and Chevron during 2019. Greenpeace Luxembourg criticized the greenwashing tactics and demanded immediate measures from Parliament and the government to ensure the withdrawal of public funds entrusted to the FDC from fossil fuel corporations.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\",\"name\":\"Greenpeace Luxembourg\",\"description\":\"Greenpeace existiert, weil unsere Erde eine Stimme braucht. Sie ben\u00f6tigt L\u00f6sungen. Ver\u00e4nderungen. Aktionen.\",\"publisher\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\",\"name\":\"Greenpeace Luxembourg\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png\",\"contentUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png\",\"width\":1080,\"height\":175,\"caption\":\"Greenpeace Luxembourg\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/greenpeaceluxembourg\",\"https:\/\/www.instagram.com\/greenpeacelux\/\",\"https:\/\/www.linkedin.com\/company\/greenpeace-luxembourg\/\",\"https:\/\/www.threads.com\/@greenpeacelux\",\"https:\/\/bsky.app\/profile\/greenpeacelux.bsky.social\",\"https:\/\/www.youtube.com\/@GreenpeaceLux\",\"https:\/\/www.tiktok.com\/@greenpeace_lux\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776\",\"name\":\"Myriam Wecker\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/author\/mwecker\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht - Greenpeace Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/","og_locale":"de_DE","og_type":"article","og_title":"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht","og_description":"Die Investitionen des Luxemburger Pensionsfonds FDC sind weiterhin nicht im Einklang mit den Zielen des Pariser Klimaschutzabkommens.","og_url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/","og_site_name":"Greenpeace Luxembourg","article_publisher":"https:\/\/www.facebook.com\/greenpeaceluxembourg","article_published_time":"2021-07-08T11:51:04+00:00","article_modified_time":"2021-12-01T15:23:51+00:00","og_image":[{"width":400,"height":600,"url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg","type":"image\/jpeg"}],"author":"Myriam Wecker","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Myriam Wecker","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#article","isPartOf":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/"},"author":{"name":"Myriam Wecker","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776"},"headline":"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht","datePublished":"2021-07-08T11:51:04+00:00","dateModified":"2021-12-01T15:23:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/"},"wordCount":847,"publisher":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg","keywords":["Luxemburg","FossileEnergien","Finanzsektor"],"articleSection":["Energie","Klima","Problem"],"inLanguage":"de-LU"},{"@type":"WebPage","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/","url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/","name":"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht - Greenpeace Luxembourg","isPartOf":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg","datePublished":"2021-07-08T11:51:04+00:00","dateModified":"2021-12-01T15:23:51+00:00","breadcrumb":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#breadcrumb"},"inLanguage":"de-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/"]}]},{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#primaryimage","url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg","contentUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/07\/8bedab2f-gp1su4qv_low_res_with_credit_line.jpg","width":400,"height":600,"caption":"Aktivisten und Aktivistinnen von Greenpeace Luxemburg platzieren zwei menschengro\u00dfe gelbe Schilder mit der Aufschrift \"Caution - Greenwash\" am Haupteingang des Sitzes des nationalen Pensionsfonds in Luxemburg, um gegen weitere Investitionen in fossile Brennstoffe zu protestieren. Known as Fonds de Compensation (FDC), Luxembourg\u2019s pension fund claims to conduct sustainable and socially responsible investments, yet provided more than half of a billion Euro to oil, gas and coal companies like Shell, BP, Total and Chevron during 2019. Greenpeace Luxembourg criticized the greenwashing tactics and demanded immediate measures from Parliament and the government to ensure the withdrawal of public funds entrusted to the FDC from fossil fuel corporations."},{"@type":"BreadcrumbList","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/11862\/fdc-investitionen-in-klimaschadliche-kohle-steigen-weiter-an-laut-jahresbericht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/"},{"@type":"ListItem","position":2,"name":"FDC-Investitionen in klimasch\u00e4dliche Kohle steigen weiter an, laut Jahresbericht"}]},{"@type":"WebSite","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website","url":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/","name":"Greenpeace Luxembourg","description":"Greenpeace existiert, weil unsere Erde eine Stimme braucht. Sie ben\u00f6tigt L\u00f6sungen. Ver\u00e4nderungen. Aktionen.","publisher":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-LU"},{"@type":"Organization","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization","name":"Greenpeace Luxembourg","url":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png","contentUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png","width":1080,"height":175,"caption":"Greenpeace Luxembourg"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/greenpeaceluxembourg","https:\/\/www.instagram.com\/greenpeacelux\/","https:\/\/www.linkedin.com\/company\/greenpeace-luxembourg\/","https:\/\/www.threads.com\/@greenpeacelux","https:\/\/bsky.app\/profile\/greenpeacelux.bsky.social","https:\/\/www.youtube.com\/@GreenpeaceLux","https:\/\/www.tiktok.com\/@greenpeace_lux"]},{"@type":"Person","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776","name":"Myriam Wecker","url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/author\/mwecker\/"}]}},"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/11862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/comments?post=11862"}],"version-history":[{"count":5,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/11862\/revisions"}],"predecessor-version":[{"id":12818,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/11862\/revisions\/12818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/media\/11859"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/media?parent=11862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/categories?post=11862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/tags?post=11862"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/p4-page-type?post=11862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}