{"id":12329,"date":"2021-09-28T12:46:32","date_gmt":"2021-09-28T10:46:32","guid":{"rendered":"https:\/\/www.greenpeace.org\/luxembourg\/?p=12329"},"modified":"2021-12-01T17:23:20","modified_gmt":"2021-12-01T15:23:20","slug":"anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/","title":{"rendered":"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen"},"content":{"rendered":"\n<p><strong>Heute hat eine Gruppe zivilgesellschaftlicher Organisationen [1] ihre Hauptkritikpunkte an der Luxembourg Sustainable Finance Strategy (LSFS) vorgestellt. Die wichtigsten Schlussfolgerungen sind, dass es der LSFS an klaren Zielen, konkreten Ma\u00dfnahmen sowie einem Zeitplan f\u00fcr den luxemburgischen Finanzsektor mangelt, um den Schutz der Menschenrechte und Umwelt sicher zu stellen. Von den Organisationen w\u00e4hrend der \u00f6ffentlichen Konsultationsphase geleistete Beitr\u00e4ge wurden seitens der LSFI v\u00f6llig au\u00dfer Acht gelassen. So sieht die LSFS beispielsweise weder einen konkreten Rahmen vor, um den luxemburgischen Finanzsektor auf die Einhaltung des Pariser Abkommens zu verpflichten, noch dass die UN-Leitprinzipien f\u00fcr Menschenrechte und Unternehmen respektiert werden m\u00fcssen. Die Gruppe der zivilgesellschaftlichen Organisationen fordert deshalb in einer anstehenden Strategie\u00fcberpr\u00fcfung die Behebung dieser M\u00e4ngel, sowie ein klares Bekenntnis der Regierung zur Schaffung des erforderlichen Regulierungsrahmens, um den Finanzsektor mit Nachhaltigkeitszielen in Einklang zu bringen. <\/strong>\n<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-1024x621.jpg\" alt=\"\" class=\"wp-image-12325\" width=\"512\" height=\"311\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-1024x621.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-300x182.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-768x465.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-1536x931.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-2048x1241.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/0bf2aa4f-img_20210927_100824_2-510x309.jpg 510w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n<p>Die am 9. Februar 2021 von der Luxembourg Sustainable Finance Initiative (LSFI) [2] ins Leben gerufene <em>&#8220;Luxembourg Sustainable Finance Strategy&#8221;<\/em> zielt darauf ab, das Bewusstsein f\u00fcr nachhaltige Finanzinitiativen in Luxemburg zu sch\u00e4rfen, sie zu f\u00f6rdern und ihre Entwicklung zu unterst\u00fctzen. Im Rahmen einer \u00f6ffentlichen Konsultation gaben mehr als 30 Organisationen [3] Ende 2020 Feedback zum ersten Entwurf der Strategie. Bei der Ver\u00f6ffentlichung des endg\u00fcltigen Strategiedokuments stellten die Organisationen der Zivilgesellschaft jedoch entt\u00e4uscht fest, dass so gut wie keine ihrer Empfehlungen von der LSFI ber\u00fccksichtigt wurde sowie, dass die endg\u00fcltige Strategie bedeutende M\u00e4ngel aufweist. Die Gruppe der zivilgesellschaftlichen Organisationen beschloss daher, ihre Bedenken und Forderungen zu wiederholen [4].  <\/p>\n\n<p>Die Organisationen m\u00f6chten aufzeigen, dass die LSFS erhebliche L\u00fccken in der Strategie aufweist, die, wenn sie nicht behoben werden, verhindern werden, dass die LSFS-Strategie sinnvolle Verbesserungen im Bereich der nachhaltigen Finanzen bringt. So konzentriert sich die LSFS in einem klassischen Fall von Quantit\u00e4t vor Qualit\u00e4t auf die F\u00f6rderung von Initiativen zur nachhaltigen Finanzierung, ohne zu pr\u00fcfen, ob die betreffenden Initiativen tats\u00e4chlich zu einer nachhaltigen Entwicklung in der Realwirtschaft f\u00fchren. Dar\u00fcber hinaus geht die LSFS nicht auf die Tatsache ein, dass die luxemburgische Finanzindustrie bei der Ausrichtung ihrer Finanzstr\u00f6me entsprechend der Ziele des Pariser Abkommens stark im R\u00fcckstand ist. Ein weiterer erheblicher Kritikpunkt an der LSFS ist das Fehlen konkreter Ma\u00dfnahmen zum Schutz der Menschenrechte. \n<\/p>\n\n<p>Angesichts dieser Unzul\u00e4nglichkeiten fordert die Gruppe der zivilgesellschaftlichen Organisationen, dass der Status quo des luxemburgischen Finanzsektors in Bezug auf seine \u00f6kologischen und gesellschaftlichen Auswirkungen analysiert wird, um die \u00dcberwachung und Messung der Fortschritte bei der Erreichung kurz-, mittel- und langfristiger Ziele zu erm\u00f6glichen. Die LSFS muss darauf abzielen, alle Finanzstr\u00f6me mit den Zielen des Pariser Abkommens in Einklang zu bringen und die nachhaltige Finanzierung in den Mainstream zu bringen, wobei es <em>Greenwashing<\/em> und <em>Rebranding<\/em> zu vermeiden gilt.\n<\/p>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-1024x654.jpg\" alt=\"\" class=\"wp-image-12323\" width=\"512\" height=\"327\" srcset=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-1024x654.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-300x192.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-768x490.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-1536x981.jpg 1536w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-2048x1308.jpg 2048w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-510x326.jpg 510w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n<p>Freiwillige Ma\u00dfnahmen allein werden nicht den notwendigen Wandel in der Finanzindustrie hin zu mehr Nachhaltigkeit bewirken. Die luxemburgische Regierung muss eine klare Haltung einnehmen und sich verpflichten, den Finanzplatz an den Nachhaltigkeitszielen auszurichten, indem sie den richtigen regulatorischen Rahmen f\u00fcr eine umfassende Transformation der luxemburgischen Finanzindustrie schafft. Die nationalen Aufsichtsbeh\u00f6rden (CSSF, CAA und BCL) sollten klare Anforderungen an die Finanzinstitute stellen, um die Risiken, die mit der Vernachl\u00e4ssigung von Nachhaltigkeitsaspekten in ihrem Gesch\u00e4ftsmodell verbunden sind, zu bewerten und zu steuern.\nDer Schutz der Menschenrechte muss ein wichtiger Bestandteil des LSFS werden. Durch die Verabschiedung eines nationalen Gesetzes \u00fcber die Sorgfaltspflicht in Bezug auf Menschenrechte und Umwelt, auch f\u00fcr den Finanzsektor, k\u00f6nnte Luxemburg als Kandidat f\u00fcr den UN-Menschenrechtsrat und als Unterzeichner zahlreicher internationaler Konventionen und Vertr\u00e4ge (z. B. CBD, UNFCCC, ILO) auf nationaler und EU-Ebene eine deutlich aktivere Rolle bei der Gestaltung einer ehrgeizigeren Regelung spielen.\nNicht zuletzt muss die Zivilgesellschaft eng in den L\u00f6sungsfindungsprozess eingebunden werden, da sie eine entscheidende Rolle im Kampf gegen den Klimawandel, den Verlust der biologischen Vielfalt und Menschenrechtsverletzungen spielt.\nAls wichtigem Standort in der globalen Finanzarchitektur muss Luxemburg seiner Verantwortung gerecht werden, den Finanzsektor und dessen Aktivit\u00e4ten zu lenken, zu \u00fcberwachen und zu regulieren, insbesondere wenn es um den Schutz der Umwelt und der Menschenrechte geht. Die LSFS muss dieser Verantwortung ebenso gerecht werden und sich mit den derzeit fehlenden oder unzureichenden Aspekten ihres Ansatzes befassen, wenn sie nachhaltiges Finanzwesen in den Mainstream bringen und eine echte Wirkung erzielen soll. Nur dann kann sie ihr Potenzial voll aussch\u00f6pfen und zu einem echten Wendepunkt f\u00fcr das Leben und die Lebensgrundlagen von Millionen von Menschen werden. \n<\/p>\n\n<hr class=\"wp-block-separator\"\/>\n\n<p>[1] Etika, Greenpeace Luxemburg, ASTM, Commission Justice &amp; Paix, SOS Faim sowie der NGO-Verband Cercle de Coop\u00e9ration des ONGD. <\/p>\n\n<p>[2] Die LSFI wurde im Januar 2020 von der luxemburgischen Regierung, Luxembourg for Finance (die Agentur f\u00fcr die Entwicklung des Finanzplatzes) und dem Hohen Rat f\u00fcr nachhaltige Entwicklung (ein unabh\u00e4ngiges Beratungsgremium der luxemburgischen Regierung in Fragen der nachhaltigen Entwicklung, welches auch die Zivilgesellschaft vertritt) gegr\u00fcndet. <\/p>\n\n<p>[3] Luxembourg Sustainable Finance Initiative, &#8216;A Sustainable Finance Strategy for Luxembourg and its financial centre&#8217;, Pressemitteilung, 9. Februar 2021 <\/p>\n\n<p>[4] Laden Sie die Kurzinformation \u201cWhy the Luxembourg Sustainable Finance Strategy will not deliver: Components for bringing sustainable finance into the mainstream\u201d <a href=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/c4a21732-numerique_common-statement-lsfs.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a> herunter. Das Briefing ist keine Punkt-f\u00fcr-Punkt-Kritik an der LSFS, sondern soll wesentliche L\u00fccken in der Strategie aufzeigen, die, wenn sie nicht behoben werden, die LSFS daran hindern werden, sinnvolle Verbesserungen im Bereich der nachhaltigen Finanzen zu erreichen.  <\/p>\n\t\t\t<section\n\t\t\tclass=\"boxout post-5673 \"\n\t\t\t\n\t\t>\n\t\t\t<a\n\t\t\t\tdata-ga-category=\"Take Action Boxout\"\n\t\t\t\tdata-ga-action=\"Image\"\n\t\t\t\tdata-ga-label=\"n\/a\"\n\t\t\t\tclass=\"cover-card-overlay\"\n\t\t\t\thref=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/wir-weigern-uns-die-klimakrise-zu-finanzieren\/\" \n\t\t\t><\/a>\n\t\t\t\t\t\t\t<img\n\t\t\t\t\t\tsrc=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-1024x683.jpg\"\n\t\t\t\t\t\tsrcset=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-300x200.jpg 300w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-768x512.jpg 768w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-1024x683.jpg 1024w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp-510x340.jpg 510w, https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2019\/09\/4cab98e6-gp0strcjp.jpg 1200w\"\n\t\t\t\t\t\tsizes=\"(min-width: 1000px) 358px, (min-width: 780px) 313px, 88px\"\n\t\t\t\t\t\talt=\"Coal Fired Power Plant in the Rhenish Lignite Mining Area. \u00a9 Bernd Lauter \/ Greenpeace\" title=\"Coal Fired Power Plant in the Rhenish Lignite Mining Area. \u00a9 Bernd Lauter \/ Greenpeace\"\n\t\t\t\t\/>\n            \t\t\t<div class=\"boxout-content\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\tclass=\"boxout-heading medium\"\n\t\t\t\t\t\tdata-ga-category=\"Take Action Boxout\"\n\t\t\t\t\t\tdata-ga-action=\"Title\"\n\t\t\t\t\t\tdata-ga-label=\"n\/a\"\n\t\t\t\t\t\thref=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/wir-weigern-uns-die-klimakrise-zu-finanzieren\/\"\n\t\t\t\t\t\t\n\t\t\t\t\t>\n\t\t\t\t\t\tFDC: Wir weigern uns die Klimakrise mit unseren Rentengeldern zu finanzieren\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t                                    <a\n                        class=\"btn btn-primary\"\n                        data-ga-category=\"Take Action Boxout\"\n                        data-ga-action=\"Call to Action\"\n                        data-ga-label=\"n\/a\"\n                        href=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/wir-weigern-uns-die-klimakrise-zu-finanzieren\/\"\n                        \n                    >\n                        Machen Sie mit!\n                    <\/a>\n                \t\t\t<\/div>\n\t\t\t\t\t<\/section>\n\t","protected":false},"excerpt":{"rendered":"<p>Eine Gruppe zivilgesellschaftlicher Organisationen hat ihre Hauptkritikpunkte an der LSFS vorgestellt.<\/p>\n","protected":false},"author":31,"featured_media":12324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"not set","p4_local_project":"not set","p4_basket_name":"not set","p4_department":"","footnotes":""},"categories":[49,48,46],"tags":[60,96],"p4-page-type":[69],"class_list":["post-12329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energie","category-klima","category-problem","tag-luxemburg","tag-finanzsektor","p4-page-type-presseerklaerungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen - Greenpeace Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen\" \/>\n<meta property=\"og:description\" content=\"Eine Gruppe zivilgesellschaftlicher Organisationen hat ihre Hauptkritikpunkte an der LSFS vorgestellt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\" \/>\n<meta property=\"og:site_name\" content=\"Greenpeace Luxembourg\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/greenpeaceluxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-28T10:46:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-01T15:23:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1635\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Myriam Wecker\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Myriam Wecker\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\"},\"author\":{\"name\":\"Myriam Wecker\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776\"},\"headline\":\"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen\",\"datePublished\":\"2021-09-28T10:46:32+00:00\",\"dateModified\":\"2021-12-01T15:23:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\"},\"wordCount\":901,\"publisher\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg\",\"keywords\":[\"Luxemburg\",\"Finanzsektor\"],\"articleSection\":[\"Energie\",\"Klima\",\"Problem\"],\"inLanguage\":\"de-LU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\",\"name\":\"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen - Greenpeace Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg\",\"datePublished\":\"2021-09-28T10:46:32+00:00\",\"dateModified\":\"2021-12-01T15:23:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#breadcrumb\"},\"inLanguage\":\"de-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage\",\"url\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg\",\"contentUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg\",\"width\":2560,\"height\":1635},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\",\"name\":\"Greenpeace Luxembourg\",\"description\":\"Greenpeace existiert, weil unsere Erde eine Stimme braucht. Sie ben\u00f6tigt L\u00f6sungen. Ver\u00e4nderungen. Aktionen.\",\"publisher\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\",\"name\":\"Greenpeace Luxembourg\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png\",\"contentUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png\",\"width\":1080,\"height\":175,\"caption\":\"Greenpeace Luxembourg\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/greenpeaceluxembourg\",\"https:\/\/www.instagram.com\/greenpeacelux\/\",\"https:\/\/www.linkedin.com\/company\/greenpeace-luxembourg\/\",\"https:\/\/www.threads.com\/@greenpeacelux\",\"https:\/\/bsky.app\/profile\/greenpeacelux.bsky.social\",\"https:\/\/www.youtube.com\/@GreenpeaceLux\",\"https:\/\/www.tiktok.com\/@greenpeace_lux\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776\",\"name\":\"Myriam Wecker\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/author\/mwecker\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen - Greenpeace Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/","og_locale":"de_DE","og_type":"article","og_title":"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen","og_description":"Eine Gruppe zivilgesellschaftlicher Organisationen hat ihre Hauptkritikpunkte an der LSFS vorgestellt.","og_url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/","og_site_name":"Greenpeace Luxembourg","article_publisher":"https:\/\/www.facebook.com\/greenpeaceluxembourg","article_published_time":"2021-09-28T10:46:32+00:00","article_modified_time":"2021-12-01T15:23:20+00:00","og_image":[{"width":2560,"height":1635,"url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg","type":"image\/jpeg"}],"author":"Myriam Wecker","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Myriam Wecker","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#article","isPartOf":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/"},"author":{"name":"Myriam Wecker","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776"},"headline":"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen","datePublished":"2021-09-28T10:46:32+00:00","dateModified":"2021-12-01T15:23:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/"},"wordCount":901,"publisher":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg","keywords":["Luxemburg","Finanzsektor"],"articleSection":["Energie","Klima","Problem"],"inLanguage":"de-LU"},{"@type":"WebPage","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/","url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/","name":"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen - Greenpeace Luxembourg","isPartOf":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg","datePublished":"2021-09-28T10:46:32+00:00","dateModified":"2021-12-01T15:23:20+00:00","breadcrumb":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#breadcrumb"},"inLanguage":"de-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/"]}]},{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#primaryimage","url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg","contentUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2021\/09\/548ba825-img_20210927_094952-scaled.jpg","width":2560,"height":1635},{"@type":"BreadcrumbList","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/12329\/anpassen-oder-scheitern-lsfs-muss-grundlegend-uberarbeitet-werden-um-die-ziele-fur-nachhaltige-finanzen-zu-erreichen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/"},{"@type":"ListItem","position":2,"name":"Anpassen oder Scheitern! LSFS muss grundlegend \u00fcberarbeitet werden, um die Ziele f\u00fcr nachhaltige Finanzen zu erreichen"}]},{"@type":"WebSite","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website","url":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/","name":"Greenpeace Luxembourg","description":"Greenpeace existiert, weil unsere Erde eine Stimme braucht. Sie ben\u00f6tigt L\u00f6sungen. Ver\u00e4nderungen. Aktionen.","publisher":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-LU"},{"@type":"Organization","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization","name":"Greenpeace Luxembourg","url":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png","contentUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png","width":1080,"height":175,"caption":"Greenpeace Luxembourg"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/greenpeaceluxembourg","https:\/\/www.instagram.com\/greenpeacelux\/","https:\/\/www.linkedin.com\/company\/greenpeace-luxembourg\/","https:\/\/www.threads.com\/@greenpeacelux","https:\/\/bsky.app\/profile\/greenpeacelux.bsky.social","https:\/\/www.youtube.com\/@GreenpeaceLux","https:\/\/www.tiktok.com\/@greenpeace_lux"]},{"@type":"Person","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/c2ae6002b8ed18c00be0c6b320eea776","name":"Myriam Wecker","url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/author\/mwecker\/"}]}},"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/12329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/comments?post=12329"}],"version-history":[{"count":7,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/12329\/revisions"}],"predecessor-version":[{"id":12798,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/12329\/revisions\/12798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/media\/12324"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/media?parent=12329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/categories?post=12329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/tags?post=12329"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/p4-page-type?post=12329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}