{"id":24933,"date":"2025-06-30T14:55:02","date_gmt":"2025-06-30T12:55:02","guid":{"rendered":"https:\/\/www.greenpeace.org\/luxembourg\/?p=24933"},"modified":"2025-06-30T15:03:02","modified_gmt":"2025-06-30T13:03:02","slug":"nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik","status":"publish","type":"post","link":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/","title":{"rendered":"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0"},"content":{"rendered":"\n<p><strong>Am heutigen Montag, den 30. Juni 2025 hat die Plattform Meng Landwirtschaft, mit ihren 19 Tr\u00e4gerorganisationen, die vollst\u00e4ndig \u00fcberarbeitete vierte Auflage ihres <a href=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/0e855cf2-meng-landwirtschaft-pladoyer-fur-eine-gerechte-und-zukunftsfahige-agarpolitik.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Pl\u00e4doyers f\u00fcr eine Neuausrichtung der Landwirtschaft<\/a> an dem 2000m2-Feld am Haus vun der Natur vorgestellt. Meng Landwirtschaft will die \u00f6ffentliche Diskussion \u00fcber die Zukunft der Landwirtschaft in Luxemburg anregen und aktiv mitgestalten.\u00a0<\/strong><\/p>\n\n<p>Meng Landwirtschaft fordert die luxemburgische Politik dazu auf, auf nationaler und europ\u00e4ischer Ebene Rahmenbedingungen zu schaffen, in denen landwirtschaftliche Betriebe nicht nur als reine Wirtschaftsakteure im Wettbewerb stehen, sondern in ihren sozialen und \u00f6kologischen Kontext eingebettet sind und im Sinne des Gemeinwohls wirken k\u00f6nnen.&nbsp;<\/p>\n\n<p>Inmitten der Umsetzung der aktuellen Gemeinsamen Agrarpolitik (GAP 2023-2027) der EU, in der Evaluationen und Anpassungen anstehen, aber gleichzeitig bereits die n\u00e4chste Phase vorbereitet wird, ist eine breite und kritische Auseinandersetzung mit der Agrarpolitik unerl\u00e4\u00dflich. Vor dem Hintergrund der gro\u00dfen umwelt- und ern\u00e4hrungspolitischen Herausforderungen sind die aktuellen nationalen und europ\u00e4ischen Liberalisierungs- und Deregulierungsvorhaben eine gro\u00dfe Gefahr f\u00fcr die kleinb\u00e4uerliche und nachhaltige Landwirtschaft in Luxemburg und weltweit, den Schutz der nat\u00fcrlichen Ressourcen und mehr Gerechtigkeit.&nbsp;<\/p>\n\n<p>Meng Landwirtschaft setzt sich f\u00fcr eine grundlegende Neuausrichtung der Agrarpolitik ein. Ein zentraler Leitgedanke dabei lautet: \u201ePublic money for public goods\u201c. \u00d6ffentliche Mittel sollten immer dem Gemeinwohl dienen. Entsprechend sollten staatliche Subventionen st\u00e4rker dazu genutzt werden, konkrete \u00f6ffentliche Leistungen wie Umwelt- und Naturschutz zu unterst\u00fctzen. Die Abwendung von rein wirtschaftlichen Leistungskriterien bietet gleichzeitig die M\u00f6glichkeit, den landwirtschaftlichen Beruf aufzuwerten und anregendere Zukunftsperspektiven f\u00fcr die Landwirt*innen zu schaffen.&nbsp;<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Die luxemburgische Agrarpolitik: seit Jahrzehnten in der Sackgasse&nbsp;<\/strong><\/h3>\n\n<p>Die luxemburgische Landwirtschaft ist gepr\u00e4gt von wirtschaftlichen Zw\u00e4ngen, Konkurrenzdenken und einer Spezialisierung auf eine intensiv betriebene Rinderzucht. Den vergleichsweise beachtlichen Spielraum, den die EU den Mitgliedstaaten im Rahmen der letzten GAP-Reform gew\u00e4hrt hat, hat die luxemburgische Regierung bislang nicht f\u00fcr eine umweltfreundlichere Agrarpolitik genutzt. Dabei w\u00e4chst die Kluft zwischen den \u00f6kologischen und sozialen Bed\u00fcrfnissen der Gesellschaft und der Verbraucher*innen einerseits, und der Art und Weise, wie die Landwirtschaft heute produziert und wie sie organisiert ist andererseits.&nbsp;<\/p>\n\n<p>Im aktuellen System gibt es f\u00fcr die Allgemeinheit wenig zu gewinnen, daf\u00fcr aber viel zu verlieren. Viel zu verlieren, weil die vorherrschende landwirtschaftliche Praxis erhebliche Auswirkungen auf die Umwelt und Biodiversit\u00e4t, das Klima und das Wohlergehen und die Gesundheit der Menschen in Luxemburg und im globalen S\u00fcden hat. Wenig zu gewinnen, weil der Sektor nur dank \u00f6ffentlicher Beihilfen \u00fcberhaupt ein positives Netto-Einkommen erwirtschaftet und den Landwirt*innen kaum attraktive Zukunftsperspektiven bietet.&nbsp;<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Neue Wurzeln schaffen f\u00fcr eine gerechte und krisenfeste Landwirtschaft&nbsp;<\/strong><\/h3>\n\n<p>Umgekehrt birgt eine sozial und \u00f6kologisch nachhaltige Landwirtschaft gro\u00dfe Chancen \u2013 mit wenig zu verlieren und viel zu gewinnen. Als aktiver Akteur im Umwelt-, Natur- und Klimaschutz ergeben sich f\u00fcr die Landwirtschaft nicht nur neue Einkommensquellen, sondern der gesamte Sektor wird insgesamt resilienter.&nbsp;<\/p>\n\n<p>Ein weiteres Ziel sollte es sein, die vielf\u00e4ltigen Aspekte von Landwirtschaft und Ern\u00e4hrung vermehrt als Ganzes zu betrachten und die luxemburgische Landwirtschaft aus ihrer derzeitigen politischen Isolation zu l\u00f6sen.Ein integrativer Ansatz, der die Wechselwirkungen zwischen Landwirtschaft, Ern\u00e4hrung, Umwelt, Klima und Gesundheit ber\u00fccksichtigt, ist unerl\u00e4sslich f\u00fcr eine zukunftsf\u00e4hige Landwirtschaft in Luxemburg. Dazu geh\u00f6rt auch der Schutz und die F\u00f6rderung lokaler Produktions-, Vertriebs- und Verteilungssysteme: Kleinere Betriebe und regionale Netzwerke m\u00fcssen gest\u00e4rkt werden, um die Abh\u00e4ngigkeit von globalen Lieferketten zu verringern und die Resilienz des Agrarsystems zu erh\u00f6hen.&nbsp;<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Ein hochaktuelles Pl\u00e4doyer mit konkreten Impulsen und Beispielen f\u00fcr die Zukunft&nbsp;<\/strong><\/h3>\n\n<p>Unterteilt in acht Impulse werden Denkanst\u00f6\u00dfe gegeben, wie die Landwirtschaft zum Wohl aller beitragen kann. Meng Landwirtschaft schl\u00e4gt vor, das Potenzial der Landwirtschaft f\u00fcr Natur- und Umweltschutz zu nutzen, Biolandwirtschaft konsequent zu f\u00f6rdern und die Nutztierhaltung nachhaltig und tierfreundlich zu gestalten. Gleichzeitig soll die lokale Produktion diversifiziert und gest\u00e4rkt sowie die gesunde Ern\u00e4hrung gesellschaftlich verankert werden. Ern\u00e4hrung und Landwirtschaft m\u00fcssen endlich zusammen gedacht und die landwirtschaftlichen Berufe aufgewertet werden.&nbsp;<\/p>\n\n<p>Eine nachhaltige Agrarpolitik ist m\u00f6glich, wie bereits heute viele Initiativen im In- und Ausland beweisen. Dementsprechend werden im neuen Pl\u00e4doyer von Meng Landwirtschaft acht Best Practice Beispiele erl\u00e4utert: von Regionen und L\u00e4ndern mit hohem Bioanteil, Initiativen, die den B\u00e4uer*innen und G\u00e4rtner*innen faire Preise garantieren \u00fcber innovative Initiativen hin zur Promotion der pflanzlichen Ern\u00e4hrung.&nbsp;<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Neuauflage des Pl\u00e4doyers von Meng Landwirtschaft gratis erh\u00e4ltlich&nbsp;<\/strong><\/h3>\n\n<p>Die Neuauflage des Pl\u00e4doyers von Meng Landwirtschaft ist digital auf www.meng-landwirtschaft.lu abrufbar und kann in Papierform gratis \u00fcber menglandwirtschaft@naturemwelt.lu bestellt werden. Am kommenden Freitag ist die Brosch\u00fcre auch beim Klimatag vom Klimab\u00fcndnis, am Samstag beim Festival Voices for planet von CELL und am gesamten Wochenende auf der Foire Agricole bei natur&amp;\u00ebmwelt und der Biovereenegung erh\u00e4ltlich.&nbsp;<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Meng Landwirtschaft: seit 15 Jahren engagiert f\u00fcr eine Agrarwende&nbsp;<\/strong><\/h3>\n\n<p>Meng Landwirtschaft ist eine Plattform luxemburgischer Nichtregierungsorganisationen, die sich mit Themen rund um Landwirtschaft, Ern\u00e4hrung, Umwelt, Naturschutz, Tierschutz, Verbraucherschutz, Gesundheit und Entwicklungszusammenarbeit befassen. Meng Landwirtschaft will die \u00f6ffentliche Diskussion \u00fcber die Zukunft der Landwirtschaft in Luxemburg anregen und aktiv mitgestalten. Die Plattform wurde 2010 gegr\u00fcndet und pr\u00e4sentierte 2014 erstmals ihre agrarpolitischen Forderungen.&nbsp;<\/p>\n\n<p>Das neue Pl\u00e4doyer wird von folgenden 19 Organisationen getragen: natur&amp;\u00ebmwelt natur&amp;\u00ebmwelt a.s.b.l., Vereenegung fir Biolandwirtschaft L\u00ebtzebuerg a.s.b.l., Greenpeace Luxembourg, Action Solidarit\u00e9 Tiers Monde, SOS Faim Luxembourg, Mouvement \u00e9cologique, etika, CELL, Slow Food Luxembourg, Cercle de Coop\u00e9ration, Aide \u00e0 l\u2018Enfance de l\u2018Inde et du N\u00e9pal, L\u00ebtzebuerger Landesverband fir Beienzuucht, SEED, Kampagne \u201eohne Pestizide\u201c, Fairtrade L\u00ebtzebuerg, Fr\u00e8res des Hommes, Foodsharing Luxembourg, Netzwierk Agro\u00f6kologie, Fondation Partage.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Plattform Meng Landwirtschaft, mit ihren 19 Tr\u00e4gerorganisationen, pr\u00e4sentiert die vollst\u00e4ndig \u00fcberarbeitete vierte Auflage ihres Pl\u00e4doyers f\u00fcr eine Neuausrichtung der Landwirtschaft an dem\u2026<\/p>\n","protected":false},"author":25,"featured_media":24936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ep_exclude_from_search":false,"p4_og_title":"","p4_og_description":"","p4_og_image":"","p4_og_image_id":"","p4_seo_canonical_url":"","p4_campaign_name":"","p4_local_project":"","p4_basket_name":"","p4_department":"","footnotes":""},"categories":[24,47],"tags":[67],"p4-page-type":[69],"class_list":["post-24933","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-greenpeace","category-natur","tag-nachhaltigelandwirtschaft","p4-page-type-presseerklaerungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v23.9 (Yoast SEO v23.9) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0 - Greenpeace Luxembourg<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0\" \/>\n<meta property=\"og:description\" content=\"Die Plattform Meng Landwirtschaft, mit ihren 19 Tr\u00e4gerorganisationen, pr\u00e4sentiert die vollst\u00e4ndig \u00fcberarbeitete vierte Auflage ihres Pl\u00e4doyers f\u00fcr eine Neuausrichtung der Landwirtschaft an dem\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\" \/>\n<meta property=\"og:site_name\" content=\"Greenpeace Luxembourg\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/greenpeaceluxembourg\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-30T12:55:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T13:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22-1024x682.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Esther Wildanger\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Esther Wildanger\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\"},\"author\":{\"name\":\"Esther Wildanger\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/3d0e81a859b59009fec36a8552ef76a7\"},\"headline\":\"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0\",\"datePublished\":\"2025-06-30T12:55:02+00:00\",\"dateModified\":\"2025-06-30T13:03:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\"},\"wordCount\":981,\"publisher\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png\",\"keywords\":[\"NachhaltigeLandwirtschaft\"],\"articleSection\":[\"Greenpeace\",\"Natur\"],\"inLanguage\":\"de-LU\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\",\"name\":\"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0 - Greenpeace Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png\",\"datePublished\":\"2025-06-30T12:55:02+00:00\",\"dateModified\":\"2025-06-30T13:03:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#breadcrumb\"},\"inLanguage\":\"de-LU\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage\",\"url\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png\",\"contentUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png\",\"width\":1772,\"height\":1181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\",\"name\":\"Greenpeace Luxembourg\",\"description\":\"Greenpeace existiert, weil unsere Erde eine Stimme braucht. Sie ben\u00f6tigt L\u00f6sungen. Ver\u00e4nderungen. Aktionen.\",\"publisher\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-LU\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization\",\"name\":\"Greenpeace Luxembourg\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-LU\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png\",\"contentUrl\":\"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png\",\"width\":1080,\"height\":175,\"caption\":\"Greenpeace Luxembourg\"},\"image\":{\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/greenpeaceluxembourg\",\"https:\/\/www.instagram.com\/greenpeacelux\/\",\"https:\/\/www.linkedin.com\/company\/greenpeace-luxembourg\/\",\"https:\/\/www.threads.com\/@greenpeacelux\",\"https:\/\/bsky.app\/profile\/greenpeacelux.bsky.social\",\"https:\/\/www.youtube.com\/@GreenpeaceLux\",\"https:\/\/www.tiktok.com\/@greenpeace_lux\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/3d0e81a859b59009fec36a8552ef76a7\",\"name\":\"Esther Wildanger\",\"url\":\"https:\/\/www.greenpeace.org\/luxembourg\/de\/author\/ewildang\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0 - Greenpeace Luxembourg","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/","og_locale":"de_DE","og_type":"article","og_title":"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0","og_description":"Die Plattform Meng Landwirtschaft, mit ihren 19 Tr\u00e4gerorganisationen, pr\u00e4sentiert die vollst\u00e4ndig \u00fcberarbeitete vierte Auflage ihres Pl\u00e4doyers f\u00fcr eine Neuausrichtung der Landwirtschaft an dem\u2026","og_url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/","og_site_name":"Greenpeace Luxembourg","article_publisher":"https:\/\/www.facebook.com\/greenpeaceluxembourg","article_published_time":"2025-06-30T12:55:02+00:00","article_modified_time":"2025-06-30T13:03:02+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22-1024x682.png","type":"image\/png"}],"author":"Esther Wildanger","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Esther Wildanger","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#article","isPartOf":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/"},"author":{"name":"Esther Wildanger","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/3d0e81a859b59009fec36a8552ef76a7"},"headline":"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0","datePublished":"2025-06-30T12:55:02+00:00","dateModified":"2025-06-30T13:03:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/"},"wordCount":981,"publisher":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png","keywords":["NachhaltigeLandwirtschaft"],"articleSection":["Greenpeace","Natur"],"inLanguage":"de-LU"},{"@type":"WebPage","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/","url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/","name":"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0 - Greenpeace Luxembourg","isPartOf":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage"},"thumbnailUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png","datePublished":"2025-06-30T12:55:02+00:00","dateModified":"2025-06-30T13:03:02+00:00","breadcrumb":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#breadcrumb"},"inLanguage":"de-LU","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/"]}]},{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#primaryimage","url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png","contentUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2025\/06\/fb989962-\u00a9naturemweltcharly-beck-22.png","width":1772,"height":1181},{"@type":"BreadcrumbList","@id":"https:\/\/www.greenpeace.org\/luxembourg\/de\/presseerklaerungen\/24933\/nei-wuerzele-fir-eis-landwirtschaft-plaedoyer-fuer-eine-gerechte-und-zukunftsfaehige-agrarpolitik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/"},{"@type":"ListItem","position":2,"name":"Nei Wuerzele fir eis Landwirtschaft: Pl\u00e4doyer f\u00fcr eine gerechte und zukunftsf\u00e4hige Agrarpolitik\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#website","url":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/","name":"Greenpeace Luxembourg","description":"Greenpeace existiert, weil unsere Erde eine Stimme braucht. Sie ben\u00f6tigt L\u00f6sungen. Ver\u00e4nderungen. Aktionen.","publisher":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-LU"},{"@type":"Organization","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#organization","name":"Greenpeace Luxembourg","url":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/","logo":{"@type":"ImageObject","inLanguage":"de-LU","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png","contentUrl":"https:\/\/www.greenpeace.org\/static\/planet4-luxembourg-stateless\/2026\/03\/3e367f94-greenpeace_logo_green_rgb.png","width":1080,"height":175,"caption":"Greenpeace Luxembourg"},"image":{"@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/greenpeaceluxembourg","https:\/\/www.instagram.com\/greenpeacelux\/","https:\/\/www.linkedin.com\/company\/greenpeace-luxembourg\/","https:\/\/www.threads.com\/@greenpeacelux","https:\/\/bsky.app\/profile\/greenpeacelux.bsky.social","https:\/\/www.youtube.com\/@GreenpeaceLux","https:\/\/www.tiktok.com\/@greenpeace_lux"]},{"@type":"Person","@id":"https:\/\/www.greenpeace.org\/luxembourg\/fr\/#\/schema\/person\/3d0e81a859b59009fec36a8552ef76a7","name":"Esther Wildanger","url":"https:\/\/www.greenpeace.org\/luxembourg\/de\/author\/ewildang\/"}]}},"_links":{"self":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/24933","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/comments?post=24933"}],"version-history":[{"count":2,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/24933\/revisions"}],"predecessor-version":[{"id":24942,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/posts\/24933\/revisions\/24942"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/media\/24936"}],"wp:attachment":[{"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/media?parent=24933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/categories?post=24933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/tags?post=24933"},{"taxonomy":"p4-page-type","embeddable":true,"href":"https:\/\/www.greenpeace.org\/luxembourg\/de\/wp-json\/wp\/v2\/p4-page-type?post=24933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}